{"id":4371,"date":"2021-12-08T16:59:42","date_gmt":"2021-12-08T13:29:42","guid":{"rendered":"https:\/\/bizma.ir\/?p=4371"},"modified":"2024-09-28T11:54:56","modified_gmt":"2024-09-28T08:24:56","slug":"hpv-treatment","status":"publish","type":"post","link":"https:\/\/bizma.ir\/mag\/hpv-treatment\/","title":{"rendered":"\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0628\u0627 \u0633\u0631\u06cc\u0639 \u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u062e\u0627\u0646\u06af\u06cc \u062f\u0631 90 \u0631\u0648\u0632!"},"content":{"rendered":"<p>\u0627\u0686 \u067e\u06cc \u0648\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 \u0648\u06cc\u0631\u0648\u0633 \u067e\u0627\u067e\u06cc\u0644\u0648\u0645\u0627\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc\u060c \u0639\u0627\u0645\u0644 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u0646\u062f\u0647 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0631\u0627\u0642\u0628\u062a\u06cc \u0627\u0633\u062a\u060c \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0627\u06af\u0631 \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0647\u0645 \u0627\u06a9\u0646\u0648\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u06f4\u06f0 \u06af\u0648\u0646\u0647 \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u06a9\u0634\u0641 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062a\u0627\u062b\u06cc\u0631\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631 \u0646\u0627\u062d\u06cc\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u0628\u0631\u0648\u0632 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u0646\u0645\u0627\u06cc\u0634 \u062f\u0647\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0642\u0627\u0644\u0647 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u0631\u0627\u0647\u200c \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u062e\u0627\u0646\u0647 \u0648 &#8230; \u0627\u0634\u0627\u0631\u0647 \u06a9\u0646\u06cc\u0645. \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0647\u0631 \u0622\u0646\u0686\u0647 \u06a9\u0647 \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0648 \u0648\u06cc\u0631\u0648\u0633 HPV \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u0631\u0627 \u062f\u0631 \u0647\u0645\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0647\u06cc\u062f \u062e\u0648\u0627\u0646\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_HPV_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc HPV \u0686\u06cc\u0633\u062a\u061f\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_HPV\" >\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc HPV<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86\" >\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\" >\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\" >\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631\u0645\u0627\u0646 \u062f\u0627\u0631\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%88%D8%A7%DA%A9%D8%B3%D9%86_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\" >\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0648\u0627\u06a9\u0633\u0646 \u062f\u0627\u0631\u062f\u061f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\" >\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%A7%D8%B1%D9%88%D9%87%D8%A7%DB%8C_%D9%85%D9%88%D8%B6%D8%B9%DB%8C_%D9%85%D8%AB%D9%84_%D9%BE%D9%88%D8%AF%D9%88%D9%81%DB%8C%D9%84%DB%8C%D9%86\" >\u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0645\u0648\u0636\u0639\u06cc \u0645\u062b\u0644 \u067e\u0648\u062f\u0648\u0641\u06cc\u0644\u06cc\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7_%DA%A9%D8%B1%D8%A7%DB%8C%D9%88_%D8%AA%D8%B1%D8%A7%D9%BE%DB%8C\" >\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u06a9\u0631\u0627\u06cc\u0648 \u062a\u0631\u0627\u067e\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7_%D9%84%DB%8C%D8%B2%D8%B1\" >\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u0644\u06cc\u0632\u0631<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%B2%DA%AF%DB%8C%D9%84%E2%80%8C_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\" >\u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B3%D8%B1%DB%8C%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\" >\u062f\u0631\u0645\u0627\u0646 \u0633\u0631\u06cc\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%A8%D8%B1%DA%AF%D8%B4%D8%AA_%D8%B2%DA%AF%DB%8C%D9%84%E2%80%8C_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\" >\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0628\u0631\u06af\u0634\u062a \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D9%82%D8%A7%D9%84_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_hpv\" >\u0631\u0627\u0647 \u0647\u0627\u06cc \u0627\u0646\u062a\u0642\u0627\u0644 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc hpv<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\" >\u062a\u0634\u062e\u06cc\u0635 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\" >\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86\" >\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\" >\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1%D8%AF_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\" >\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631\u062f \u062f\u0627\u0631\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D9%85%D8%B9%D9%85%D9%88%D9%84%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u062a\u0641\u0627\u0648\u062a \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u0632\u06af\u06cc\u0644 \u0645\u0639\u0645\u0648\u0644\u06cc \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%DA%A9%D8%B1%D9%85_%D9%88_%D9%BE%D9%85%D8%A7%D8%AF_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u0631\u0645 \u0648 \u067e\u0645\u0627\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7%D8%B9%D8%AB_%D8%AE%D8%A7%D8%B1%D8%B4_%D9%85%DB%8C%D8%B4%D9%88%D8%AF%D8%9F\" >\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627\u0639\u062b \u062e\u0627\u0631\u0634 \u0645\u06cc\u0634\u0648\u062f\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%85%D9%86%D8%AC%D8%B1_%D8%A8%D9%87_%D8%B3%D8%B1%D8%B7%D8%A7%D9%86_%D9%85%DB%8C%D8%B4%D9%88%D8%AF%D8%9F\" >\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0645\u0646\u062c\u0631 \u0628\u0647 \u0633\u0631\u0637\u0627\u0646 \u0645\u06cc\u0634\u0648\u062f\u061f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\" >\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B6\" >\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u0648\u0639 \u06f6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B1%DB%B1\" >\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u0648\u0639 \u06f1\u06f1<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B1%DB%B6\" >\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc\u00a0\u0646\u0648\u0639 \u06f1\u06f6<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B1%DB%B8\" >\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc\u00a0\u0646\u0648\u0639 \u06f1\u06f8<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%B3%D8%B1%D8%B7%D8%A7%D9%86_%D9%87%D8%A7%DB%8C_%D9%86%D8%A7%D8%B4%DB%8C_%D8%A7%D8%B2_%D9%88%DB%8C%D8%B1%D9%88%D8%B3_HPV\" >\u0633\u0631\u0637\u0627\u0646 \u0647\u0627\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0648\u06cc\u0631\u0648\u0633 HPV<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/bizma.ir\/mag\/hpv-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84%E2%80%8C_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86_%D8%AF%D8%B1_%D8%AE%D8%A7%D9%86%D9%87\" >\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u062f\u0631 \u062e\u0627\u0646\u0647<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_HPV_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc HPV \u0686\u06cc\u0633\u062a\u061f\u00a0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0648\u06cc\u0631\u0648\u0633\u06cc \u06cc\u06a9 \u0639\u0627\u0631\u0636\u0647 \u067e\u0648\u0633\u062a\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0627\u0646\u0648\u0627\u0639 \u0628\u0633\u06cc\u0627\u0631 \u0645\u062e\u062a\u0644\u0641\u06cc \u062f\u0627\u0631\u062f \u06a9\u0647 \u0627\u063a\u0644\u0628 \u0622\u0646\u200c\u0647\u0627 \u062e\u06cc\u0644\u06cc \u062e\u0637\u0631\u0646\u0627\u06a9 \u0648 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0646\u06cc\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0645\u0627\u0646\u0646\u062f \u06af\u0648\u0634\u062a\u200c\u0647\u0627\u06cc \u0627\u0636\u0627\u0641\u06cc \u0648 \u0646\u0631\u0645\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0627\u0637\u0631\u0627\u0641 \u062f\u0633\u062a\u06af\u0627\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0638\u0627\u0647\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0648 \u0634\u0627\u06cc\u0639\u200c\u062a\u0631\u06cc\u0646 \u0639\u0641\u0648\u0646\u062a\u200c\u0647\u0627\u06cc \u0645\u0642\u0627\u0631\u0628\u062a\u06cc \u0645\u06cc\u200c\u0628\u0627\u0634\u062f.<\/p>\n<p>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u062f\u0631 \u0645\u0631\u0627\u062d\u0644 \u0627\u0648\u0644\u06cc\u0647 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0627\u062f\u0647 \u0634\u0648\u062f\u060c \u0633\u0644\u0627\u0645\u062a \u0641\u0631\u062f \u0628\u0647 \u062e\u0637\u0631 \u0646\u0645\u06cc\u200c\u0627\u0641\u062a\u062f \u0648\u0644\u06cc \u0627\u06af\u0631 \u0639\u0641\u0648\u0646\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u062f\u0627\u0626\u0645\u06cc \u0634\u0648\u062f \u0648 \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0646\u0627\u0633\u0628\u06cc \u0628\u0631\u0627\u06cc \u0631\u0641\u0639 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062e\u0648\u062f \u0646\u0628\u0627\u0634\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0631\u0639\u062a \u0631\u0634\u062f \u0648 \u062a\u06a9\u062b\u06cc\u0631 \u0633\u0644\u0648\u0644\u06cc \u062f\u0631 \u0646\u0627\u062d\u06cc\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627\u0639\u062b \u0633\u0631\u0637\u0627\u0646 \u0634\u0648\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0632\u0646\u0627\u0646 \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0622\u0633\u06cc\u0628 \u067e\u0630\u06cc\u0631\u062a\u0631 \u0647\u0633\u062a\u0646\u062f \u0648 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0631\u06cc\u0639\u0627\u064b \u06a9\u0646\u062a\u0631\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0646\u0634\u0648\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0641\u0631\u062f \u062f\u0686\u0627\u0631 \u0633\u0631\u0637\u0627\u0646 \u062f\u0647\u0627\u0646\u0647 \u0631\u062d\u0645 \u0648 \u06af\u0631\u062f\u0646 \u0631\u062d\u0645 \u0634\u0648\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_HPV\"><\/span><strong>\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc HPV<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0627\u0641\u0631\u0627\u062f \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u062a\u0641\u0627\u0648\u062a \u0628\u0627\u0634\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0639\u0644\u0627\u0645\u062a \u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0628\u0631\u0648\u0632 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0639\u0644\u0627\u0645\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0632\u0646\u0627\u0646 \u0642\u0627\u0628\u0644 \u0628\u0631\u0631\u0633\u06cc \u0647\u0633\u062a\u0646\u062f\u060c \u0645\u062a\u0641\u0627\u0648\u062a \u0628\u0627\u0634\u0646\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u0627\u062d\u06cc\u0647 \u062f\u0631\u06af\u06cc\u0631\u06cc \u0648 \u0634\u062f\u062a \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0641\u0631\u0627\u062f \u0639\u0644\u0627\u0626\u0645 \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0622\u0646\u200c\u0647\u0627 \u0627\u0634\u0627\u0631\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86\"><\/span><strong>\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0632 \u0645\u0647\u0645\u200c \u062a\u0631\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0628\u0627\u0646\u0648\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u062a\u0631\u0634\u062d\u0627\u062a \u0648\u0627\u0698\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u062a\u0631\u0634\u062d\u0627\u062a \u0648\u0627\u0698\u0646 \u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u062d\u0627\u0644\u0627\u062a \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0633\u0644\u0627\u0645\u062a\u06cc \u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u0628\u062f\u0646 \u0647\u0633\u062a\u0646\u062f\u060c \u0627\u06cc\u0646 \u062a\u0631\u0634\u062d\u0627\u062a \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0647\u0648\u0631\u0645\u0648\u0646\u06cc \u0628\u06cc\u0648\u0644\u0648\u0698\u06cc\u06a9\u06cc \u0648 \u06cc\u0627 \u062f\u0631\u06af\u06cc\u0631\u06cc \u0648\u06cc\u0631\u0648\u0633\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u0634\u06a9\u0644\u060c\u00a0 \u0631\u0646\u06af \u0648 \u0628\u0648 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f.<\/p>\n<p>\u0627\u0644\u0628\u062a\u0647 \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u062a\u0646\u0647\u0627 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u0628\u0631\u0648\u0632 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u0686\u0646\u062f\u06cc\u0646 \u0645\u0627\u0647 \u0627\u0632 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0645\u0634\u06a9\u0648\u06a9 \u06af\u0630\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0632\u06cc\u0631\u0627 \u062f\u0648\u0631\u0647 \u0646\u0647\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0686\u0646\u062f \u0645\u0627\u0647 \u06cc\u0627 \u062d\u062a\u06cc \u0686\u0646\u062f \u0633\u0627\u0644 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0637\u0648\u0644 \u0628\u06cc\u0627\u0646\u062c\u0627\u0645\u062f.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0644\u062a\u0647\u0627\u0628\u060c \u062e\u0627\u0631\u0634\u060c \u0633\u0648\u0632\u0634 \u0648 \u0639\u0644\u0627\u0626\u0645 \u0627\u0648\u0644\u06cc\u0647 \u0632\u06af\u06cc\u0644 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u067e\u0633 \u0627\u0632 \u0645\u062f\u062a\u06cc \u062e\u0648\u062f \u0631\u0627 \u0646\u0634\u0627\u0646 \u062f\u0647\u062f. \u062a\u063a\u06cc\u06cc\u0631 \u0631\u0646\u06af \u067e\u0648\u0633\u062a \u062f\u0631 \u0627\u06cc\u0646 \u0646\u0627\u062d\u06cc\u0647 \u0631\u0627 \u0646\u06cc\u0632 \u0628\u0627\u06cc\u062f \u062c\u062f\u06cc \u0628\u06af\u06cc\u0631\u06cc\u0645. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0631 \u0627\u062b\u0631 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u062f\u0647\u0627\u0646\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0648\u06cc\u0631\u0648\u0633 \u0647\u0627 \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0645\u062b\u0644 \u0632\u0628\u0627\u0646\u060c \u062f\u0647\u0627\u0646 \u0648 \u06af\u0644\u0648 \u0631\u0627 \u062f\u0631\u06af\u06cc\u0631 \u06a9\u0646\u0646\u062f. \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u0627\u062d\u06cc\u0647 \u062f\u0631\u06af\u06cc\u0631 \u0634\u062f\u0647\u060c \u0639\u0644\u0627\u0626\u0645 \u062f\u0631 \u0627\u0641\u0631\u0627\u062f \u0645\u062e\u062a\u0644\u0641 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0634\u062f\u062a \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0648\u0632 \u062f\u0647\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631 \u0647\u06cc\u0686 \u062a\u0633\u062a\u06cc \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0645\u0646\u062d\u0635\u0631\u0627\u064b \u0628\u0631\u0627\u06cc \u063a\u0631\u0628\u0627\u0644\u06af\u0631\u06cc \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c\u062a\u0646\u0627\u0633\u0644\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u067e\u0633 \u0627\u0632 \u06af\u0630\u0634\u062a \u062f\u0648\u0631\u0647 \u0637\u0648\u0644\u0627\u0646\u06cc \u0646\u0647\u0641\u062a\u06af\u06cc \u0648 \u062a\u0634\u062e\u06cc\u0635 \u0639\u0644\u0627\u0626\u0645 \u0627\u0648\u0644\u06cc\u0647 \u0633\u0631\u0637\u0627\u0646 \u0628\u0647 \u0627\u0628\u062a\u0644\u0627\u06cc \u062e\u0648\u062f \u067e\u06cc \u0645\u06cc\u200c\u0628\u0631\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\"><\/span><strong>\u0639\u0644\u0627\u0626\u0645 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0628\u0631\u0648\u0632 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc\u06cc \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc (\u0628\u0627 \u0631\u0646\u06af \u067e\u0648\u0633\u062a \u0648 \u06cc\u0627 \u062a\u06cc\u0631\u0647\u200c\u062a\u0631 \u0627\u0632 \u067e\u0648\u0633\u062a) \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0627\u0644\u0628\u062a\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u062f\u0631 \u0628\u062f\u0646 \u0645\u0631\u062f\u0627\u0646 \u0628\u062f\u0648\u0646 \u0639\u0644\u0627\u0645\u062a \u0631\u0634\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u062f\u0631 \u0628\u0631\u062e\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646 \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635\u060c \u0622\u0632\u0645\u0627\u06cc\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0646\u0645\u0648\u0646\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0627\u0632 \u067e\u0648\u0633\u062a \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u062a\u062c\u0648\u06cc\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u0646\u06a9\u062a\u0647: \u0627\u0646\u0648\u0627\u0639 \u0645\u062e\u062a\u0644\u0641 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u062f\u0631 \u0632\u0646\u0627\u0646 \u062f\u0631 \u0639\u0631\u0636 \u062f\u0648 \u0633\u0627\u0644 \u06cc\u0627 \u06a9\u0645\u062a\u0631 \u0642\u0627\u0628\u0644 \u062a\u0634\u062e\u06cc\u0635 \u0647\u0633\u062a\u0646\u062f \u0648\u0644\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0628\u0627 \u0639\u0644\u0627\u0626\u0645 \u0638\u0627\u0647\u0631\u06cc \u0642\u0627\u0628\u0644 \u0627\u0646\u062c\u0627\u0645 \u0646\u06cc\u0633\u062a \u0632\u06cc\u0631\u0627 \u0639\u0644\u0627\u0626\u0645 \u062f\u06cc\u0631\u062a\u0631 \u0638\u0627\u0647\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0627\u0634\u062a\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u06cc \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0634\u0631\u06cc\u06a9 \u062c\u0646\u0633\u06cc \u0634\u0645\u0627 \u0627\u062e\u06cc\u0631\u0627\u064b \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0628\u0627 \u0627\u0641\u0631\u0627\u062f \u062f\u06cc\u06af\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a\u060c \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0633\u0627\u0644\u200c\u0647\u0627 \u062f\u0631 \u062f\u0648\u0631\u0647 \u0646\u0647\u0641\u062a\u06af\u06cc \u0628\u0648\u062f\u0647 \u0628\u0627\u0634\u062f \u0648 \u0646\u0634\u0627\u0646\u0647\u200c \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0632 \u062f\u0631 \u067e\u0648\u0633\u062a \u0628\u062f\u0646 \u0628\u06cc\u0645\u0627\u0631 \u0628\u0631\u0648\u0632 \u0646\u062f\u0627\u062f\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9279 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0639\u0644\u0627\u0626\u0645-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-HPV.webp\" alt=\"\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631\u0645\u0627\u0646 \u062f\u0627\u0631\u062f\u061f\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0639\u0644\u0627\u0626\u0645-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-HPV.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0639\u0644\u0627\u0626\u0645-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-HPV-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0639\u0644\u0627\u0626\u0645-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-HPV-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0639\u0644\u0627\u0626\u0645-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-HPV-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span>\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631\u0645\u0627\u0646 \u062f\u0627\u0631\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0644\u0647\u061b \u0648\u0644\u06cc \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0631\u06af\u0634\u062a \u067e\u0630\u06cc\u0631 \u0627\u0633\u062a. \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u062c\u0631\u0627\u062a \u06af\u0641\u062a \u06a9\u0647 \u062f\u0631 \u0628\u062f\u0646 \u0641\u0631\u062f \u0628\u06cc\u0645\u0627\u0631 \u067e\u0633 \u0627\u0632 \u0628\u0647 \u06a9\u0627\u0631\u06af\u06cc\u0631\u06cc \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646\u060c \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0634\u0647 \u0627\u0632 \u0628\u06cc\u0646 \u062e\u0648\u0627\u0647\u062f \u0631\u0641\u062a. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0642\u0627\u0628\u0644 \u0631\u0641\u0639 \u0647\u0633\u062a\u0646\u062f \u0648\u0644\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u067e\u0633 \u0627\u0632 \u067e\u0627\u06cc\u0627\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u062f\u0631\u0645\u0627\u0646\u06cc\u060c \u0632\u06af\u06cc\u0644 \u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u06cc \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u0645\u062e\u062a\u0644\u0641 \u067e\u062f\u06cc\u062f\u0627\u0631 \u0634\u0648\u0646\u062f.&#8221;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%88%D8%A7%DA%A9%D8%B3%D9%86_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span>\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0648\u0627\u06a9\u0633\u0646 \u062f\u0627\u0631\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0632\u0631\u06cc\u0642 \u0648\u0627\u06a9\u0633\u0646 \u06af\u0627\u0631\u062f\u0627\u0633\u06cc\u0644 \u0648 \u0648\u0627\u06a9\u0633\u0646 \u0633\u0631\u0648\u0627\u0631\u06cc\u06a9\u0633 \u0628\u0631\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0633\u0631\u0637\u0627\u0646 \u0645\u0642\u0639\u062f\u060c \u062f\u0647\u0627\u0646\u0647 \u0631\u062d\u0645 \u0648 \u0648\u0627\u0698\u0646 \u0628\u0631\u0627\u06cc \u0622\u0642\u0627\u06cc\u0627\u0646 \u0648 \u062e\u0627\u0646\u0645\u200c\u0647\u0627 \u0627\u0632 \u0633\u0646\u06cc\u0646 \u0628\u0644\u0648\u063a \u062c\u0646\u0633\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0648\u0627\u06a9\u0633\u0646 \u062f\u0631 \u0633\u0647 \u062f\u0648\u0632 \u0645\u062a\u0641\u0627\u0648\u062a \u0628\u0627 \u0641\u0627\u0635\u0644\u0647 \u062f\u0648\u0645\u0627\u0647 \u0648 \u0634\u0634 \u0645\u0627\u0647 \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u062a\u0632\u0631\u06cc\u0642 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0648\u0627\u06a9\u0633\u0646 \u0639\u0648\u0627\u0631\u0636 \u062c\u062f\u06cc \u0646\u062f\u0627\u0631\u062f \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0622\u0646 \u0631\u0627 \u0627\u0632 \u062f\u0627\u0631\u0648\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u062a\u0647\u06cc\u0647 \u06a9\u0631\u062f.<\/p>\n<p>\u0648\u0627\u06a9\u0633\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0639\u0648\u0627\u0631\u0636 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u062a\u06cc\u067e\u200c\u0647\u0627\u06cc \u067e\u0631\u062e\u0637\u0631 \u0648 \u0627\u06cc\u062c\u0627\u062f \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc \u062f\u0631 \u0628\u062f\u0646 \u0627\u0641\u0631\u0627\u062f \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u062f. \u0648\u0627\u06a9\u0633\u0646\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u062a\u06cc\u067e\u200c\u0647\u0627\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646 \u0648\u06cc\u0631\u0648\u0633\u060c \u0627\u06cc\u0645\u0646\u06cc \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<p>\u0645\u062d\u0635\u0648\u0644 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc : <a href=\"https:\/\/bizma.ir\/product\/dr-biz-black-garlic\/\" target=\"_blank\" rel=\"noopener\">\u0633\u06cc\u0631 \u0633\u06cc\u0627\u0647 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\"><\/span><strong>\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0648 \u06cc\u0627 HPV \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u062c\u0647\u0627\u0646 \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0647\u200c \u0627\u0633\u062a. \u0648\u0644\u06cc \u0647\u06cc\u0686 \u06cc\u06a9 \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0642\u062f\u0631\u062a \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0631\u0627 \u062f\u0631 \u0628\u062f\u0646 \u0646\u062f\u0627\u0631\u0646\u062f \u0648 \u062a\u0646\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0631\u0627 \u062f\u0631\u0645\u0627\u0646 \u06a9\u0646\u0646\u062f\u200c.<\/p>\n<p>\u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0645\u0631\u0648\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u06a9\u0631\u0627\u06cc\u0648 \u062a\u0631\u0627\u067e\u06cc \u0644\u06cc\u0632\u0631 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0645\u0648\u0636\u0639\u06cc \u0645\u062b\u0644 \u067e\u0648\u062f\u0648\u0641\u06cc\u0644\u06cc\u0646 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0646\u06cc\u0632 \u0686\u0646\u062f \u0633\u0627\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0631\u0633\u0648\u0645 \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u0627\u062b\u0631\u0628\u062e\u0634\u06cc \u0622\u0646\u200c\u0647\u0627 \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AF%D8%A7%D8%B1%D9%88%D9%87%D8%A7%DB%8C_%D9%85%D9%88%D8%B6%D8%B9%DB%8C_%D9%85%D8%AB%D9%84_%D9%BE%D9%88%D8%AF%D9%88%D9%81%DB%8C%D9%84%DB%8C%D9%86\"><\/span><strong>\u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0645\u0648\u0636\u0639\u06cc \u0645\u062b\u0644 \u067e\u0648\u062f\u0648\u0641\u06cc\u0644\u06cc\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c \u062a\u0631\u06cc\u0646 \u0645\u062d\u0644\u0648\u0644\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0631 \u0631\u0648\u06cc \u0636\u0627\u06cc\u0639\u0627\u062a \u06cc\u0627 \u0647\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0645\u062d\u0644\u0648\u0644 \u067e\u0648\u062f\u0648\u0641\u06cc\u0644\u06cc\u0646 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0637\u0648\u0644\u0627\u0646\u06cc \u0645\u062f\u062a \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062d\u0644\u0648\u0644 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062a\u062d\u0631\u06cc\u06a9\u0627\u062a \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u0648\u0636\u0648\u0639\u06cc \u06a9\u0647 \u062f\u0627\u0631\u062f\u060c \u0645\u0645\u0646\u0648\u0639 \u0627\u0633\u062a \u0648 \u062a\u0646\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u062f\u062a \u06cc\u06a9 \u062a\u0627 \u0633\u0647 \u0645\u0627\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0622\u0646 \u06a9\u0631\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7_%DA%A9%D8%B1%D8%A7%DB%8C%D9%88_%D8%AA%D8%B1%D8%A7%D9%BE%DB%8C\"><\/span><strong>\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u06a9\u0631\u0627\u06cc\u0648 \u062a\u0631\u0627\u067e\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631\u06cc \u0628\u0627\u0644\u0627 \u0648 \u0647\u0632\u06cc\u0646\u0647 \u06a9\u0645\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0627\u0631\u062f \u062a\u0648\u0627\u0646\u0633\u062a\u0647 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0645\u062d\u0628\u0648\u0628\u06cc\u062a \u0627\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646\u06cc \u0634\u0648\u062f. \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0631\u0627\u06cc\u0648\u062a\u0631\u0627\u067e\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0631\u0627\u06cc\u062c \u0627\u0633\u062a.<\/p>\n<p>\u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0631\u0627\u06a9\u0632 \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0627\u06cc\u0639 \u0646\u06cc\u062a\u0631\u0648\u0698\u0646 \u0648 \u0633\u0631\u0645\u0627\u06cc \u062d\u0627\u0635\u0644 \u0627\u0632 \u0622\u0646 \u0628\u0647 \u06a9\u0645\u06a9 \u067e\u0631\u0648\u0628 \u06a9\u0631\u0627\u06cc\u0648\u060c \u062f\u0631 \u0645\u062d\u0644 \u0648\u062c\u0648\u062f \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u06cc\u062a\u0631\u0648\u0698\u0646 \u0628\u062e\u0627\u0631 \u0634\u062f\u0647 \u0628\u0627 \u062f\u0645\u0627\u06cc \u0645\u0646\u0641\u06cc \u06f2\u06f0 \u062f\u0631\u062c\u0647 \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u0627\u0645\u0644\u0627\u064b \u062e\u0641\u06cc\u0641 \u0628\u0631 \u0631\u0648\u06cc \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0627\u0633\u067e\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0628\u0627\u0641\u062a \u0633\u0644\u0648\u0644\u06cc \u0632\u06af\u06cc\u0644 \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u0648\u062f. \u062f\u0648\u0631\u0647 \u0646\u0642\u0627\u0647\u062a \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0633\u06cc\u0627\u0631 \u0645\u062e\u062a\u0635\u0631 \u0627\u0633\u062a \u0648 \u0627\u0641\u0631\u0627\u062f \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u067e\u0633 \u0627\u0632 \u06af\u0630\u0634\u062a \u06cc\u06a9 \u0647\u0641\u062a\u0647 \u062a\u0627\u0648\u0644\u200c\u0647\u0627\u06cc \u062e\u0641\u06cc\u0641\u06cc \u06a9\u0647 \u0646\u0627\u0634\u06cc \u0627\u0632 \u062e\u0634\u06a9 \u0634\u062f\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0648\u062f\u0646\u062f \u0631\u0627 \u062f\u06cc\u06af\u0631 \u0645\u0634\u0627\u0647\u062f\u0647 \u0646\u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7_%D9%84%DB%8C%D8%B2%D8%B1\"><\/span><strong>\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u0644\u06cc\u0632\u0631<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u062a\u0627\u0628\u0627\u0646\u062f\u0646 \u067e\u0631\u062a\u0648\u0647\u0627\u06cc \u0641\u0631\u0648\u0633\u0631\u062e \u0628\u0647 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u062d\u0627\u0635\u0644 \u0634\u062f\u0647 \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc HPV \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0631\u0627\u06cc\u062c \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u062a\u0647\u0627\u062c\u0645 \u062f\u0642\u06cc\u0642\u200c\u062a\u0631\u06cc \u0628\u0647 \u0648\u06cc\u0631\u0648\u0633 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u0644\u0628\u062a\u0647 \u0639\u0648\u0627\u0631\u0636 \u062c\u0627\u0646\u0628\u06cc \u0627\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u0627 \u0631\u0648\u0634 \u0642\u0628\u0644\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0633\u062a. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0641\u0631\u062f \u062a\u0627 \u06cc\u06a9 \u0647\u0641\u062a\u0647 \u0627\u062d\u0633\u0627\u0633 \u062f\u0631\u062f \u06cc\u0627 \u0633\u0648\u0632\u0634 \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u06cc\u06a9 \u0631\u0648\u0634 \u0627\u0645\u06cc\u062f \u0628\u062e\u0634 \u062f\u06cc\u06af\u0631 \u0646\u06cc\u0632 \u062a\u0648\u0633\u0637 \u062f\u0627\u0646\u0634\u06a9\u062f\u0647 \u067e\u0632\u0634\u06a9\u06cc \u0627\u0635\u0641\u0647\u0627\u0646 \u062f\u0631 \u062d\u0627\u0644 \u0628\u0631\u0631\u0633\u06cc \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u06a9\u0647 \u0628\u0647 \u0644\u06cc\u0632\u0631 \u06a9\u0631\u0628\u0646 \u062f\u06cc \u0627\u06a9\u0633\u06cc\u062f \u0645\u0634\u0647\u0648\u0631 \u0627\u0633\u062a \u0634\u0627\u0646\u0633 \u062f\u0631\u0645\u0627\u0646 \u062f\u0648 \u0628\u0631\u0627\u0628\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0631\u0648\u0634 \u06a9\u0631\u0627\u06cc\u0648\u062a\u0631\u0627\u067e\u06cc \u0645\u06cc\u200c\u0628\u0627\u0634\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u062f\u0646 \u062c\u0644\u0633\u0627\u062a \u062f\u0631\u0645\u0627\u0646\u06cc \u0644\u06cc\u0632\u0631 \u0648 \u06a9\u0631\u0627\u06cc\u0648 \u062a\u0631\u0627\u067e\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0634\u0645\u0627 \u0628\u0647 \u0646\u062a\u06cc\u062c\u0647 \u062f\u0644\u062e\u0648\u0627\u0647 \u0648 \u0631\u0636\u0627\u06cc\u062a \u0628\u062e\u0634\u06cc \u0628\u0631\u0633\u06cc\u062f. \u062a\u0635\u0648\u0631 \u0646\u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062a\u0646\u0647\u0627 \u0628\u0627 \u06cc\u06a9 \u062c\u0644\u0633\u0647 \u0644\u06cc\u0632\u0631 \u06cc\u0627 \u06a9\u0631\u0627\u06cc\u0648\u062a\u0631\u0627\u067e\u06cc\u060c \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0634\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0646\u0627\u062d\u06cc\u0647 \u062e\u062f\u0627\u062d\u0627\u0641\u0638\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/p>\n<p>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0632\u0631\u06af \u0628\u0627\u0634\u0646\u062f \u0648 \u0646\u062a\u0648\u0627\u0646 \u0627\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0642\u0628\u0644\u06cc \u062f\u0631\u0645\u0627\u0646 \u06a9\u0631\u062f\u060c \u067e\u0632\u0634\u06a9 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u062c\u0631\u0627\u062d\u06cc \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0631\u0627 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc \u062f\u0647\u062f \u0648\u06cc\u0698\u06af\u06cc \u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0628\u0627 \u0631\u0648\u0634 \u0627\u0644\u06a9\u062a\u0631\u0648\u0633\u0631\u062c\u0631\u06cc \u0648 \u06cc\u0627 \u0631\u0627\u062f\u06cc\u0648\u0633\u0631\u062c\u0631\u06cc \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9281 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u062f\u0631\u0645\u0627\u0646-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc.webp\" alt=\"\u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u062f\u0631\u0645\u0627\u0646-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u062f\u0631\u0645\u0627\u0646-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u062f\u0631\u0645\u0627\u0646-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u062f\u0631\u0645\u0627\u0646-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C_%D8%B2%DA%AF%DB%8C%D9%84%E2%80%8C_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\"><\/span>\u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0645\u0648\u062b\u0631 \u0648 \u062e\u0627\u0646\u06af\u06cc \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u062f\u0631 \u0645\u062f\u062a \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631\u06cc \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u062a\u06cc\u062c\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f\u061b \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062a\u0648\u0635\u06cc\u0647\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0630\u06a9\u0631 \u0634\u062f\u0647 \u0627\u0633\u062a \u0631\u0627 \u062c\u062f\u06cc \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<p>\u0642\u0628\u0644 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0641\u0634\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631 \u0631\u0648\u06cc \u0628\u062f\u0646 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u062f\u0631 \u062d\u0642\u06cc\u0642\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0628\u0633\u06cc\u0627\u0631 \u0636\u0639\u06cc\u0641 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u062a\u0627 \u0639\u0648\u0627\u0645\u0644 \u0627\u0633\u062a\u0631\u0633 \u0632\u0627\u060c \u0645\u0635\u0631\u0641 \u063a\u0630\u0627\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646\u060c \u06a9\u0634\u06cc\u062f\u0646 \u0633\u06cc\u06af\u0627\u0631 \u0648 \u062a\u0645\u0627\u0645\u06cc \u0639\u0627\u062f\u062a\u200c\u0647\u0627\u06cc \u0646\u0627\u0633\u0627\u0644\u0645 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u062f\u062a\u06cc \u0645\u062d\u062f\u0648\u062f \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0627\u062b\u0631\u0628\u062e\u0634\u06cc \u0644\u0627\u0632\u0645 \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<p>\u0647\u0631 \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646\u062f \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u062f\u0646 \u0634\u0645\u0627 \u0631\u0627 \u0642\u0648\u06cc\u200c\u062a\u0631 \u06a9\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0628\u0631\u0648\u0632 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0648 \u0627\u062d\u062a\u0645\u0627\u0644 \u0639\u0648\u062f \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc \u067e\u0627\u067e\u06cc\u0644\u0648\u0645\u0627 \u0648\u06cc\u0631\u0648\u0633 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u062f. \u0645\u0635\u0631\u0641 <a href=\"https:\/\/bizma.ir\/category-ganoderma-coffee\/\" target=\"_blank\" rel=\"noopener\">\u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a>\u060c \u063a\u0630\u0627\u0647\u0627\u06cc \u0633\u0631\u0634\u0627\u0631 \u0627\u0632 \u0622\u0646\u062a\u06cc \u0627\u06a9\u0633\u06cc\u062f\u0627\u0646\u060c \u063a\u0644\u0627\u062a \u06a9\u0627\u0645\u0644\u060c \u06af\u0648\u0634\u062a \u06a9\u0645 \u0686\u0631\u0628 \u0648 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u0632\u06cc\u0627\u062f \u0628\u0627\u0639\u062b \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0634\u0645\u0627 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B3%D8%B1%DB%8C%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\"><\/span><strong>\u062f\u0631\u0645\u0627\u0646 \u0633\u0631\u06cc\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0639\u0641\u0648\u0646\u062a \u0628\u0627 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u06a9\u0646\u062a\u0631\u0644 \u0648 \u0645\u0647\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062f\u0627\u0631\u0648\u0647\u0627 \u0648 \u0645\u0648\u0627\u062f\u063a\u0630\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0633\u0631\u0639\u062a \u062f\u0631\u0645\u0627\u0646 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u062e\u0627\u0635 \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0627\u0633\u062a\u062d\u0645\u0627\u0645 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u067e\u0648\u0633\u062a \u0627\u06cc\u0646 \u0646\u0627\u062d\u06cc\u0647 \u062a\u062d\u0631\u06cc\u06a9 \u0646\u0634\u0648\u062f.<\/p>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634 \u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0633\u0631\u06cc\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0635\u0627\u0628\u0648\u0646 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0648 \u06cc\u0627 \u0634\u0627\u0645\u067e\u0648 \u0628\u062f\u0646 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0627\u0644\u062a\u0647\u0627\u0628\u060c \u062e\u0627\u0631\u0634 \u0648 \u0633\u0648\u0632\u0634 \u0627\u06cc\u0646 \u0632\u06af\u06cc\u0644 \u0647\u0627\u0633\u062a. \u062e\u0648\u0627\u0635 \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631 \u0627\u06cc\u0646 \u0642\u0627\u0631\u0686 \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0627\u0633\u062a \u062a\u0627 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0645\u062b\u0644 \u0635\u0627\u0628\u0648\u0646 \u0648 \u0634\u0627\u0645\u067e\u0648 \u0628\u062a\u0648\u0627\u0646 \u0627\u0632 \u0639\u0635\u0627\u0631\u0647 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f.<\/p>\n<p>\u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646 \u0622\u0646\u200c\u0647\u0627 \u062e\u0648\u0627\u0647\u0646\u062f \u0634\u062f \u0648\u0644\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0628\u0631\u062e\u06cc \u0645\u0648\u0627\u0631\u062f \u062f\u0631 \u0642\u0633\u0645\u062a\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\u200c\u062a\u0631 \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u06cc\u0632 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u062a\u0627 \u067e\u0633 \u0627\u0632 \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0628\u0627 \u0631\u0648\u0634 \u0647\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc\u060c \u062d\u062a\u0645\u0627\u064b \u0628\u0647 \u0645\u062a\u062e\u0635\u0635 \u0628\u0631\u0627\u06cc \u0645\u0639\u0627\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062f\u0648\u0631\u0647\u200c\u200c\u0627\u06cc \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0642\u0647\u0648\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 hpv: <a href=\"https:\/\/bizma.ir\/product\/ganoderma-supreme-coffee-dr-biz\/\" target=\"_blank\" rel=\"noopener\">\u0642\u0647\u0648\u0647 \u0641\u0648\u0631\u06cc \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%A8%D8%B1%DA%AF%D8%B4%D8%AA_%D8%B2%DA%AF%DB%8C%D9%84%E2%80%8C_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\"><\/span><strong>\u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0628\u0631\u06af\u0634\u062a \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0648 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0627\u0645\u06a9\u0627\u0646 \u067e\u0630\u06cc\u0631 \u0627\u0633\u062a\u060c \u0648\u0644\u06cc \u0627\u0645\u06a9\u0627\u0646 \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u062f\u0646 \u0648\u06cc\u0631\u0648\u0633 \u062f\u0631 \u0628\u062f\u0646 \u0648 \u0631\u06cc\u0634\u0647\u200c\u06a9\u0646 \u06a9\u0631\u062f\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062a\u0627 \u0628\u0647 \u062d\u0627\u0644 \u0628\u0647 \u0635\u0648\u0631\u062a \u0642\u0637\u0639\u06cc \u0628\u0647 \u0627\u062b\u0628\u0627\u062a \u0646\u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a. \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0631\u062f\u0646 \u0646\u06a9\u0627\u062a \u0632\u06cc\u0631 \u0627\u0632 \u0628\u0631\u06af\u0634\u062a \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631\u0645\u0627\u0646 \u0634\u062f\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<ul>\n<li>\u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062a\u06cc\u063a \u0648 \u0645\u0648\u0627\u062f \u0645\u0648\u0628\u0631 \u0628\u0631\u0627\u06cc \u0632\u062f\u0648\u062f\u0646 \u0645\u0648\u0647\u0627\u06cc \u0632\u0627\u0626\u062f \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc<\/li>\n<li>\u0627\u0632 \u0647\u0631\u06af\u0648\u0646\u0647 \u062a\u062d\u0631\u06cc\u06a9 \u0645\u062b\u0644 \u062e\u0627\u0631\u0627\u0646\u062f\u0646 \u062e\u0634\u06a9\u200c\u06a9\u0631\u062f\u0646 \u0628\u0627 \u062f\u0633\u062a\u0645\u0627\u0644\u200c\u0647\u0627\u06cc \u0632\u0645\u062e\u062a \u0648 \u06cc\u0627 \u0644\u06cc\u0641\u200c\u0647\u0627\u06cc \u0644\u0627\u06cc\u0647 \u0628\u0631\u062f\u0627\u0631 \u0628\u0631\u0627\u06cc \u0634\u0633\u062a\u0646 \u0627\u06cc\u0646 \u0646\u0648\u0627\u062d\u06cc \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/li>\n<li>\u062a\u0627 \u062d\u0630\u0641 \u06a9\u0627\u0645\u0644 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc\u060c \u0641\u0639\u0627\u0644\u06cc\u062a \u062c\u0646\u0633\u06cc \u0631\u0627 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0628\u0631\u0633\u0627\u0646\u06cc\u062f.<\/li>\n<li>\u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0627\u0632 \u0627\u06cc\u0646 \u067e\u0633\u060c \u0631\u0648\u0627\u0628\u0637 \u062c\u0646\u0633\u06cc \u06a9\u0646\u062a\u0631\u0644 \u0634\u062f\u0647 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u06a9\u0627\u0646\u062f\u0648\u0645 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/li>\n<li>\u0645\u0639\u0627\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0631\u062a\u0628 \u0648 \u062c\u062f\u06cc \u067e\u06cc\u06af\u06cc\u0631\u06cc \u06a9\u0646\u06cc\u062f\u200c.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87_%D9%87%D8%A7%DB%8C_%D8%A7%D9%86%D8%AA%D9%82%D8%A7%D9%84_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_hpv\"><\/span>\u0631\u0627\u0647 \u0647\u0627\u06cc \u0627\u0646\u062a\u0642\u0627\u0644 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc hpv<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u062a\u0646\u0647\u0627 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0648\u0627\u0698\u06cc\u0646\u0627\u0644 \u06cc\u0627 \u0645\u0642\u0639\u062f\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0686\u0627\u0631 \u0634\u0648\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u062f\u0627\u0634\u062a\u0646 \u062a\u0645\u0627\u0633 \u067e\u0648\u0633\u062a\u06cc \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u062c\u0646\u0633\u06cc \u0628\u0627 \u0641\u0631\u062f \u0628\u06cc\u0645\u0627\u0631 \u0628\u0631\u0627\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0648\u06cc\u0631\u0648\u0633 \u06a9\u0627\u0641\u06cc\u0633\u062a.<\/p>\n<p>\u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0648 \u0641\u0631\u062f \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0647\u06cc\u0686 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0628\u0627 \u062a\u0645\u0627\u0633 \u067e\u0648\u0633\u062a \u0622\u0644\u0648\u062f\u0647 \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc\u060c \u0628\u0627\u0639\u062b \u0627\u0646\u062a\u0642\u0627\u0644 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0634\u0648\u0646\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u0639\u0627\u0645\u0644 \u0627\u06cc\u062c\u0627\u062f \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0646\u0648\u0639\u06cc \u0648\u06cc\u0631\u0648\u0633 \u0627\u0633\u062a\u060c \u0641\u0631\u062f \u062d\u0627\u0645\u0644 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0646\u062a\u0642\u0627\u0644 \u062f\u0647\u0646\u062f\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p>\u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0627\u0646\u0648\u0627\u0646 \u0648 \u0622\u0642\u0627\u06cc\u0627\u0646\u06cc \u06a9\u0647 \u062e\u0648\u062f \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0631\u0627 \u062f\u0631 \u0628\u062f\u0646 \u062f\u0627\u0631\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0646\u0627\u0642\u0644 \u0627\u0641\u0631\u0627\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0631\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0686\u0627\u0631 \u06a9\u0646\u0646\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062d\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0627\u0646\u062f\u0648\u0645 \u0646\u06cc\u0632 \u06a9\u0627\u0641\u06cc \u0646\u06cc\u0633\u062a! \u0632\u06cc\u0631\u0627 \u0627\u06cc\u0646 \u067e\u0648\u0634\u0634 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0645\u0627\u0645\u06cc \u067e\u0648\u0633\u062a \u0627\u06cc\u0646 \u0646\u0648\u0627\u062d\u06cc \u0631\u0627 \u067e\u0648\u0634\u0634 \u062f\u0647\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0648\u06cc\u0631\u0648\u0633 \u067e\u0633 \u0627\u0632 \u0628\u0647 \u0648\u062c\u0648\u062f \u0622\u0645\u062f\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0645\u0646\u062a\u0642\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u067e\u0633 \u0627\u0632 \u0645\u0639\u0627\u06cc\u0646\u0647 \u062c\u0633\u0645\u06cc \u0634\u0631\u06cc\u06a9 \u062c\u0646\u0633\u06cc \u062e\u0648\u062f \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u0627\u0646\u062f\u0648\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u062f\u0648\u0646 \u0646\u06af\u0631\u0627\u0646\u06cc \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0628\u0631\u0642\u0631\u0627\u0631 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u06cc\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u062f\u0631 \u062f\u0647\u0627\u0646 \u06cc\u0627 \u06af\u0644\u0648 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u062f\u0647\u0627\u0646\u06cc \u0627\u0646\u062a\u0642\u0627\u0644 \u062f\u0627\u062f\u0647 \u0634\u062f\u0647 \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0645\u06a9\u0627\u0646 \u062f\u0627\u0631\u062f \u062a\u0627 \u0645\u0627\u062f\u0631 \u0622\u0644\u0648\u062f\u0647 \u0628\u0647 \u0648\u06cc\u0631\u0648\u0633 \u0627\u0686 \u067e\u06cc \u0648\u06cc \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u062a\u0648\u0644\u062f \u0646\u0648\u0632\u0627\u062f\u060c \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0631\u0627 \u0628\u0647 \u06a9\u0648\u062f\u06a9 \u062e\u0648\u062f \u0627\u0646\u062a\u0642\u0627\u0644 \u062f\u0647\u062f. \u0627\u0644\u0628\u062a\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u06cc\u0646 \u06af\u0648\u0646\u0647 \u0627\u0628\u062a\u0644\u0627 \u0634\u062f\u0646\u0631\u0628\u0633\u06cc\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646 \u0627\u0633\u062a \u0648 \u0628\u0647 \u0646\u062f\u0631\u062a \u0631\u062e \u0645\u06cc\u200c\u062f\u0647\u062f. \u062f\u0631 \u062d\u0627\u0644\u062a \u06a9\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u062d\u0648\u0644\u0647 \u062d\u0645\u0627\u0645 \u0628\u0647 \u0635\u0648\u0631\u062a \u0627\u0634\u062a\u0631\u0627\u06a9\u06cc \u0648 \u06cc\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u063a\u0630\u0627\u062e\u0648\u0631\u06cc \u0645\u0634\u062a\u0631\u06a9 \u0628\u0627\u0639\u062b \u0627\u0646\u062a\u0642\u0627\u0644 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\"><\/span><strong>\u062a\u0634\u062e\u06cc\u0635 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062a\u0646\u0647\u0627 \u0628\u0627 \u0645\u0639\u0627\u06cc\u0646\u0647 \u067e\u0632\u0634\u06a9 \u0648 \u063a\u0631\u0628\u0627\u0644\u06af\u0631\u06cc\u200c\u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0648\u062c\u0648\u062f \u062a\u0648\u062f\u0647\u200c\u0647\u0627\u06cc \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0631\u0627 \u062a\u0627\u06cc\u06cc\u062f \u06a9\u0631\u062f. \u0627\u0644\u0628\u062a\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0648\u0686\u06a9 \u0628\u0627\u0634\u0646\u062f \u0632\u06cc\u0631\u0627 \u062f\u0631 \u0645\u0631\u0627\u062d\u0644 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u062a\u0631\u060c \u062a\u0634\u062e\u06cc\u0635 \u0622\u0646\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u062e\u0648\u062f \u0627\u0641\u0631\u0627\u062f \u0646\u06cc\u0632 \u0633\u0627\u062f\u0647\u200c\u062a\u0631 \u0627\u0633\u062a. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0622\u0646\u200c\u0647\u0627 \u0627\u0634\u0627\u0631\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u0639\u0641\u0648\u0646\u062a \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f:<\/p>\n<ul>\n<li>\u0628\u0627\u0631\u062f\u0627\u0631 \u0628\u0648\u062f\u0646 \u06cc\u0627 \u0642\u0635\u062f \u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u062f\u0646<\/li>\n<li>\u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0642\u0627\u0631\u0628\u062a\u06cc<\/li>\n<li>\u062f\u0627\u0634\u062a\u0646 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0645\u062d\u0627\u0641\u0638\u062a \u0646\u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u062e\u0648\u062f\u062a\u0627\u0646 \u06cc\u0627 \u0647\u0645\u0633\u0631\u062a\u0627\u0646<\/li>\n<li>\u0628\u0631\u0648\u0632 \u0639\u0644\u0627\u0626\u0645 \u0645\u0634\u06a9\u0648\u06a9 \u0648 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0634\u0628\u06cc\u0647 \u0628\u0647 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc<\/li>\n<\/ul>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u067e\u0632\u0634\u06a9 \u0627\u0632 \u0645\u0642\u0639\u062f \u0648 \u06cc\u0627 \u0648\u0627\u0698\u0646 \u0628\u0631\u0627\u06cc \u0628\u0631\u0631\u0633\u06cc \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc \u0646\u0645\u0648\u0646\u0647\u200c\u0628\u0631\u062f\u0627\u0631\u06cc \u06a9\u0646\u062f\u060c \u0647\u0632\u06cc\u0646\u0647\u200c \u0627\u06cc\u0646 \u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627 \u0646\u0633\u0628\u062a\u0627 \u0628\u0627\u0644\u0627\u0633\u062a. \u0627\u0644\u0628\u062a\u0647 \u0627\u06cc\u0646 \u0646\u0645\u0648\u0646\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0628\u0627 \u0628\u06cc\u200c\u062d\u0633\u06cc \u0645\u0648\u0636\u0639\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0641\u0631\u062f \u062f\u0631\u062f \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u062a\u062d\u0645\u0644 \u0646\u06a9\u0646\u062f.<\/p>\n<p>\u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0648\u06cc\u0631\u0648\u0633 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0622\u0632\u0645\u0627\u06cc\u0634 \u062e\u0648\u0646 \u0627\u0646\u062c\u0627\u0645 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f. \u067e\u0633 \u0627\u0632 \u0628\u0631\u0631\u0633\u06cc\u200c\u0647\u0627\u06cc \u0644\u0627\u0632\u0645 \u0648 \u062a\u0634\u062e\u06cc\u0635 \u0642\u0637\u0639\u06cc \u067e\u0632\u0634\u06a9\u060c \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u062d\u0644\u060c \u062a\u0639\u062f\u0627\u062f \u0648 \u0634\u06a9\u0644 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u060c \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u062a\u0648\u0633\u0637 \u0645\u062a\u062e\u0635\u0635 \u0628\u0647 \u0627\u0641\u0631\u0627\u062f \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627 \u0628\u0631\u062f\u0627\u0634\u062a\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0647\u062f\u0641 \u0627\u0635\u0644\u06cc \u0627\u0633\u062a \u0648 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0622\u0646 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u0627 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062e\u0648\u0631\u0627\u06a9\u06cc \u0648 \u0645\u0648\u0627\u062f\u063a\u0630\u0627\u06cc\u06cc \u0645\u062e\u062a\u0644\u0641 \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0648\u06cc\u0631\u0648\u0633 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u0627\u0632\u06af\u0634\u062a \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9280 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0627\u0646\u0648\u0627\u0639-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc.webp\" alt=\"\u0631\u0627\u0647 \u0647\u0627\u06cc \u0627\u0646\u062a\u0642\u0627\u0644 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc hpv\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0627\u0646\u0648\u0627\u0639-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0627\u0646\u0648\u0627\u0639-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0627\u0646\u0648\u0627\u0639-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2021\/12\/\u0627\u0646\u0648\u0627\u0639-\u0632\u06af\u06cc\u0644-\u062a\u0646\u0627\u0633\u0644\u06cc-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\"><\/span><strong>\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u06af\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0632 \u0648\u06cc\u0631\u0648\u0633 \u0627\u0646\u0633\u0627\u0646\u06cc \u067e\u0627\u067e\u06cc\u0644\u0648\u0645\u0627 \u062a\u0627 \u0628\u0647 \u062d\u0627\u0644 \u06a9\u0634\u0641 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0641\u0642\u0637 \u0686\u0646\u062f \u0645\u0648\u0631\u062f \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0645\u062b\u0644 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0646\u0642\u0627\u0637 \u0645\u062e\u062a\u0644\u0641 \u0628\u062f\u0646 \u0641\u0631\u062f \u0634\u0648\u0646\u062f. \u0628\u0631\u062e\u06cc \u062f\u06cc\u06af\u0631 \u06a9\u0627\u0645\u0644\u0627 \u0628\u062f\u0648\u0646 \u0646\u0634\u0627\u0646\u0647 \u062f\u0631 \u0628\u062f\u0646 \u062a\u06a9\u062b\u06cc\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86\"><\/span><strong>\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06cc\u0646 \u0632\u06af\u06cc\u0644\u200c \u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0627\u0637\u0631\u0627\u0641 \u0648\u0627\u0698\u0646\u060c \u062f\u0627\u062e\u0644 \u0645\u0642\u0639\u062f \u06cc\u0627 \u0646\u0632\u062f\u06cc\u06a9 \u0631\u062d\u0645 \u0628\u0647 \u0648\u062c\u0648\u062f \u0628\u06cc\u0627\u06cc\u0646\u062f. \u0632\u06af\u06cc\u0644\u200c \u0647\u0627\u06cc \u0645\u0642\u0639\u062f\u06cc \u06a9\u0648\u0686\u06a9\u062a\u0631 \u0647\u0633\u062a\u0646\u062f \u0648\u0644\u06cc \u0632\u06af\u06cc\u0644\u200c \u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u06a9\u0647 \u062f\u0631 \u062f\u0627\u062e\u0644 \u0648\u0627\u0698\u0646 \u0648 \u062f\u0647\u0627\u0646\u0647 \u0631\u062d\u0645 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0634\u062f\u06cc\u062f\u06cc \u0645\u062b\u0644 \u0633\u0631\u0637\u0627\u0646 \u0634\u0648\u0646\u062f.<\/p>\n<p>\u0628\u0631\u062e\u06cc \u0627\u0632 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u062f\u0647\u0627\u0646\u0647 \u0645\u062c\u0627\u0631\u06cc \u0627\u062f\u0631\u0627\u0631\u060c \u06af\u0631\u062f\u0646\u0647 \u0631\u062d\u0645\u060c \u0646\u0648\u0627\u062d\u06cc \u0628\u06cc\u0646 \u0648\u0627\u0698\u0646 \u0648 \u0645\u0642\u0639\u062f\u060c \u06af\u0644\u0648 \u0648 \u062f\u0647\u0627\u0646 \u0628\u0647 \u0648\u062c\u0648\u062f \u0628\u06cc\u0627\u06cc\u0646\u062f. \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f \u067e\u0632\u0634\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062a\u0639\u062f\u0627\u062f \u0648 \u0634\u06a9\u0644 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u060c \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0645\u062a\u0641\u0627\u0648\u062a \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u062d\u0627\u0644\u0627\u062a \u0630\u06a9\u0631 \u0634\u062f\u0647 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\"><\/span><strong>\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u062f\u0631 \u062e\u0627\u0646\u0645\u200c\u0647\u0627 \u0634\u0627\u06cc\u0639\u200c\u062a\u0631 \u0627\u0633\u062a. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0631\u0648\u0632 \u0632\u06af\u06cc\u0644\u200c \u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631 \u0622\u0642\u0627\u06cc\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0645\u0628\u062a\u0644\u0627 \u0634\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u067e\u0633 \u0627\u0632 \u0645\u0627\u0647\u200c\u0647\u0627 \u0648 \u0633\u0627\u0644\u200c\u0647\u0627 \u0627\u062a\u0641\u0627\u0642 \u0628\u06cc\u0641\u062a\u062f. \u0627\u06cc\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0646\u0648\u06a9 \u0622\u0644\u062a \u062a\u0646\u0627\u0633\u0644\u06cc \u0648 \u0627\u0637\u0631\u0627\u0641 \u0645\u0642\u0639\u062f \u0628\u0647 \u0648\u062c\u0648\u062f \u0628\u06cc\u0627\u06cc\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u062f\u0631 \u062f\u0647\u0627\u0646\u060c \u062f\u0627\u062e\u0644 \u0645\u062c\u0627\u0631\u06cc \u0627\u062f\u0631\u0627\u0631\u06cc\u060c \u067e\u0648\u0633\u062a \u062e\u062a\u0646\u0647 \u06af\u0627\u0647\u060c \u0628\u0631 \u0631\u0648\u06cc \u0628\u06cc\u0636\u0647\u200c\u0647\u0627 \u0648 \u0641\u0627\u0635\u0644\u0647 \u06a9\u06cc\u0633\u0647 \u0628\u06cc\u0636\u0647 \u0648 \u0645\u0642\u0639\u062f \u0646\u06cc\u0632 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc\u06cc \u0631\u0634\u062f \u06a9\u0646\u0646\u062f.<\/p>\n<p><strong>\u067e\u0627\u0633\u062e \u0628\u0647 \u0633\u0648\u0627\u0644\u0627\u062a \u0634\u0645\u0627:<\/strong><\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%AF%D8%B1%D8%AF_%D8%AF%D8%A7%D8%B1%D8%AF%D8%9F\"><\/span>\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u0631\u062f \u062f\u0627\u0631\u062f\u061f<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u062e\u06cc\u0631 \u0627\u06cc\u0646 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u062f\u0631\u062f\u06cc \u0646\u062f\u0627\u0631\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u062f\u0631 \u0645\u0648\u0627\u0631\u062f \u062e\u06cc\u0644\u06cc \u0634\u062f\u06cc\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u062e\u0627\u0631\u0634 \u0648 \u0627\u0644\u062a\u0647\u0627\u0628 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u0646\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0634\u0645\u0627 \u0646\u0628\u0627\u06cc\u062f \u062a\u0627 \u06a9\u0627\u0645\u0644 \u0634\u062f\u0646 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u060c \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0648\u0627\u06af\u06cc\u0631\u062f\u0627\u0631 \u0627\u0633\u062a<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%AA%D9%81%D8%A7%D9%88%D8%AA_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D9%85%D8%B9%D9%85%D9%88%D9%84%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span>\u062a\u0641\u0627\u0648\u062a \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u0632\u06af\u06cc\u0644 \u0645\u0639\u0645\u0648\u0644\u06cc \u0686\u06cc\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u0634\u06a9\u0644 \u06af\u0631\u062f\u06cc \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0631 \u0631\u0648\u06cc \u06cc\u06a9 \u067e\u0627\u06cc\u0647 \u0627\u0635\u0644\u06cc \u0631\u0634\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0646\u06cc\u0633\u062a\u0646\u062f \u0627\u0645\u0627 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627\u0641\u062a \u0642\u0631\u0645\u0632 \u0631\u0646\u06af \u0648 \u0646\u0631\u0645\u06cc \u062f\u0627\u0631\u0646\u062f \u06a9\u0647 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062e\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0631\u062e\u0644\u0627\u0641 \u0632\u06af\u06cc\u0644\u200c\u062a\u0646\u0627\u0633\u0644\u06cc\u060c \u0631\u0634\u062f \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u0633\u0631\u06cc\u0639 \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0646\u06a9\u062a\u0647 \u0631\u0627 \u0647\u0645 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f \u06a9\u0647 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u0645\u0639\u0645\u0648\u0644\u06cc \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0631\u0627\u06cc\u062c \u0646\u06cc\u0633\u062a\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%DA%A9%D8%B1%D9%85_%D9%88_%D9%BE%D9%85%D8%A7%D8%AF_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0628\u0647\u062a\u0631\u06cc\u0646 \u06a9\u0631\u0645 \u0648 \u067e\u0645\u0627\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0686\u06cc\u0633\u062a\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0627\u0628\u062a\u062f\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u0645\u062a\u062e\u0635\u0635 \u067e\u0648\u0633\u062a \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0634\u06a9\u0644 \u0648 \u062a\u0639\u062f\u0627\u062f \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u062a\u0648\u0627\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0634\u0645\u0627 \u0631\u0627 \u062f\u0631\u0645\u0627\u0646 \u06a9\u0631\u062f. \u0627\u063a\u0644\u0628 \u0645\u0648\u0627\u0631\u062f \u0627\u0632 \u06a9\u0631\u0645\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0627\u0646\u062f\u06cc\u0644\u06cc\u0646 \u200c\u0648 \u0627\u0644\u062f\u0631\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%A8%D8%A7%D8%B9%D8%AB_%D8%AE%D8%A7%D8%B1%D8%B4_%D9%85%DB%8C%D8%B4%D9%88%D8%AF%D8%9F\"><\/span><strong>\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627\u0639\u062b \u062e\u0627\u0631\u0634 \u0645\u06cc\u0634\u0648\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062d\u0633 \u062e\u0627\u0631\u0634 \u0648 \u0627\u0644\u062a\u0647\u0627\u0628 \u062f\u0631 \u0645\u0648\u0627\u0631\u062f \u0628\u0633\u06cc\u0627\u0631 \u0646\u0627\u062f\u0631\u06cc \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f. \u062f\u0631 \u062d\u0627\u0644\u062a\u06cc \u06a9\u0647\u00a0 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627 \u062a\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0634\u062f \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0632\u0631\u06af \u0634\u062f\u0647 \u0628\u0627\u0634\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u067e\u0633 \u0627\u0632 \u062a\u0634\u062e\u06cc\u0635 \u067e\u0632\u0634\u06a9 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u0627\u0646\u062c\u0627\u0645 \u0647\u0631 \u062a\u062d\u0631\u06cc\u06a9 \u067e\u0648\u0633\u062a\u06cc \u0645\u062b\u0644 \u062e\u0627\u0631\u0634 \u0648 \u06cc\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644\u06cc \u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u062d\u0631\u06cc\u06a9 \u067e\u0648\u0633\u062a \u0627\u06cc\u0646 \u0646\u0648\u0627\u062d\u06cc \u0634\u0648\u0646\u062f\u060c \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%A2%DB%8C%D8%A7_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%85%D9%86%D8%AC%D8%B1_%D8%A8%D9%87_%D8%B3%D8%B1%D8%B7%D8%A7%D9%86_%D9%85%DB%8C%D8%B4%D9%88%D8%AF%D8%9F\"><\/span><strong>\u0622\u06cc\u0627 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0645\u0646\u062c\u0631 \u0628\u0647 \u0633\u0631\u0637\u0627\u0646 \u0645\u06cc\u0634\u0648\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0631\u06cc\u0633\u06a9 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u06cc \u0633\u0631\u0637\u0627\u0646 \u062a\u0648\u0633\u0637 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u06a9\u0645 \u062e\u0637\u0631 \u0628\u0633\u06cc\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646 \u0627\u0633\u062a \u0648 \u0641\u0642\u0637 \u0686\u0646\u062f \u0646\u0648\u0639 \u067e\u0631\u062e\u0637\u0631 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0645\u0631\u0627\u062d\u0644 \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u0633\u0631\u0637\u0627\u0646 \u0634\u0648\u0646\u062f. \u067e\u0633 \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f \u062f\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0648\u0642\u0627\u062a \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0628\u0627 \u0627\u0646\u062c\u0627\u0645 \u0646\u0645\u0648\u0646\u0647 \u0628\u0631\u062f\u0627\u0631\u06cc \u0648 \u062a\u0634\u062e\u06cc\u0635 \u0632\u0648\u062f\u0647\u0646\u06af\u0627\u0645 \u0622\u0644\u0648\u062f\u0647 \u0634\u062f\u0646 \u0628\u0647 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633\u060c \u0628\u0627 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062a\u062c\u0648\u06cc\u0632\u06cc \u062a\u0648\u0633\u0637 \u067e\u0632\u0634\u06a9 \u0627\u0632 \u0634\u0631 \u0627\u06cc\u0646 \u0632\u0627\u0626\u062f\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u0633\u062a\u06cc \u062e\u0644\u0627\u0635 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u0644\u0628\u062a\u0647 \u067e\u0633 \u0627\u0632 \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0646\u062c\u0627\u0645 \u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc \u062e\u0627\u0635 \u0628\u0631\u0627\u06cc \u062e\u0627\u0646\u0645\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0633\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u06f3\u06f0 \u0633\u0627\u0644 \u0648 \u0622\u0642\u0627\u06cc\u0627\u0646\u06cc \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0636\u0639\u06cc\u0641\u200c\u062a\u0631\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D9%88%D8%A7%D8%B9_%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C\"><\/span><strong>\u0627\u0646\u0648\u0627\u0639 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u062d\u0627\u0644\u062a \u06a9\u0644\u06cc \u062a\u0646\u0647\u0627 \u0686\u0646\u062f \u0646\u0648\u0639 \u0627\u0632 \u0627\u06cc\u0646 \u062a\u06cc\u067e\u200c\u0647\u0627 \u0646\u06af\u0631\u0627\u0646 \u06a9\u0646\u0646\u062f\u0647 \u0647\u0633\u062a\u0646\u062f \u0648 \u0633\u0627\u06cc\u0631 \u0648\u06cc\u0631\u0648\u0633\u200c\u0647\u0627 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0633\u0627\u062f\u0647 \u06a9\u0646\u062a\u0631\u0644 \u06a9\u0631\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B6\"><\/span><strong>\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u0648\u0639 \u06f6<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u06a9\u0645 \u062e\u0637\u0631 \u0627\u0633\u062a \u0648 \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0647 \u0634\u06a9\u0644 \u06af\u0644 \u06a9\u0644\u0645 \u062f\u0631 \u0645\u0642\u0639\u062f \u0648 \u0646\u0648\u0627\u062d\u06cc \u062a\u0646\u0627\u0633\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u06a9\u0627\u0647\u0634 \u0634\u0631\u06a9\u0627\u06cc \u062c\u0646\u0633\u06cc \u0648 \u0632\u062f\u0646 \u0648\u0627\u06a9\u0633\u0646 \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B1%DB%B1\"><\/span><strong>\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u0648\u0639 \u06f1\u06f1<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0646\u06cc\u0632 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0632\u06af\u06cc\u0644\u200c\u0647\u0627\u06cc \u062e\u0641\u06cc\u0641 \u062a\u0646\u0627\u0633\u0644\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u062d\u0646\u06cc\u0641 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0628\u0627\u0646\u0648\u0627\u0646 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u062f\u0631 \u0633\u0627\u062e\u062a\u0627\u0631 \u0631\u062d\u0645 \u0634\u0648\u062f. \u0646\u06af\u0631\u0627\u0646 \u0646\u0628\u0627\u0634\u06cc\u062f \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0646\u06cc\u0632 \u062c\u0632\u0621 \u0645\u0648\u0627\u0631\u062f \u06a9\u0645 \u062e\u0637\u0631 \u0627\u0633\u062a \u0648 \u0628\u0627 \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0631\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646 \u06a9\u0631\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B1%DB%B6\"><\/span><strong>\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><strong>\u00a0\u0646\u0648\u0639 \u06f1\u06f6<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0628\u0633\u06cc\u0627\u0631 \u0634\u0627\u06cc\u0639 \u0627\u0633\u062a \u0648\u0644\u06cc \u0647\u06cc\u0686 \u0639\u0644\u0627\u0645\u062a \u0648 \u0646\u0634\u0627\u0646\u0647\u200c\u0627\u06cc \u0646\u062f\u0627\u0631\u062f. \u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u067e\u0633 \u0627\u0632 \u062f\u0648\u0631\u0647 \u0646\u0647\u0641\u062a\u06af\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0627 \u06f5\u06f0 \u062f\u0631\u0635\u062f \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0633\u0631\u0637\u0627\u0646 \u0631\u062d\u0645 \u062f\u0631 \u0628\u0627\u0646\u0648\u0627\u0646 \u0634\u0648\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B2%DA%AF%DB%8C%D9%84_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D9%86%D9%88%D8%B9_%DB%B1%DB%B8\"><\/span><strong>\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/strong><strong>\u00a0\u0646\u0648\u0639 \u06f1\u06f8<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u067e\u0631\u062e\u0637\u0631\u062a\u0631\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u062a\u06cc\u067e \u06f1\u06f8 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f \u06a9\u0647 \u062a\u0627 \u06f7\u06f0 \u062f\u0631\u0635\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0633\u0631\u0637\u0627\u0646 \u062f\u0647\u0627\u0646\u0647 \u0631\u062d\u0645 \u0634\u0648\u062f.<\/p>\n<p><strong>\u0646\u06a9\u062a\u0647:<\/strong> \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0647 \u062a\u0646\u0647\u0627\u06cc\u06cc \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0633\u0631\u0637\u0627\u0646 \u0634\u0648\u062f \u0628\u0644\u06a9\u0647 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0633\u0644\u0648\u0644\u200c\u0647\u0627\u06cc \u0628\u062f\u0646 \u062a\u0648\u0633\u0637 \u0628\u0627 \u0648\u0631\u0648\u062f \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0627\u062a\u0641\u0627\u0642 \u0645\u06cc\u200c\u0627\u0641\u062a\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0646\u062c\u0631 \u0628\u0647 \u0633\u0631\u0637\u0627\u0646 \u0634\u0648\u0646\u062f. \u0631\u0634\u062f \u063a\u06cc\u0631 \u0637\u0628\u06cc\u0639\u06cc \u0633\u0644\u0648\u0644\u200c\u0647\u0627 \u0627\u062d\u062a\u0645\u0627\u0644 \u0633\u0631\u0637\u0627\u0646\u06cc \u0634\u062f\u0646 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"%D8%B3%D8%B1%D8%B7%D8%A7%D9%86_%D9%87%D8%A7%DB%8C_%D9%86%D8%A7%D8%B4%DB%8C_%D8%A7%D8%B2_%D9%88%DB%8C%D8%B1%D9%88%D8%B3_HPV\"><\/span><strong>\u0633\u0631\u0637\u0627\u0646 \u0647\u0627\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0648\u06cc\u0631\u0648\u0633 <\/strong><strong>HPV<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u0633\u0631\u0637\u0627\u0646 \u062f\u0647\u0627\u0646\u060c \u0633\u0631\u0637\u0627\u0646 \u0645\u0642\u0639\u062f\u060c \u0633\u0631\u0637\u0627\u0646 \u0622\u0644\u062a \u062a\u0646\u0627\u0633\u0644\u06cc \u0645\u0631\u062f\u0627\u0646\u0647 \u0648 \u0633\u0631\u0637\u0627\u0646 \u0631\u062d\u0645 \u062f\u0631 \u0632\u0646\u0627\u0646 \u0634\u0648\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B2%DA%AF%DB%8C%D9%84%E2%80%8C_%D8%AA%D9%86%D8%A7%D8%B3%D9%84%DB%8C_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86_%D8%AF%D8%B1_%D8%AE%D8%A7%D9%86%D9%87\"><\/span>\u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u062f\u0631 \u062e\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0634\u0627\u06cc\u0639\u200c\u062a\u0631\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0642\u0627\u0631\u0628\u062a\u06cc \u0645\u06cc\u200c\u0628\u0627\u0634\u062f \u0648 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u063a\u06cc\u0631 \u062a\u0647\u0627\u062c\u0645\u06cc \u0648 \u062e\u0627\u0646\u06af\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0631\u0627 \u062f\u0631\u0645\u0627\u0646 \u06a9\u0631\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0633\u0627\u0644\u0645 \u0648 \u062f\u0627\u0634\u062a\u0646 \u0634\u0631\u06cc\u06a9 \u062c\u0646\u0633\u06cc \u0633\u0627\u0644\u0645 \u0648 \u0639\u062f\u0645 \u0631\u0648\u0627\u0628\u0637 \u062c\u0646\u0633\u06cc \u067e\u0631 \u062e\u0637\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0628\u0631\u06af\u0634\u062a \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0631\u062f.<\/p>\n<p>\u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u0641\u0648\u0631\u06cc \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0635\u0627\u0628\u0648\u0646 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0628\u0627 \u0633\u0631\u0639\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0631\u0645\u0627\u0646 \u0634\u0648\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0627\u0644\u062a\u0647\u0627\u0628\u0627\u062a \u0627\u06cc\u0646 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f. \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647<a href=\"https:\/\/bizma.ir\/product\/dr-biz-special-hpv-package\/\" target=\"_blank\" rel=\"noopener\"> \u067e\u06a9\u06cc\u062c \u062f\u0631\u0645\u0627\u0646 \u0632\u06af\u06cc\u0644\u200c \u062a\u0646\u0627\u0633\u0644\u06cc \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a> \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u062f\u0631 \u062e\u0627\u0646\u0647\u00a0\u0627\u06cc\u0646 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0628\u06cc\u0632\u0645\u0627 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0645\u0642\u0627\u0644\u0627\u062a \u0645\u0631\u062a\u0628\u0637 :<\/p>\n<ul>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/home-treatment-of-hpv\/\">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0648\u062b\u0631\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc<\/a><\/li>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/treatment-of-vaginal-dryness\/\">\u062f\u0631\u0645\u0627\u0646 \u062e\u0634\u06a9\u06cc \u0648\u0627\u0698\u0646 \u0641\u0648\u0631\u06cc \u062f\u0631 \u062e\u0627\u0646\u0647<\/a><\/li>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/benefits-mens-hygiene-gel\/\">\u0698\u0644 \u0628\u0647\u062f\u0627\u0634\u062a\u06cc \u0622\u0642\u0627\u06cc\u0627\u0646 \u0686\u06cc\u0633\u062a \u0648 \u0686\u0647 \u0641\u0648\u0627\u06cc\u062f\u06cc \u062f\u0627\u0631\u062f<\/a><\/li>\n<\/ul>\n<div id=\"gtx-trans\" style=\"position: absolute; left: 728px; top: 3900.34px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0686 \u067e\u06cc \u0648\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 \u0648\u06cc\u0631\u0648\u0633 \u067e\u0627\u067e\u06cc\u0644\u0648\u0645\u0627\u06cc \u0627\u0646\u0633\u0627\u0646\u06cc\u060c \u0639\u0627\u0645\u0644 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u0646\u062f\u0647 \u0632\u06af\u06cc\u0644 \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u0627\u0646\u0648\u0627\u0639 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0631\u0627\u0642\u0628\u062a\u06cc \u0627\u0633\u062a\u060c \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0627\u06af\u0631 \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0647\u0645 \u0627\u06a9\u0646\u0648\u0646 \u0628\u06cc\u0634 \u0627\u0632 \u06f4\u06f0 \u06af\u0648\u0646\u0647 \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u0627\u06cc\u0646 \u0648\u06cc\u0631\u0648\u0633 \u06a9\u0634\u0641 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u062a\u0627\u062b\u06cc\u0631\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0631 \u0646\u0627\u062d\u06cc\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u0628\u0627 \u0628\u0631\u0648\u0632 \u0636\u0627\u06cc\u0639\u0627\u062a \u067e\u0648\u0633\u062a\u06cc \u06af\u0648\u0646\u0627\u06af\u0648\u0646\u06cc \u0646\u0645\u0627\u06cc\u0634 &hellip;<\/p>\n","protected":false},"author":2787,"featured_media":9282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[236],"class_list":["post-4371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health","tag-hpv"],"_links":{"self":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts\/4371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/users\/2787"}],"replies":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/comments?post=4371"}],"version-history":[{"count":0,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts\/4371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/media\/9282"}],"wp:attachment":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/media?parent=4371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/categories?post=4371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/tags?post=4371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}