{"id":4381,"date":"2022-06-13T14:30:55","date_gmt":"2022-06-13T11:00:55","guid":{"rendered":"https:\/\/bizma.ir\/?p=4381"},"modified":"2024-09-30T14:31:08","modified_gmt":"2024-09-30T11:01:08","slug":"infertility-treatment","status":"publish","type":"post","link":"https:\/\/bizma.ir\/mag\/infertility-treatment\/","title":{"rendered":"\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0686\u06cc\u0633\u062a\u061f \u0639\u0644\u0627\u0626\u0645 \u0648 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc"},"content":{"rendered":"<p>\u0642\u0628\u0644 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0632\u0648\u062c\u200c\u0647\u0627 \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u062c\u0647\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0631\u0627 \u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0627\u0648\u0644 \u0627\u0632\u062f\u0648\u0627\u062c \u062e\u0648\u062f \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f \u0648\u0644\u06cc \u067e\u0633 \u0627\u0632 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0631\u062f\u0646 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0627 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062a\u0648\u0627\u0646\u0633\u062a\u0647\u200c\u0627\u0646\u062f \u0635\u0627\u062d\u0628 \u0641\u0631\u0632\u0646\u062f \u0634\u0648\u062f. \u0627\u062d\u0633\u0627\u0633 \u0644\u0630\u062a \u067e\u062f\u0631 \u0648 \u0645\u0627\u062f\u0631 \u0634\u062f\u0646 \u062a\u062c\u0631\u0628\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u062e\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0646\u062a\u0648\u0627\u0646\u0646\u062f \u0622\u0646 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u0646\u062f. \u0622\u062e\u0631\u06cc\u0646 \u062a\u0639\u0631\u06cc\u0641\u06cc \u06a9\u0647 \u062c\u0627\u0645\u0639\u0647 \u067e\u0632\u0634\u06a9\u0627\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0627\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0627\u0631\u0627\u0626\u0647 \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u0648\u062c\u0648\u062f \u062a\u0644\u0627\u0634\u200c\u0647\u0627\u06cc \u0645\u06a9\u0631\u0631 \u0628\u062f\u0648\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u067e\u0633 \u06af\u0630\u0634\u062a \u06cc\u06a9\u0633\u0627\u0644 \u0645\u0648\u0641\u0642 \u0628\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0646\u0634\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0645\u06cc \u062a\u0648\u0627\u0646 \u0634\u06a9 \u06a9\u0631\u062f \u06a9\u0647 \u0627\u0641\u0631\u0627\u062f \u0646\u0627\u0628\u0627\u0631\u0648\u0631 \u0647\u0633\u062a\u0646\u062f. \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0642\u0627\u0644\u0647 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u062a\u0645\u0627\u0645\u06cc \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\u060c \u0639\u0644\u0644 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u0645 \u062a\u0627 \u067e\u0627\u06cc\u0627\u0646 \u0645\u062a\u0646 \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0647\u06cc\u062f \u062e\u0648\u0627\u0646\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D9%81%D8%B1%D8%A7%DB%8C%D9%86%D8%AF_%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%AA%D8%AE%D9%85%DA%A9\" >\u0641\u0631\u0627\u06cc\u0646\u062f \u0628\u0627\u0631\u0648\u0631\u06cc \u062a\u062e\u0645\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%B9%D9%84%D9%84_%D8%A7%D8%B5%D9%84%DB%8C_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D9%88_%D9%86%D8%A7%D8%B2%D8%A7%DB%8C%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u0639\u0644\u0644 \u0627\u0635\u0644\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0648 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0686\u06cc\u0633\u062a\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D8%A7%D8%B3%D9%BE%D8%B1%D9%85_%D8%B3%D8%A7%D9%84%D9%85_%D9%88_%DA%A9%D8%A7%D9%81%DB%8C_%D8%AA%D9%88%D8%B3%D8%B7_%D9%85%D8%B1%D8%AF\" >\u0639\u062f\u0645 \u062a\u0648\u0644\u06cc\u062f \u0627\u0633\u067e\u0631\u0645 \u0633\u0627\u0644\u0645 \u0648 \u06a9\u0627\u0641\u06cc \u062a\u0648\u0633\u0637 \u0645\u0631\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D8%AA%D8%AE%D9%85%DA%A9_%D8%B3%D8%A7%D9%84%D9%85_%D8%A8%D8%AF%D9%86_%D8%B2%D9%86\" >\u0639\u062f\u0645 \u062a\u0648\u0644\u06cc\u062f \u062a\u062e\u0645\u06a9 \u0633\u0627\u0644\u0645 \u0628\u062f\u0646 \u0632\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%A7%D9%86%D8%B3%D8%AF%D8%A7%D8%AF_%D9%84%D9%88%D9%84%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B1%D8%AD%D9%85%DB%8C\" >\u0627\u0646\u0633\u062f\u0627\u062f \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0631\u062d\u0645\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D8%A7%D9%86%D8%A7%DB%8C%DB%8C_%D8%A7%D8%B3%D9%BE%D8%B1%D9%85_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B1%D9%88%D8%B1_%DA%A9%D8%B1%D8%AF%D9%86_%D8%AA%D8%AE%D9%85%DA%A9\" >\u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0627\u0633\u067e\u0631\u0645 \u062f\u0631 \u0628\u0627\u0631\u0648\u0631 \u06a9\u0631\u062f\u0646 \u062a\u062e\u0645\u06a9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D8%A7%D9%86%D8%A7%DB%8C%DB%8C_%D8%AA%D8%AE%D9%85%DA%A9_%D8%A8%D8%A7%D8%B1%D9%88%D8%B1_%D8%AF%D8%B1_%D9%84%D8%A7%D9%86%D9%87_%DA%AF%D8%B2%DB%8C%D9%86%DB%8C\" >\u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062a\u062e\u0645\u06a9 \u0628\u0627\u0631\u0648\u0631 \u062f\u0631 \u0644\u0627\u0646\u0647 \u06af\u0632\u06cc\u0646\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%AF%D9%84%D8%A7%DB%8C%D9%84_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D9%85%D8%B1%D8%AF%D8%A7%D9%86_%D9%88_%D8%B2%D9%86%D8%A7%D9%86\" >\u062f\u0644\u0627\u06cc\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%B9%D9%88%D8%A7%D9%85%D9%84_%D8%AE%D8%A7%D8%B1%D8%AC%DB%8C_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" >\u0639\u0648\u0627\u0645\u0644 \u062e\u0627\u0631\u062c\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%B3%D9%86_%D9%88_%D8%AE%D8%B7%D8%B1_%D8%A8%D8%B1%D9%88%D8%B2_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" >\u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0646 \u0648 \u062e\u0637\u0631 \u0628\u0631\u0648\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%A2%D8%B2%D9%85%D8%A7%DB%8C%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\" >\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%AA%D8%B3%D8%AA_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B2%D9%86%D8%A7%D9%86\" >\u062a\u0633\u062a \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u0632\u0646\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\" >\u062a\u0634\u062e\u06cc\u0635 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%DA%86%D9%87_%D8%B2%D9%85%D8%A7%D9%86%DB%8C_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A8%D9%87_%D9%BE%D8%B2%D8%B4%DA%A9_%D9%85%D8%B1%D8%A7%D8%AC%D8%B9%D9%87_%DA%A9%D8%B1%D8%AF%D8%9F\" >\u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0631\u062f\u061f<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D9%85%D9%87%D9%85%E2%80%8C%D8%AA%D8%B1%DB%8C%D9%86_%D8%B1%D9%88%D8%B4_%D8%AF%D8%B1_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" >\u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\" >\u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D9%82%D8%A7%D8%B1%DA%86_%DA%AF%D8%A7%D9%86%D9%88%D8%AF%D8%B1%D9%85%D8%A7_%D9%88_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" >\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D8%AA%D8%A7%D8%AB%DB%8C%D8%B1_%D9%82%D9%87%D9%88%D9%87_%D8%B3%D9%88%D9%BE%D8%B1%DB%8C%D9%85_%DA%AF%D8%A7%D9%86%D9%88%D8%AF%D8%B1%D9%85%D8%A7_%D8%AF%D8%B1_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" >\u062a\u0627\u062b\u06cc\u0631 \u0642\u0647\u0648\u0647 \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/bizma.ir\/mag\/infertility-treatment\/#%D9%86%D8%AD%D9%88%D9%87_%D9%85%D8%B5%D8%B1%D9%81_%D9%82%D9%87%D9%88%D9%87_%DA%AF%D8%A7%D9%86%D9%88%D8%AF%D8%B1%D9%85%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%B2%D8%A7%DB%8C%DB%8C_%D9%88_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" >\u0646\u062d\u0648\u0647 \u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h2><span class=\"ez-toc-section\" id=\"%D9%81%D8%B1%D8%A7%DB%8C%D9%86%D8%AF_%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%AA%D8%AE%D9%85%DA%A9\"><\/span><strong>\u0641\u0631\u0627\u06cc\u0646\u062f \u0628\u0627\u0631\u0648\u0631\u06cc \u062a\u062e\u0645\u06a9<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0641\u0631\u0627\u06cc\u0646\u062f \u062a\u0648\u0644\u06cc\u062f \u0645\u062b\u0644 \u062f\u0631 \u0627\u0646\u0633\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0627\u0633\u062a. \u0641\u0631\u0627\u06cc\u0646\u062f \u0644\u0642\u0627\u062d \u0648 \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u0646\u062f \u062a\u0627 \u0641\u0631\u062f \u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u0648\u062f. \u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0647\u0631 \u0645\u0627\u0647 \u0628\u0647 \u062e\u0627\u0637\u0631 \u067e\u06cc\u0627\u0645\u06cc \u06a9\u0647 \u0627\u0632 \u0647\u06cc\u067e\u0648\u0641\u06cc\u0632 \u0628\u0627 \u0622\u0632\u0627\u062f \u0634\u062f\u0646 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u0647\u06cc\u067e\u0648\u0641\u06cc\u0632\u06cc \u0628\u0647 \u062a\u062e\u0645\u062f\u0627\u0646 \u0645\u06cc\u200c\u0631\u0633\u062f\u060c \u0628\u062f\u0646 \u0632\u0646 \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u062e\u0645\u06af\u0630\u0627\u0631\u06cc \u0622\u0645\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u062d\u0642\u06cc\u0642\u062a \u0627\u06cc\u0646 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627 \u062a\u062e\u0645\u062f\u0627\u0646 \u0631\u0627 \u062a\u062d\u0631\u06cc\u06a9 \u0628\u0647 \u0631\u0647\u0627\u0633\u0627\u0632\u06cc \u062a\u062e\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u062f\u0631 \u0631\u0648\u0632\u0647\u0627\u06cc \u06f1\u06f4 \u062a\u0627 \u06f2\u06f8 \u067e\u0633 \u0627\u0632 \u0634\u0631\u0648\u0639 \u0642\u0627\u0639\u062f\u06af\u06cc\u060c \u0628\u0627\u0644\u0627\u062a\u0631\u06cc\u0646 \u0634\u0627\u0646\u0633 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062a\u062e\u0645\u06a9 \u0628\u0639\u062f \u0627\u0632 \u0622\u0632\u0627\u062f \u0634\u062f\u0646 \u062f\u0631 \u0637\u0648\u0644 \u0644\u0648\u0644\u0647 \u0641\u0627\u0644\u0648\u067e \u062d\u0631\u06a9\u062a \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062a\u0627 \u06f2\u06f4 \u0633\u0627\u0639\u062a \u0627\u0645\u06a9\u0627\u0646 \u0628\u0627\u0631\u0648\u0631 \u0634\u062f\u0646 \u062f\u0627\u0631\u062f.<a href=\"https:\/\/bizma.ir\/product\/sexual-enhancement-pack\/\"><img decoding=\"async\" class=\"aligncenter wp-image-7491 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0648\u0627\u06cc-\u062c\u0646\u0633\u06cc-\u0645\u06af.jpg\" alt=\"\u067e\u06a9\u06cc\u062c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u0648\u0627\u06cc \u062c\u0646\u0633\u06cc \u0648 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\" width=\"728\" height=\"90\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0648\u0627\u06cc-\u062c\u0646\u0633\u06cc-\u0645\u06af.jpg 728w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0648\u0627\u06cc-\u062c\u0646\u0633\u06cc-\u0645\u06af-300x37.jpg 300w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><\/a><\/p>\n<p>\u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0627\u062d\u062a\u0645\u0627\u0644 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0645\u062d\u0627\u0641\u0638\u062a \u0646\u0634\u062f\u0647 \u062f\u0648 \u0631\u0648\u0632 \u0642\u0628\u0644 \u0627\u0632 \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0635\u0648\u0631\u062a \u06af\u0631\u0641\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0628\u06cc\u0634\u062a\u0631\u06cc\u0646 \u0645\u06cc\u0632\u0627\u0646 \u062e\u0648\u062f\u0634 \u0627\u0633\u062a. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u0633\u067e\u0631\u0645 \u062a\u0646\u0647\u0627 \u062a\u0627 \u06f7\u06f2 \u0633\u0627\u0639\u062a \u0642\u0627\u0628\u0644\u06cc\u062a \u0628\u0627\u0631\u0648\u0631 \u0633\u0627\u0632\u06cc \u062a\u062e\u0645\u06a9 \u0631\u0627 \u062f\u0627\u0631\u062f. \u062f\u0631 \u0637\u0648\u0644 \u0627\u06cc\u0646 \u06f7\u06f2 \u0633\u0627\u0639\u062a\u060c \u062a\u062e\u0645\u06a9 \u0646\u06cc\u0632 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u0641\u0639\u0627\u0644 \u062f\u0631 \u0644\u0648\u0644\u0647 \u0641\u0627\u0644\u0648\u067e \u062d\u0636\u0648\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u0647 \u0627\u0633\u067e\u0631\u0645 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062a\u062e\u0645\u06a9 \u0628\u0631\u0633\u062f\u060c \u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u0632\u0627\u0644 \u0645\u0631\u062f \u0628\u0627\u06cc\u062f \u0645\u0627\u06cc\u0639 \u0645\u0646\u06cc \u06a9\u0627\u0641\u06cc \u0648 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a\u06cc \u0648\u0627\u0631\u062f \u0648\u0627\u0698\u0646 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f. \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627 \u0628\u0627\u06cc\u062f \u0642\u062f\u0631\u062a \u062d\u0631\u06a9\u062a \u0648 \u0634\u06a9\u0644 \u0633\u0627\u0644\u0645\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 ph \u0645\u062d\u06cc\u0637 \u0631\u062d\u0645 \u0648 \u0648\u0627\u0698\u0646 \u0632\u0646 \u0646\u06cc\u0632 \u0637\u0648\u0631\u06cc \u0628\u0627\u0634\u062f \u062a\u0627 \u0627\u0645\u06a9\u0627\u0646 \u062d\u0631\u06a9\u062a \u0627\u0633\u067e\u0631\u0645 \u0628\u0647 \u0633\u0645\u062a \u062a\u062e\u0645\u06a9 \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9061 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646.webp\" alt=\"\u0639\u0644\u0644 \u0627\u0635\u0644\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0648 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0686\u06cc\u0633\u062a\u061f\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B9%D9%84%D9%84_%D8%A7%D8%B5%D9%84%DB%8C_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D9%88_%D9%86%D8%A7%D8%B2%D8%A7%DB%8C%DB%8C_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span><strong>\u0639\u0644\u0644<\/strong> <strong>\u0627\u0635\u0644\u06cc<\/strong> <strong>\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0648 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0686\u06cc\u0633\u062a\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u062d\u0627\u0644\u062a \u0639\u0645\u0648\u0645\u06cc \u0627\u06af\u0631 \u062f\u0631 \u0647\u0631 \u06cc\u06a9 \u0627\u0632 \u0645\u0631\u0627\u062d\u0644 \u0630\u06a9\u0631 \u0634\u062f\u0647\u060c \u0628\u062f\u0646 \u06a9\u0627\u0631\u06a9\u0631\u062f \u0635\u062d\u06cc\u062d \u062e\u0648\u062f \u0631\u0627 \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0641\u0631\u0627\u062f \u062f\u0686\u0627\u0631 <a href=\"https:\/\/fa.wikipedia.org\/wiki\/%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\" target=\"_blank\" rel=\"noopener\">\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a> \u0628\u0627\u0634\u0646\u062f. \u062f\u0631 \u062d\u0627\u0644\u062a \u0639\u0627\u062f\u06cc \u0627\u0633\u067e\u0631\u0645 \u0633\u0627\u0644\u0645 \u0648 \u0642\u0627\u0628\u0644 \u0642\u0628\u0648\u0644 \u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u062f\u0631 \u0628\u062f\u0646 \u0645\u0631\u062f \u0628\u0627 \u062a\u062e\u0645\u06a9 \u0633\u0627\u0644\u0645 \u062f\u0631 \u0628\u062f\u0646 \u0632\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u062a\u062e\u0645\u06a9 \u0628\u0627\u0631\u0648\u0631 \u0634\u062f\u0647\u060c \u0633\u0644\u0648\u0644 \u062a\u062e\u0645 \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0633\u067e\u0633 \u062a\u0642\u0633\u06cc\u0645\u0627\u062a \u0633\u0644\u0648\u0644\u06cc \u0628\u0627 \u0633\u0631\u0639\u062a \u0628\u0627\u0644\u0627\u06cc\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u062c\u0646\u06cc\u0646 \u062f\u0631 \u0628\u062f\u0646 \u0645\u0627\u062f\u0631 \u0631\u0634\u062f \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0645\u062a\u0648\u0644\u062f \u0645\u06cc\u200c\u0634\u0648\u062f. \u0639\u062f\u0645 \u06a9\u0627\u0631\u06a9\u0631\u062f \u0635\u062d\u06cc\u062d \u062f\u0633\u062a\u06af\u0627\u0647 \u062a\u0648\u0644\u06cc\u062f \u0645\u062b\u0644 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0639\u0644\u062a \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0644\u0627\u06cc\u0644 \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644:<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D8%A7%D8%B3%D9%BE%D8%B1%D9%85_%D8%B3%D8%A7%D9%84%D9%85_%D9%88_%DA%A9%D8%A7%D9%81%DB%8C_%D8%AA%D9%88%D8%B3%D8%B7_%D9%85%D8%B1%D8%AF\"><\/span><strong>\u0639\u062f\u0645 \u062a\u0648\u0644\u06cc\u062f \u0627\u0633\u067e\u0631\u0645 \u0633\u0627\u0644\u0645 \u0648 \u06a9\u0627\u0641\u06cc \u062a\u0648\u0633\u0637 \u0645\u0631\u062f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u06cc\u062c\u200c\u062a\u0631\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646\u060c \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u0627\u0633\u067e\u0631\u0645 \u0634\u06a9\u0644 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u062a\u062d\u0631\u06a9 \u0627\u06cc\u0646 \u0633\u0644\u0648\u0644 \u0647\u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D9%84%DB%8C%D8%AF_%D8%AA%D8%AE%D9%85%DA%A9_%D8%B3%D8%A7%D9%84%D9%85_%D8%A8%D8%AF%D9%86_%D8%B2%D9%86\"><\/span><strong>\u0639\u062f\u0645 \u062a\u0648\u0644\u06cc\u062f \u062a\u062e\u0645\u06a9 \u0633\u0627\u0644\u0645 \u0628\u062f\u0646 \u0632\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0648 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0646\u0648\u0628\u062a \u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0646\u062f\u0627\u0634\u062a\u0646 \u062a\u062e\u0645\u06a9 \u0633\u0627\u0644\u0645 \u0648 \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u0631\u0648\u0646\u062f \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0627\u0633\u062a.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%86%D8%B3%D8%AF%D8%A7%D8%AF_%D9%84%D9%88%D9%84%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%B1%D8%AD%D9%85%DB%8C\"><\/span><strong>\u0627\u0646\u0633\u062f\u0627\u062f \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0631\u062d\u0645\u06cc <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u0633\u0644\u0648\u0644\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0631\u0645 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0627\u06cc\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627 \u0628\u0647 \u062a\u062e\u0645\u06a9 \u0645\u06cc\u200c\u0631\u0633\u0646\u062f\u060c \u0633\u0627\u0644\u0645 \u0628\u0648\u062f\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0631\u062d\u0645\u06cc \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0634\u0627\u0646\u0633 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u062f\u060c \u0627\u0632 \u0637\u0631\u0641\u06cc \u0627\u0646\u0633\u062f\u0627\u062f \u0648 \u06af\u0631\u0641\u062a\u06af\u06cc \u062f\u0631 \u06cc\u06a9 \u06cc\u0627 \u0647\u0631 \u062f\u0648 \u0644\u0648\u0644\u0647\u200c \u0628\u0627\u0639\u062b \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D8%A7%D9%86%D8%A7%DB%8C%DB%8C_%D8%A7%D8%B3%D9%BE%D8%B1%D9%85_%D8%AF%D8%B1_%D8%A8%D8%A7%D8%B1%D9%88%D8%B1_%DA%A9%D8%B1%D8%AF%D9%86_%D8%AA%D8%AE%D9%85%DA%A9\"><\/span><strong>\u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0627\u0633\u067e\u0631\u0645 \u062f\u0631 \u0628\u0627\u0631\u0648\u0631 \u06a9\u0631\u062f\u0646 \u062a\u062e\u0645\u06a9<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0633\u0644\u0648\u0644 \u0627\u0633\u067e\u0631\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0646\u0641\u0648\u0630 \u0628\u0647 \u063a\u0634\u0627\u06cc \u0633\u0644\u0648\u0644 \u062a\u062e\u0645\u06a9 \u0648 \u0628\u0627\u0631\u0648\u0631 \u06a9\u0631\u062f\u0646 \u0622\u0646 \u0631\u0627 \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0631\u062f \u062f\u0686\u0627\u0631 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B9%D8%AF%D9%85_%D8%AA%D9%88%D8%A7%D9%86%D8%A7%DB%8C%DB%8C_%D8%AA%D8%AE%D9%85%DA%A9_%D8%A8%D8%A7%D8%B1%D9%88%D8%B1_%D8%AF%D8%B1_%D9%84%D8%A7%D9%86%D9%87_%DA%AF%D8%B2%DB%8C%D9%86%DB%8C\"><\/span><strong>\u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062a\u062e\u0645\u06a9 \u0628\u0627\u0631\u0648\u0631 \u062f\u0631 \u0644\u0627\u0646\u0647 \u06af\u0632\u06cc\u0646\u06cc <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u062a\u062e\u0645\u06a9 \u0628\u0627\u0631\u0648\u0631 \u0634\u062f\u0647 \u0646\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0631\u062d\u0645 \u0648 \u062f\u06cc\u0648\u0627\u0631\u0647\u200c\u0647\u0627\u06cc \u0622\u0646 \u0644\u0627\u0646\u0647 \u06af\u0632\u06cc\u0646\u06cc \u06a9\u0646\u062f\u060c \u062c\u0646\u06cc\u0646\u06cc \u0634\u06a9\u0644 \u0646\u062e\u0648\u0627\u0647\u062f \u06af\u0631\u0641\u062a.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9064 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0641\u0631\u0627\u06cc\u0646\u062f-\u0628\u0627\u0631\u0648\u0631\u06cc-\u062a\u062e\u0645\u06a9.webp\" alt=\"\u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0627\u0633\u067e\u0631\u0645 \u062f\u0631 \u0628\u0627\u0631\u0648\u0631 \u06a9\u0631\u062f\u0646 \u062a\u062e\u0645\u06a9\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0641\u0631\u0627\u06cc\u0646\u062f-\u0628\u0627\u0631\u0648\u0631\u06cc-\u062a\u062e\u0645\u06a9.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0641\u0631\u0627\u06cc\u0646\u062f-\u0628\u0627\u0631\u0648\u0631\u06cc-\u062a\u062e\u0645\u06a9-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0641\u0631\u0627\u06cc\u0646\u062f-\u0628\u0627\u0631\u0648\u0631\u06cc-\u062a\u062e\u0645\u06a9-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0641\u0631\u0627\u06cc\u0646\u062f-\u0628\u0627\u0631\u0648\u0631\u06cc-\u062a\u062e\u0645\u06a9-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D9%84%D8%A7%DB%8C%D9%84_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D9%85%D8%B1%D8%AF%D8%A7%D9%86_%D9%88_%D8%B2%D9%86%D8%A7%D9%86\"><\/span>\u062f\u0644\u0627\u06cc\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0630\u06a9\u0631 \u0634\u062f\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0646\u0627\u0628\u0627\u0631\u0648\u0631 \u0647\u0633\u062a\u0646\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u0639\u0644\u0627\u0626\u0645\u06cc \u0631\u0648\u0628\u0647\u200c\u0631\u0648 \u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0639\u0644\u0627\u0626\u0645 \u062f\u0631 \u0622\u0642\u0627\u06cc\u0627\u0646 \u0648 \u0628\u0627\u0646\u0648\u0627\u0646 \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a.<\/p>\n<ol>\n<li>\u0646\u0642\u0635 \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u062a\u0639\u062f\u0627\u062f \u06a9\u0627\u0641\u06cc \u0627\u0633\u067e\u0631\u0645<\/li>\n<li><a href=\"https:\/\/bizma.ir\/mag\/premature-ejaculation\/\" target=\"_blank\" rel=\"noopener\">\u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u0627\u0646\u0632\u0627\u0644<\/a><\/li>\n<li>\u0648\u062c\u0648\u062f \u0627\u0644\u062a\u0647\u0627\u0628 \u06cc\u0627 \u062f\u0631\u062f \u062f\u0631 \u0628\u06cc\u0636\u0647<\/li>\n<li>\u06a9\u0648\u0686\u06a9 \u0628\u0648\u062f\u0646 \u063a\u06cc\u0631 \u0646\u0631\u0645\u0627\u0644 \u0628\u06cc\u0636\u0647<\/li>\n<li>\u0648\u062c\u0648\u062f \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u0631\u0648\u0646\u062f \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc<\/li>\n<li>\u0642\u0627\u0639\u062f\u06af\u06cc\u200c\u0647\u0627\u06cc \u0646\u0627\u0645\u0646\u0638\u0645<\/li>\n<li>\u0633\u0631\u0637\u0627\u0646 \u062f\u0633\u062a\u06af\u0627\u0647 \u062a\u0648\u0644\u06cc\u062f \u0645\u062b\u0644\u06cc \u0632\u0646<\/li>\n<li>\u0646\u0627\u0647\u0646\u062c\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0631\u062d\u0645 \u0648 \u062f\u0647\u0627\u0646\u0647 \u0631\u062d\u0645<\/li>\n<li>\u0633\u0642\u0637 \u0645\u06a9\u0631\u0631<\/li>\n<li>\u0622\u0646\u062f\u0648\u0645\u062a\u0631\u06cc\u0648\u0632<\/li>\n<li>\u06cc\u0627\u0626\u0633\u06af\u06cc \u0632\u0648\u062f \u0647\u0646\u06af\u0627\u0645<\/li>\n<li>\u0628\u0627\u0644\u0627 \u0628\u0648\u062f\u0646 \u0633\u0637\u062d \u0647\u0648\u0631\u0645\u0648\u0646 \u067e\u0631\u0648\u0644\u0627\u06a9\u062a\u06cc\u0646<\/li>\n<li>\u0686\u0633\u0628\u0646\u062f\u06af\u06cc \u0644\u06af\u0646\u06cc<\/li>\n<li>\u0633\u0646\u062f\u0631\u0648\u0645 \u062a\u062e\u0645\u062f\u0627\u0646 \u067e\u0644\u06cc \u06a9\u06cc\u0633\u062a\u06cc\u06a9<\/li>\n<\/ol>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9063 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0648\u0627\u0645\u0644-\u062e\u0627\u0631\u062c\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc.webp\" alt=\"\u0639\u0648\u0627\u0645\u0644 \u062e\u0627\u0631\u062c\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0648\u0627\u0645\u0644-\u062e\u0627\u0631\u062c\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0648\u0627\u0645\u0644-\u062e\u0627\u0631\u062c\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0648\u0627\u0645\u0644-\u062e\u0627\u0631\u062c\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0648\u0627\u0645\u0644-\u062e\u0627\u0631\u062c\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%B9%D9%88%D8%A7%D9%85%D9%84_%D8%AE%D8%A7%D8%B1%D8%AC%DB%8C_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\"><\/span><strong>\u0639\u0648\u0627\u0645\u0644 \u062e\u0627\u0631\u062c\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0639\u0644\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0641\u0642\u0637 \u0628\u0647 \u0645\u0648\u0627\u0631\u062f \u0630\u06a9\u0631 \u0634\u062f\u0647 \u0645\u062d\u062f\u0648\u062f \u0646\u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0648\u0627\u062f \u0622\u0631\u0627\u06cc\u0634\u06cc \u0646\u0627\u0645\u0631\u063a\u0648\u0628\u060c \u0622\u0644\u0627\u06cc\u0646\u062f\u0647\u200c\u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0647\u0648\u0627\u06cc \u062a\u0646\u0641\u0633\u06cc\u060c \u0648\u062c\u0648\u062f \u0622\u0641\u062a \u06a9\u0634\u200c\u0647\u0627 \u0648 \u062d\u0634\u0631\u0647 \u06a9\u0634\u200c\u0647\u0627\u060c \u06a9\u0627\u0631 \u0628\u0627 \u06af\u0627\u0632\u0647\u0627\u06cc \u0628\u06cc\u0647\u0648\u0634\u06cc\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0645\u062b\u0644 \u062c\u06cc\u0648\u0647\u060c \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0633\u06cc\u062a\u0648\u062a\u0648\u06a9\u0633\u06cc\u06a9 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0645\u0648\u0627\u062c \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0627\u0632 \u062a\u0644\u0641\u0646 \u0647\u0645\u0631\u0627\u0647 \u06cc\u0627 \u062a\u0644\u0648\u06cc\u0632\u06cc\u0648\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f. \u062f\u0631 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0632\u0648\u062c\u06cc\u0646 \u0645\u0648\u062b\u0631 \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0632\u06cc\u0627\u062f \u0627\u0632 \u0645\u0627\u06cc\u06a9\u0631\u0648\u0641\u0631 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0634\u0647 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0648\u062f \u0632\u06cc\u0631\u0627 \u0627\u0645\u0648\u0627\u062c \u0645\u0627\u06cc\u06a9\u0631\u0648\u0648\u06cc\u0648 \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0631\u0627\u062f\u06cc\u06a9\u0627\u0644\u200c\u0647\u0627\u06cc \u0622\u0632\u0627\u062f \u0646\u0642\u0634 \u062f\u0627\u0631\u0646\u062f \u0648 \u0631\u0627\u0628\u0637\u0647 \u0645\u0633\u062a\u0642\u06cc\u0645\u06cc \u0628\u06cc\u0646 \u0631\u0627\u062f\u06cc\u06a9\u0627\u0644\u200c\u0647\u0627\u06cc \u0622\u0632\u0627\u062f \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u0645\u0648\u0627\u062c \u0627\u0644\u06a9\u062a\u0631\u0648\u0645\u063a\u0646\u0627\u0637\u06cc\u0633\u06cc \u062f\u0631 \u0633\u0644\u0648\u0644\u200c\u0647\u0627\u06cc \u0628\u062f\u0646 \u0645\u0648\u062b\u0631 \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0631 \u0631\u0648\u06cc \u062a\u06a9\u062b\u06cc\u0631 \u0633\u0644\u0648\u0644\u200c\u0647\u0627 \u062a\u0627\u062b\u06cc\u0631 \u06af\u0630\u0627\u0631\u0646\u062f. \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0631 \u06a9\u06cc\u0641\u06cc\u062a \u0627\u0633\u067e\u0631\u0645 \u0648 \u062a\u062e\u0645\u06a9 \u062a\u0623\u062b\u06cc\u0631 \u0628\u06af\u0630\u0627\u0631\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0633\u062a\u0631\u0633 \u062f\u0627\u0634\u062a\u0646 \u062f\u0631 \u0637\u0648\u0644\u0627\u0646\u06cc \u0645\u062f\u062a \u0628\u0627\u0639\u062b \u0627\u062e\u062a\u0644\u0627\u0644 \u062f\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u0645\u062d\u0631\u06a9 \u062a\u0648\u0644\u06cc\u062f \u0627\u0633\u067e\u0631\u0645 \u0648 \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u0641\u0634\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u06cc \u062f\u0631 \u062f\u0631\u0627\u0632\u0645\u062f\u062a \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0627 \u0639\u0648\u0627\u0631\u0636\u06cc \u0645\u062b\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\u060c \u0632\u0627\u06cc\u0645\u0627\u0646 \u0632\u0648\u062f\u0631\u0633 \u0648 \u0633\u0642\u0637 \u062c\u0646\u06cc\u0646 \u062f\u0631 \u0627\u0641\u0631\u0627\u062f \u062f\u06cc\u062f\u0647 \u0634\u0648\u062f.<\/p>\n<p>\u0645\u0637\u0627\u0644\u0639\u0647 \u0645\u0642\u0627\u0644\u0647 <a href=\"https:\/\/bizma.ir\/mag\/%d8%a7%d9%81%d8%b2%d8%a7%db%8c%d8%b4-%d9%85%db%8c%d9%84-%d8%ac%d9%86%d8%b3%db%8c\/\" target=\"_blank\" rel=\"noopener\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u0644 \u062c\u0646\u0633\u06cc<\/a><\/p>\n<p>\u0632\u0646\u062f\u06af\u06cc \u0645\u0627\u0634\u06cc\u0646\u06cc \u06a9\u0645 \u062a\u062d\u0631\u06a9 \u0648 \u0645\u062f\u0631\u0646\u06cc \u06a9\u0647 \u0632\u0646\u062f\u06af\u06cc \u0634\u0647\u0631\u06cc \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0631\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0648\u0646\u062f. \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u0627\u0636\u0627\u0641\u0647 \u0648\u0632\u0646 \u063a\u06cc\u0631 \u0637\u0628\u06cc\u0639\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0648\u0632\u0646 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0647 \u067e\u0632\u0634\u06a9 \u062e\u0648\u062f \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f. \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0628\u0627 \u0634\u0627\u062e\u0635 \u062a\u0648\u062f\u0647 \u0628\u062f\u0646\u06cc \u0628\u06cc\u0646 \u06f2\u06f5 \u062a\u0627 \u06f3\u06f0 \u0686\u06cc\u0632\u06cc \u062f\u0631 \u062d\u062f\u0648\u062f \u062f\u0648 \u0628\u0631\u0627\u0628\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0633\u0627\u06cc\u0631 \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0645\u0639\u0631\u0636 \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0647\u0633\u062a\u0646\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u06a9\u0627\u0647\u0634 \u0648\u0632\u0646 \u0628\u0627\u06cc\u062f \u0627\u0635\u0648\u0644\u06cc \u0648 \u0639\u0644\u0645\u06cc \u0628\u0627\u0634\u062f.<\/p>\n<p>\u062d\u0630\u0641 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0648\u0639\u062f\u0647\u200c\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc \u0648 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0631\u062f\u0646 \u0631\u0698\u06cc\u0645\u200c\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc \u0628\u0627 \u06a9\u0627\u0644\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646 \u0648 \u06af\u06cc\u0627\u0647\u062e\u0648\u0627\u0631\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0641\u0631\u062f \u0631\u0627 \u062f\u0631 \u0645\u0639\u0631\u0636 \u062e\u0637\u0631 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0642\u0631\u0627\u0631 \u062f\u0647\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u06cc\u200c\u0627\u0634\u062a\u0647\u0627\u06cc\u06cc \u0639\u0635\u0628\u06cc \u0648 \u0633\u0627\u06cc\u0631 \u062f\u0644\u0627\u06cc\u0644\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0631 \u0631\u0648\u06cc \u0645\u0642\u062f\u0627\u0631 \u063a\u0630\u0627\u06cc \u0645\u0635\u0631\u0641\u06cc \u0634\u0645\u0627 \u062a\u0627\u062b\u06cc\u0631 \u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u0646\u062f \u0631\u0627 \u062f\u0631\u0645\u0627\u0646 \u06a9\u0646\u06cc\u062f. \u0632\u06cc\u0631\u0627 \u06a9\u0645\u0628\u0648\u062f \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0645\u0647\u0645\u06cc \u0645\u062b\u0644 \u0627\u0633\u06cc\u062f \u0641\u0648\u0644\u06cc\u06a9\u060c \u0622\u0647\u0646 \u0648 \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 b\u06f1\u06f2 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0648\u062f. \u0645\u0635\u0631\u0641 \u062f\u062e\u0627\u0646\u06cc\u0627\u062a \u0646\u06cc\u0632 \u062f\u0631 \u062d\u0627\u0645\u0644\u06af\u06cc \u062a\u0627\u062b\u06cc\u0631 \u062f\u0627\u0631\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0628\u06cc\u0646 \u0645\u0635\u0631\u0641 \u0633\u06cc\u06af\u0627\u0631 \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0631\u0627\u0628\u0637\u0647 \u0645\u0633\u062a\u0642\u06cc\u0645\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0633\u0645\u0648\u0645 \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u062f\u062e\u0627\u0646\u06cc\u0627\u062a \u0642\u062f\u0631\u062a \u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0631\u062f \u0648 \u0632\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u063a\u0630\u0627\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u062f\u0627\u0631\u0627\u06cc \u0645\u0642\u0627\u062f\u06cc\u0631 \u0628\u0627\u0644\u0627\u06cc\u06cc \u0633\u0645 \u0647\u0633\u062a\u0646\u062f \u0646\u06cc\u0632 \u0628\u0627\u0639\u062b \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u0646\u06af\u0647\u062f\u0627\u0631\u0646\u062f\u0647\u200c\u0647\u0627 \u0648 \u0627\u0641\u0632\u0648\u062f\u0646\u06cc\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0637\u0628\u06cc\u0639\u06cc \u0648 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u06a9\u0647 \u0645\u0636\u0631 \u0647\u0633\u062a\u0646\u062f \u0646\u06cc\u0632 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u06a9\u0627\u0647\u0634 \u062a\u0648\u0627\u0646 \u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0648\u062b\u0631 \u0628\u0627\u0634\u0646\u062f. \u062a\u0645\u0631\u06cc\u0646\u0627\u062a \u0648\u0631\u0632\u0634\u06cc \u0633\u0646\u06af\u06cc\u0646 \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f \u062f\u0686\u0627\u0631 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0642\u0627\u0639\u062f\u06af\u06cc \u0648 \u0639\u062f\u0645 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062a\u0648\u0644\u06cc\u062f \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0634\u0648\u0646\u062f. \u0645\u0639\u0645\u0648\u0644\u0627 \u062f\u0648\u0646\u062f\u06af\u0627\u0646 \u0645\u0627\u0631\u0627\u062a\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u062a\u0645\u0631\u06cc\u0646\u0627\u062a \u0648\u0631\u0632\u0634\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0633\u0646\u06af\u06cc\u0646\u06cc \u062f\u0627\u0631\u0646\u062f \u062f\u0686\u0627\u0631 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%B3%D9%86_%D9%88_%D8%AE%D8%B7%D8%B1_%D8%A8%D8%B1%D9%88%D8%B2_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\"><\/span><strong>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0646 \u0648 \u062e\u0637\u0631 \u0628\u0631\u0648\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc <\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0646 \u0630\u062e\u0627\u06cc\u0631 \u062a\u062e\u0645\u062f\u0627\u0646 \u06a9\u0627\u0647\u0634 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u062a\u0639\u062f\u0627\u062f \u0627\u0633\u067e\u0631\u0645 \u00a0\u062a\u0648\u0644\u06cc\u062f \u0634\u062f\u0647 \u0646\u06cc\u0632 \u06a9\u0627\u0647\u0634 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u062d\u0642\u06cc\u0642\u062a \u06f3\u06f5 \u0633\u0627\u0644\u06af\u06cc \u0622\u063a\u0627\u0632 \u06a9\u0627\u0647\u0634 \u0630\u062e\u0627\u06cc\u0631 \u062a\u062e\u0645\u062f\u0627\u0646 \u0627\u0633\u062a. \u0647\u0631 \u0633\u0627\u0644\u06cc \u06a9\u0647 \u0627\u0632 \u0639\u0645\u0631 \u0632\u0648\u062c\u06cc\u0646 \u0645\u06cc\u200c\u06af\u0630\u0631\u062f \u0642\u062f\u0631\u062a \u0628\u0627\u0631\u0648\u0631\u06cc \u0622\u0646\u200c\u0647\u0627 \u0646\u06cc\u0632 \u06a9\u0645\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0646\u060c \u062a\u0648\u0627\u0646\u0627\u063a \u0628\u062f\u0646 \u0645\u0631\u062f \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627 \u0648 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062d\u0631\u06a9\u062a \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627 \u06a9\u0627\u0647\u0634 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0632\u0648\u062c\u06cc\u0646 \u062f\u0631 \u0633\u0646\u06cc\u0646 \u0628\u0627\u0644\u0627\u062a\u0631 \u0642\u0635\u062f \u0641\u0631\u0632\u0646\u062f \u0622\u0648\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f\u060c \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0647\u0631 \u0632\u0645\u0627\u0646\u06cc \u0627\u0645\u06a9\u0627\u0646 \u0628\u0631\u0648\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u0648 \u0646\u0627\u0647\u0646\u062c\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0698\u0646\u062a\u06cc\u06a9\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n<p>\u062e\u0627\u0646\u0645\u200c\u0647\u0627\u06cc \u0645\u062c\u0631\u062f\u06cc \u06a9\u0647 \u0642\u0635\u062f \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062a\u0639\u062f\u0627\u062f\u06cc \u0627\u0632 \u062a\u062e\u0645\u06a9\u200c\u0647\u0627\u06cc \u0633\u0627\u0644\u0645 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0645\u0631\u0627\u06a9\u0632 \u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u0641\u0631\u06cc\u0632 \u0634\u062f\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f \u062a\u0627 \u067e\u0633 \u0627\u0632 \u0627\u0632\u062f\u0648\u0627\u062c \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u0633\u0646\u06cc\u0646 \u0628\u0627\u0644\u0627\u062a\u0631 \u0646\u06cc\u0632 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0627\u0633\u062a\u0631\u0633 \u062f\u0631 \u0628\u0627\u0646\u0648\u0627\u0646 \u0645\u062c\u0631\u062f \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0641\u0631\u0632\u0646\u062f \u0622\u0648\u0631\u06cc \u06a9\u0645 \u0634\u0648\u062f. \u0627\u0644\u0628\u062a\u0647 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0633\u0646\u06cc\u0646 \u067e\u0627\u06cc\u06cc\u0646\u200c\u062a\u0631 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0627\u0632\u062f\u0648\u0627\u062c \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0637\u0644\u0627\u06cc\u06cc \u062a\u0648\u0644\u062f \u0641\u0631\u0632\u0646\u062f\u060c \u0635\u0627\u062d\u0628 \u0641\u0631\u0632\u0646\u062f \u0634\u0648\u06cc\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9062 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0644\u0644-\u0627\u0635\u0644\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0648-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0686\u06cc\u0633\u062a.webp\" alt=\"\u062a\u0633\u062a \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u0632\u0646\u0627\u0646\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0644\u0644-\u0627\u0635\u0644\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0648-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0686\u06cc\u0633\u062a.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0644\u0644-\u0627\u0635\u0644\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0648-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0686\u06cc\u0633\u062a-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0644\u0644-\u0627\u0635\u0644\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0648-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0686\u06cc\u0633\u062a-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0639\u0644\u0644-\u0627\u0635\u0644\u06cc-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u0648-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0686\u06cc\u0633\u062a-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A2%D8%B2%D9%85%D8%A7%DB%8C%D8%B4%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%AF%D8%B1_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\"><\/span><strong>\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u067e\u0632\u0634\u06a9 \u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u062f\u0631 \u062c\u0631\u06cc\u0627\u0646 \u062a\u0645\u0627\u0645\u06cc \u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u0634\u0645\u0627 \u0627\u0632 \u062c\u0645\u0644\u0647 \u0639\u0627\u062f\u0627\u062a \u062c\u0646\u0633\u06cc \u0628\u0627\u0634\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u062a\u063a\u06cc\u06cc\u0631 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u062a\u0627 \u062d\u062f\u0648\u062f\u06cc \u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u0647 \u0648\u062c\u0648\u062f \u0622\u0645\u062f\u0647 \u0631\u0627 \u062d\u0644 \u06a9\u0646\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062a\u0633\u062a\u200c\u0647\u0627 \u0648 \u0622\u0632\u0645\u0648\u0646 \u0648 \u062e\u0637\u0627\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0686\u0646\u062f\u06cc\u0646 \u0645\u0627\u0647 \u0637\u0648\u0644 \u0628\u06a9\u0634\u0646\u062f. \u0627\u06cc\u0646 \u0646\u06a9\u062a\u0647 \u0631\u0627 \u0647\u0645 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u06cc\u06a9 \u0633\u0648\u0645 \u0627\u0632 \u0632\u0648\u062c\u200c\u0647\u0627\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u060c \u0639\u0644\u062a \u0645\u0634\u062e\u0635\u06cc \u0628\u0631\u0627\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p>\u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0627\u06cc\u0646 \u06a9\u0647 \u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc \u062a\u0634\u062e\u06cc\u0635\u06cc \u0648 \u067e\u0631\u0648\u0633\u0647 \u0637\u0648\u0644\u0627\u0646\u06cc \u0648 <strong>\u0647\u0632\u06cc\u0646\u0647<\/strong> \u0628\u0631\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0633\u0646\u062c\u0634 \u0648 \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u06a9\u0634\u0648\u0631 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u06cc\u0646 \u0645\u0631\u062d\u0644\u0647 \u062c\u0632\u0648 \u0645\u0631\u0627\u062d\u0644 \u062f\u0634\u0648\u0627\u0631 \u0648 \u0633\u062e\u062a \u0627\u0633\u062a \u0648 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0647\u0632\u06cc\u0646\u0647 \u062a\u0648\u0633\u0637 <strong>\u0628\u06cc\u0645\u0647<\/strong> \u067e\u0631\u062f\u0627\u062e\u062a \u0646\u0645\u06cc\u200c\u0634\u0648\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0647\u06cc\u0686 \u0636\u0645\u0627\u0646\u062a\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f \u06a9\u0647 \u0628\u0639\u062f \u0627\u0632 \u0627\u0646\u062c\u0627\u0645 \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0645\u0631\u0627\u062d\u0644\u060c \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0635\u0648\u0631\u062a \u06af\u06cc\u0631\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u062a\u0627 \u062a\u0645\u0627\u0645\u06cc \u0634\u0631\u0627\u06cc\u0637 \u0631\u0627 \u0628\u0633\u0646\u062c\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B3%D8%AA_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B2%D9%86%D8%A7%D9%86\"><\/span><strong>\u062a\u0633\u062a \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0631\u0627\u06cc \u0632\u0646\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u0647 \u062a\u062e\u0645\u06a9 \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0631\u0648\u0631 \u0634\u0648\u062f\u060c \u062a\u062e\u0645\u062f\u0627\u0646\u200c\u0647\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0637\u0648\u0631 \u0645\u0646\u0638\u0645 \u062a\u062e\u0645\u06a9 \u0622\u0632\u0627\u062f \u06a9\u0646\u0646\u062f \u0648 \u0633\u0627\u06cc\u0631 \u0627\u062c\u0632\u0627\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u0646\u06cc\u0632 \u0628\u0647 \u062f\u0631\u0633\u062a\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u0648\u062f \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u0646\u062f. \u0627\u0628\u062a\u062f\u0627 \u067e\u0632\u0634\u06a9 \u0627\u0632 \u0634\u0645\u0627 \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u062a\u0627\u0631\u06cc\u062e\u0686\u0647 \u067e\u0632\u0634\u06a9\u06cc\u060c \u0639\u0627\u062f\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0627\u0628\u0637 \u062c\u0646\u0633\u06cc \u0648 \u0633\u06cc\u06a9\u0644\u200c\u0647\u0627\u06cc \u0642\u0627\u0639\u062f\u06af\u06cc \u0633\u0648\u0627\u0644\u0627\u062a\u06cc \u062e\u0648\u0627\u0647\u062f \u067e\u0631\u0633\u06cc\u062f\u200c \u0633\u067e\u0633 \u0628\u0647 \u062a\u0631\u062a\u06cc\u0628 \u062a\u0633\u062a \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc\u060c \u0631\u0627\u062f\u06cc\u0648\u06af\u0631\u0627\u0641\u06cc \u0627\u0632 \u0631\u062d\u0645 \u0648 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0631\u062d\u0645\u06cc\u060c \u0644\u0627\u067e\u0627\u0631\u0648\u0633\u06a9\u0648\u067e\u06cc\u060c \u0622\u0632\u0645\u0627\u06cc\u0634 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc\u060c \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u062a\u062e\u0645\u062f\u0627\u0646\u060c \u062a\u0633\u062a\u200c\u0647\u0627\u06cc \u0698\u0646\u062a\u06cc\u06a9\u06cc \u0648 \u062a\u0633\u062a \u0641\u0631\u0627\u0635\u0648\u062a \u0644\u06af\u0646 \u0627\u0646\u062c\u0627\u0645 \u062e\u0648\u0627\u0647\u062f \u0634\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0627\u0646\u062c\u0627\u0645 \u062a\u0645\u0627\u0645\u06cc \u062a\u0633\u062a\u200c\u0647\u0627 \u0646\u06cc\u0633\u062a \u0648 \u062a\u0631\u062a\u06cc\u0628 \u0622\u0646\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062a\u0648\u0627\u0641\u0642 \u0628\u06cc\u0645\u0627\u0631 \u0648 \u067e\u0632\u0634\u06a9 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u062a\u0641\u0627\u0648\u062a \u0628\u0627\u0634\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%B4%D8%AE%DB%8C%D8%B5_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%AF%D8%B1_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\"><\/span><strong>\u062a\u0634\u062e\u06cc\u0635 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0645\u0639\u0627\u06cc\u0646\u0647 \u062f\u0642\u06cc\u0642 \u067e\u0633 \u0627\u0632 \u062f\u0631\u06cc\u0627\u0641\u062a \u0634\u0631\u062d \u062d\u0627\u0644 \u0628\u06cc\u0645\u0627\u0631 \u062a\u0648\u0633\u0637 \u0627\u0648\u0631\u0648\u0644\u0648\u0698\u06cc\u0633\u062a \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0633\u067e\u0633 \u0628\u0627 \u0622\u0632\u0645\u0627\u06cc\u0634 \u0627\u0633\u067e\u0631\u0645\u060c \u062a\u0639\u062f\u0627\u062f \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0646\u0645\u0648\u0646\u0647\u060c \u062d\u062c\u0645 \u0645\u0627\u06cc\u0639 \u0645\u0646\u06cc\u060c \u0645\u06cc\u0632\u0627\u0646 \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627\u06cc \u0645\u062a\u062d\u0631\u06a9 \u0648 \u0645\u06cc\u0632\u0627\u0646 \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0634\u06a9\u0644 \u0637\u0628\u06cc\u0639\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0622\u0632\u0645\u0627\u06cc\u0634\u0627\u062a\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0639\u0641\u0648\u0646\u062a \u0631\u0627 \u0646\u06cc\u0632 \u0646\u0634\u0627\u0646 \u062f\u0647\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0686\u0646\u062f \u0628\u0627\u0631 \u062f\u0631 \u0645\u0627\u0647 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0646\u0645\u0648\u0646\u0647 \u06af\u06cc\u0631\u06cc \u0628\u0627\u0634\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646 \u0646\u0638\u0631 \u0642\u0637\u0639\u06cc \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0645\u06cc\u0632\u0627\u0646 \u0633\u0644\u0627\u0645\u062a \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627 \u0627\u0631\u0627\u0626\u0647 \u062f\u0627\u062f. \u0633\u067e\u0633 \u0628\u0627 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0633\u0637\u062d \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627 \u0645\u06cc\u0632\u0627\u0646 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0647\u0648\u0631\u0645\u0648\u0646\u06cc \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u06cc\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0622\u0632\u0645\u0627\u06cc\u0634\u0627\u062a \u067e\u06cc\u0634\u0631\u0641\u062a\u0647\u200c\u062a\u0631\u06cc \u0645\u062b\u0644 \u0631\u0646\u06af \u0622\u0645\u06cc\u0632\u06cc \u0627\u0633\u067e\u0631\u0645 \u0648 \u0628\u0631\u0631\u0633\u06cc \u0622\u0646\u062a\u06cc\u200c\u0628\u0627\u062f\u06cc\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0631\u0645 \u0646\u06cc\u0627\u0632 \u0628\u0627\u0634\u062f\u060c \u067e\u0632\u0634\u06a9 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u06cc\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0627\u0631\u0648\u0644\u0648\u0698\u06cc \u0627\u0631\u062c\u0627\u0639 \u062e\u0648\u0627\u0647\u062f \u062f\u0627\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0639\u0644\u062a \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0647\u0646\u0648\u0632 \u0647\u0645 \u0646\u0627\u0645\u0634\u062e\u0635 \u0628\u0627\u0634\u062f\u060c \u0628\u0627 \u0627\u0646\u062c\u0627\u0645 \u0622\u0632\u0645\u0627\u06cc\u0634\u0627\u062a \u0698\u0646\u062a\u06cc\u06a9\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0644\u062d\u0627\u0638 \u06a9\u0631\u0648\u0645\u0648\u0632\u0648\u0645\u06cc \u0633\u0627\u06cc\u0631 \u0641\u0627\u06a9\u062a\u0648\u0631\u0647\u0627 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0631\u062f.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%DA%86%D9%87_%D8%B2%D9%85%D8%A7%D9%86%DB%8C_%D8%A8%D8%A7%DB%8C%D8%AF_%D8%A8%D9%87_%D9%BE%D8%B2%D8%B4%DA%A9_%D9%85%D8%B1%D8%A7%D8%AC%D8%B9%D9%87_%DA%A9%D8%B1%D8%AF%D8%9F\"><\/span><strong>\u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0631\u062f\u061f<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u0627\u06cc\u0646\u06a9\u0647 \u0634\u0645\u0627 \u0648 \u0647\u0645\u0633\u0631\u062a\u0627\u0646 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0631\u062a\u0628 \u06cc\u06a9 \u0633\u0627\u0644 \u0628\u062f\u0648\u0646 \u0647\u06cc\u0686 \u06a9\u062f\u0627\u0645\u06cc\u06a9 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc\u060c \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0628\u0631\u0642\u0631\u0627\u0631 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0635\u0648\u0631\u062a \u0646\u06af\u0631\u0641\u062a\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0627 \u067e\u0632\u0634\u06a9 \u0645\u0634\u0648\u0631\u062a \u06a9\u0646\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06af\u0631 \u0622\u0642\u0627\u06cc\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0633\u0627\u0628\u0642\u0647 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u0646\u0633\u06cc \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u067e\u0631\u0648\u0633\u062a\u0627\u062a \u0628\u06cc\u0636\u0647 \u0648 \u06cc\u0627 \u062a\u0639\u062f\u0627\u062f \u0627\u0633\u067e\u0631\u0645 \u06a9\u0645 \u062f\u0627\u0631\u06cc\u062f \u06cc\u0627 \u0627\u06af\u0631 \u062e\u0627\u0646\u0645\u06cc \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0633\u06cc\u06a9\u0644\u200c\u0647\u0627\u06cc \u0646\u0627\u0645\u0646\u0638\u0645\u06cc \u062f\u0627\u0631\u06cc\u062f \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0627\u0644\u062a\u0647\u0627\u0628 \u0644\u06af\u0646 \u0648 \u06cc\u0627 \u062f\u0631\u062f \u0644\u06af\u0646\u06cc \u062f\u0627\u0631\u06cc\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u067e\u0633 \u0627\u0632 \u06af\u0630\u0634\u062a \u06f6 \u0645\u0627\u0647 \u06cc\u0627 \u0632\u0648\u062f\u062a\u0631 \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9059 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0645\u0631\u062f\u0627\u0646.webp\" alt=\"\u062a\u0634\u062e\u06cc\u0635 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0645\u0631\u062f\u0627\u0646.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0645\u0631\u062f\u0627\u0646-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0645\u0631\u062f\u0627\u0646-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0645\u0631\u062f\u0627\u0646-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%85%D9%87%D9%85%E2%80%8C%D8%AA%D8%B1%DB%8C%D9%86_%D8%B1%D9%88%D8%B4_%D8%AF%D8%B1_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\"><\/span><strong>\u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0639\u0645\u0648\u0644\u0627\u064b \u0633\u0627\u0628\u0642\u0647 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u0631\u0627 \u0686\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u062f\u0627\u0634\u062a\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc\u06cc \u062e\u0627\u0635 \u0645\u062b\u0644 \u0646\u0627\u0631\u0633\u0627\u06cc\u06cc \u06a9\u0644\u06cc\u0647\u060c \u062f\u06cc\u0627\u0628\u062a\u060c \u06a9\u0645 \u06a9\u0627\u0631\u06cc \u0648 \u067e\u0631\u06a9\u0627\u0631\u06cc \u062a\u06cc\u0631\u0648\u0626\u06cc\u062f \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0642\u0644\u0628\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631 \u0631\u0648\u06cc \u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u062f\u0646 \u0648 \u0646\u0634\u062f\u0646 \u062a\u0627\u062b\u06cc\u0631 \u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0636\u062f \u0627\u0641\u0633\u0631\u062f\u06af\u06cc\u060c \u0622\u0631\u0627\u0645\u0628\u062e\u0634 \u0648 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u200c\u06af\u0631\u062f\u0627\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0633\u0637\u062d \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0628\u062f\u0646 \u0627\u0641\u0631\u0627\u062f \u0627\u0632 \u062d\u0627\u0644\u062a \u062a\u0639\u0627\u062f\u0644 \u062e\u0627\u0631\u062c \u0634\u0648\u062f \u0648 \u0628\u0627\u0631\u0648\u0631\u06cc \u062a\u062d\u062a \u062a\u0627\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u0628\u06af\u06cc\u0631\u062f.<\/p>\n<ul>\n<li>\u062f\u0627\u0631\u0648 \u062f\u0631\u0645\u0627\u0646\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631<\/li>\n<li>\u0627\u0646\u062c\u0627\u0645 \u062c\u0631\u0627\u062d\u06cc \u0628\u0631\u0627\u06cc \u062d\u0644 \u06a9\u0631\u062f\u0646 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u0622\u0646\u0627\u062a\u0648\u0645\u06cc\u06a9 \u062f\u0631 \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/li>\n<li>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u06cc\u06a9\u0631\u0648 \u0627\u06cc\u0646\u062c\u06a9\u0634\u0646 \u0648 \u0633\u0627\u06cc\u0631 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u06a9\u0645\u06a9 \u0628\u0627\u0631\u0648\u0631\u06cc<\/li>\n<li>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u0633\u067e\u0631\u0645 \u0627\u0647\u062f\u0627\u06cc\u06cc\u060c \u0631\u062d\u0645 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646\u060c \u062c\u0646\u06cc\u0646 \u0627\u0647\u062f\u0627\u06cc\u06cc \u06cc\u0627 \u062a\u062e\u0645\u06a9 \u0627\u0647\u062f\u0627\u06cc\u06cc<\/li>\n<\/ul>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9060 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc-\u062a\u0634\u062e\u06cc\u0635-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646.webp\" alt=\"\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc-\u062a\u0634\u062e\u06cc\u0635-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc-\u062a\u0634\u062e\u06cc\u0635-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc-\u062a\u0634\u062e\u06cc\u0635-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0622\u0632\u0645\u0627\u06cc\u0634\u200c\u0647\u0627\u06cc-\u062a\u0634\u062e\u06cc\u0635-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-\u062f\u0631-\u0632\u0646\u0627\u0646-\u0648-\u0645\u0631\u062f\u0627\u0646-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C_%D8%B2%D9%86%D8%A7%D9%86_%D9%88_%D9%85%D8%B1%D8%AF%D8%A7%D9%86\"><\/span><strong>\u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0632\u0646\u0627\u0646 \u0648 \u0645\u0631\u062f\u0627\u0646<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0631 \u06af\u0630\u0634\u062a\u0647\u200c\u0627\u06cc \u0646\u0647 \u0686\u0646\u062f\u0627\u0646 \u062f\u0648\u0631\u060c \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u06a9\u0627\u0631\u06cc \u0646\u0634\u062f\u0646\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u062f \u0648\u0644\u06cc \u0627\u0645\u0631\u0648\u0632\u0647 \u0628\u0627 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0627\u0645\u06cc\u062f \u0628\u062e\u0634\u060c \u0686\u06cc\u0632\u06cc \u062f\u0631 \u062d\u062f\u0648\u062f \u06f8\u06f5 \u062f\u0631\u0635\u062f \u0627\u0632 \u0632\u0648\u062c\u200c\u0647\u0627\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631 \u067e\u0633 \u0627\u0632 \u06af\u0630\u0631\u0627\u0646\u062f\u0646 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u060c \u0635\u0627\u062d\u0628 \u0641\u0631\u0632\u0646\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0645\u0648\u062b\u0631 \u0648 \u0627\u06cc\u0645\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u063a\u0644\u0628\u0647 \u0628\u0631 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p>\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0642\u0635\u062f \u062f\u0627\u0631\u06cc\u0645 \u062a\u0627 \u0634\u0645\u0627 \u0631\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627 \u0627\u06cc\u0646 \u0631\u0648\u0634 \u0622\u0634\u0646\u0627 \u06a9\u0646\u06cc\u0645 \u0648\u0644\u06cc \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645 \u062f\u0631 \u0645\u0648\u0627\u062c\u0647\u0647 \u0628\u0627 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0632\u0646 \u0648 \u0645\u0631\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u0622\u06af\u0627\u0647\u06cc \u0648 \u0645\u0637\u0627\u0644\u0639\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u0648 \u0645\u0631\u0627\u062c\u0639\u0647 \u0628\u0647 \u0645\u062a\u062e\u0635\u0635\u06cc\u0646 \u0648 \u0645\u0634\u0627\u0648\u0631\u06cc\u0646 \u0645\u0631\u0628\u0648\u0637\u0647 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0647 \u062c\u0627\u06cc \u062f\u0631\u06af\u06cc\u0631 \u0634\u062f\u0646 \u0628\u0627 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0645\u0646\u0641\u06cc \u0648 \u0641\u0631\u0627\u0631 \u0627\u0632 \u0645\u0633\u0626\u0644\u0647 \u067e\u06cc\u0634 \u0622\u0645\u062f\u0647 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062f\u0631\u0645\u0627\u0646 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p>\u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0631\u0627\u0647 \u062d\u0644 \u067e\u06cc\u0634\u0646\u0647\u0627\u062f\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0633\u06cc\u0627\u0631 \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0646\u0628\u0627\u0634\u062f. \u062f\u0631 \u0645\u0648\u0627\u0631\u062f\u06cc \u0632\u0648\u062c\u06cc\u0646 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0639\u062f\u0645 \u0622\u0634\u0646\u0627\u06cc\u06cc \u0628\u0627 \u0627\u0635\u0648\u0644 \u0631\u0627\u0628\u0637\u0647 \u0635\u062d\u06cc\u062d \u062c\u0646\u0633\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0631\u062f\u0627\u0631 \u0634\u062f\u0646 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0641\u0631\u0632\u0646\u062f\u0622\u0648\u0631\u06cc \u0646\u062f\u0627\u0631\u0646\u062f. \u062f\u0631 \u062d\u0642\u06cc\u0642\u062a \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0628\u0633\u06cc\u0627\u0631\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u0627\u0646\u062c\u0627\u0645 \u0622\u0646\u200c\u0647\u0627 \u0634\u0627\u0646\u0633 \u0641\u0631\u0632\u0646\u062f \u0622\u0648\u0631\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p><strong>\u0646\u06a9\u062a\u0647:<\/strong> \u062d\u062f\u0627\u0642\u0644 \u0628\u0627\u06cc\u062f \u06cc\u06a9 \u0633\u0627\u0644 \u0628\u0647 \u0637\u0648\u0631 \u0645\u062f\u0627\u0648\u0645 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0645\u0646\u0638\u0645 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648 \u0627\u0632 \u0647\u06cc\u0686 \u06cc\u06a9 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u06cc\u06a9 \u0633\u0627\u0644 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u06af\u0632\u0627\u0631\u0634 \u0646\u0634\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u0634\u06a9\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u06a9 \u06a9\u0631\u062f. \u0627\u0644\u0628\u062a\u0647 \u062c\u0627\u06cc \u0646\u06af\u0631\u0627\u0646\u06cc \u0646\u06cc\u0633\u062a \u0632\u06cc\u0631\u0627 \u0637\u0628\u0642 \u0622\u0645\u0627\u0631 \u0633\u0627\u0632\u0645\u0627\u0646 \u062c\u0647\u0627\u0646\u06cc \u0628\u0647\u062f\u0627\u0634\u062a \u0627\u0639\u0644\u0627\u0645 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0686\u06cc\u0632\u06cc \u062f\u0631 \u062d\u062f\u0648\u062f \u06f1\u06f5 \u062f\u0631\u0635\u062f \u06a9\u0644 \u0632\u0648\u062c\u06cc\u0646\u060c \u0646\u0627\u0628\u0627\u0631\u0648\u0631 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p>\u0639\u0644\u062a \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0645\u0631\u062f\u060c \u0632\u0646 \u0648 \u06cc\u0627 \u0647\u0631 \u062f\u0648 \u0637\u0631\u0641 \u0628\u0627\u0634\u062f. \u062f\u0631 \u062d\u0627\u0644\u062a \u0639\u0645\u0648\u0645\u06cc \u06f4\u06f5 \u062f\u0631\u0635\u062f \u0627\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\u200c\u0647\u0627 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0632\u0646\u0627\u0646\u060c \u06f4\u06f0 \u062f\u0631\u0635\u062f \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0645\u0631\u062f\u0627\u0646 \u0648 \u06f1\u06f5 \u062f\u0631\u0635\u062f \u0646\u06cc\u0632 \u0639\u0644\u062a\u06cc \u0646\u0627\u0634\u0646\u0627\u062e\u062a\u0647 \u062f\u0627\u0631\u0646\u062f.<\/p>\n<p>\u0628\u0627 \u0645\u0631\u0627\u062c\u0639\u0647 \u0628\u0647 \u0645\u0631\u0627\u06a9\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0639\u062a\u0628\u0631 \u067e\u0633 \u0641\u0631\u0627\u06af\u06cc\u0631\u06cc \u0627\u0635\u0648\u0644 \u0635\u062d\u06cc\u062d \u0627\u0646\u062c\u0627\u0645 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u06a9\u0647 \u0628\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0628\u06cc\u0646\u062c\u0627\u0645\u062f\u060c \u0628\u0627\u06cc\u062f \u0645\u062f\u062a \u0632\u0645\u0627\u0646 \u0645\u0639\u06cc\u0646\u06cc \u0637\u0628\u0642 \u0627\u0635\u0648\u0644 \u0622\u0645\u0648\u0632\u0634 \u062f\u0627\u062f\u0647 \u0634\u062f\u0647 \u0632\u0648\u062c\u06cc\u0646 \u0631\u0627\u0628\u0637\u0647 \u062c\u0646\u0633\u06cc \u0628\u0631\u0642\u0631\u0627\u0631 \u06a9\u0646\u0646\u062f \u062a\u0627 \u0639\u0644\u062a \u062f\u0642\u06cc\u0642 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0646\u0627\u062e\u062a\u0647 \u0634\u0648\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646 \u0647\u0631 \u0686\u0647 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0645\u0634\u06a9\u0644 \u0631\u0627 \u0628\u0631\u0637\u0631\u0641 \u0648 \u0632\u0648\u062c \u0631\u0627 \u0628\u0647 \u0647\u062f\u0641 \u0634\u06cc\u0631\u06cc\u0646 \u062e\u0648\u062f \u06cc\u0639\u0646\u06cc \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0648 \u062f\u0631 \u0622\u063a\u0648\u0634 \u06af\u0631\u0641\u062a\u0646 \u06a9\u0648\u062f\u06a9\u0634\u0627\u0646 \u0631\u0633\u0627\u0646\u062f.<\/p>\n<p>\u0642\u0628\u0644 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632 \u0628\u0627\u06cc\u062f \u0628\u06af\u0648\u06cc\u0645 \u06a9\u0647 \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0628\u0647\u062a\u0631 \u0627\u0632 \u062f\u0631\u0645\u0627\u0646 \u0627\u0633\u062a. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u0633\u0646 \u0637\u0644\u0627\u06cc\u06cc \u062a\u0648\u0644\u062f \u0648 \u0641\u0631\u0632\u0646\u062f \u0622\u0648\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062f\u0631 \u0633\u0646\u06cc\u0646 \u0628\u0627\u0644\u0627\u062a\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0646\u0628\u0627\u0634\u06cc\u062f. \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062a\u0639\u062f\u0627\u062f \u0622\u0645\u06cc\u0632\u0634\u200c\u0647\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 \u0646\u0634\u062f\u0647 \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u062f \u0632\u06cc\u0631\u0627 \u062a\u062e\u0645\u06a9 \u062a\u0646\u0647\u0627 \u06f2\u06f4 \u0633\u0627\u0639\u062a \u067e\u0633 \u0627\u0632 \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0642\u0627\u0628\u0644\u06cc\u062a \u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0627\u0631\u062f.<\/p>\n<p>\u067e\u0632\u0634\u06a9 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u0634\u06a9\u0644\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0622\u0632\u0645\u0627\u06cc\u0634\u0627\u062a \u062a\u0634\u062e\u06cc\u0635\u06cc \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u060c \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u0631\u0627\u06cc \u0632\u0646\u0627\u0646 \u062a\u062c\u0648\u06cc\u0632 \u06a9\u0646\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0627\u0631\u0648\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0639\u0648\u0627\u0631\u0636 \u062c\u062f\u06cc \u0645\u062b\u0644 \u0686\u0646\u062f\u0642\u0644\u0648\u0632\u0627\u06cc\u06cc\u060c \u062c\u0631\u0627\u062d\u06cc \u0628\u0627 \u062f\u0631\u062f\u0647\u0627\u06cc \u0634\u062f\u06cc\u062f\u060c \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062e\u0627\u0631\u062c \u0627\u0632 \u0631\u062d\u0645 \u0648 \u0648\u0632\u0646 \u06a9\u0645 \u0646\u0648\u0632\u0627\u062f \u0647\u0646\u06af\u0627\u0645 \u062a\u0648\u0644\u062f \u0631\u0627 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062e\u0627\u0637\u0631 \u0639\u0644\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u0628\u0627\u0634\u062f. \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0634\u0648\u0646\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0634\u06a9\u0644 \u0628\u0631\u06af\u0634\u062a \u0627\u0646\u0632\u0627\u0644 \u0628\u0627\u0634\u062f \u06cc\u0627 \u0645\u06cc\u0632\u0627\u0646 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u062c\u0646\u0633\u06cc \u062a\u0631\u0634\u062d \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u063a\u062f\u0647 \u0647\u06cc\u067e\u0648\u0641\u06cc\u0632 \u067e\u0627\u06cc\u06cc\u0646\u200c\u062a\u0631 \u0627\u0632 \u0633\u0637\u062d \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0628\u0627\u0634\u0646\u062f. \u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u060c \u062a\u0648\u0644\u06cc\u062f \u0627\u0633\u067e\u0631\u0645 \u062f\u0686\u0627\u0631 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a\u06cc \u062e\u0648\u0627\u0647\u062f \u0634\u062f.<\/p>\n<p>\u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u062f\u06cc\u06af\u0631\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u0633\u067e\u0631\u0645 \u0645\u06cc\u0632\u0627\u0646 \u06a9\u0631\u0648\u0645\u0648\u0632\u0648\u0645 \u0644\u0627\u0632\u0645 \u0631\u0627 \u0628\u0647 \u062a\u062e\u0645\u06a9 \u0627\u0646\u062a\u0642\u0627\u0644 \u0646\u062f\u0647\u062f. \u062c\u0647\u0634\u200c\u0647\u0627\u06cc \u06a9\u0631\u0648\u0645\u0648\u0632\u0648\u0645\u06cc \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0635\u0644\u06cc\u200c\u062a\u0631\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0647\u0633\u062a\u0646\u062f \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u062e\u0627\u0637\u0631 \u0645\u0635\u0631\u0641 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0633\u0631\u0637\u0627\u0646\u060c \u0641\u0634\u0627\u0631 \u062e\u0648\u0646 \u0648 \u0647\u0645\u06cc\u0646\u200c\u0637\u0648\u0631 \u0636\u062f \u0627\u0641\u0633\u0631\u062f\u06af\u06cc \u0628\u0627\u0634\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0631\u0645\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0628\u0647 \u06a9\u0627\u0631 \u06af\u0631\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0628\u0627\u0632 \u06a9\u0631\u062f\u0646 \u0627\u0646\u0633\u062f\u0627\u062f \u0645\u062c\u0627\u0631\u06cc \u0627\u0633\u067e\u0631\u0645 \u0627\u0633\u062a. \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u067e\u06cc\u0634 \u0627\u0632 \u0627\u06cc\u0646 \u0648\u0627\u0632\u06a9\u062a\u0648\u0645\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0647 \u0628\u0627\u0634\u0646\u062f \u06cc\u0627 \u0628\u0631 \u0627\u062b\u0631 \u0636\u0631\u0628\u0647\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0634\u062f\u06cc\u062f\u060c \u0642\u0633\u0645\u062a\u06cc \u0627\u0632 \u0645\u062c\u0627\u0631\u06cc \u0627\u0633\u067e\u0631\u0645 \u0622\u0646\u200c\u0647\u0627 \u0628\u0633\u062a\u0647 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0647\u0646\u06af\u0627\u0645 \u0627\u0646\u0632\u0627\u0644 \u0627\u0633\u067e\u0631\u0645 \u06a9\u0627\u0641\u06cc \u0631\u0627 \u0627\u0632 \u0628\u062f\u0646 \u062e\u0627\u0631\u062c \u06a9\u0646\u0646\u062f\u200c. \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0622\u0642\u0627\u06cc\u0627\u0646 \u0627\u0632 \u06a9\u0634\u06cc\u062f\u0646 \u0633\u06cc\u06af\u0627\u0631\u060c \u0645\u0635\u0631\u0641 \u0645\u0648\u0627\u062f \u0645\u062e\u062f\u0631 \u0648 \u0627\u0644\u06a9\u0644 \u0648 \u0627\u0646\u062c\u0627\u0645 \u0648\u0631\u0632\u0634\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u062a\u0647\u0627\u062c\u0645\u06cc \u062e\u0648\u062f \u062f\u0627\u0631\u06cc \u06a9\u0646\u0646\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9058 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0627\u0631\u0686-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0648-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc.webp\" alt=\"\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0627\u0631\u0686-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0648-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0627\u0631\u0686-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0648-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0627\u0631\u0686-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0648-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0642\u0627\u0631\u0686-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0648-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D9%82%D8%A7%D8%B1%DA%86_%DA%AF%D8%A7%D9%86%D9%88%D8%AF%D8%B1%D9%85%D8%A7_%D9%88_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\"><\/span><strong>\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0644\u0627\u06cc\u0644\u06cc \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0648\u0646\u062f \u0627\u063a\u0644\u0628 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0627\u0634\u06a9\u0627\u0644\u0627\u062a\u06cc \u062f\u0631 \u062a\u0639\u062f\u0627\u062f \u0648 \u0634\u06a9\u0644 \u0627\u0633\u067e\u0631\u0645 \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u067e\u0627\u06cc\u06cc\u0646 \u0628\u0648\u062f\u0646 \u0634\u0627\u0646\u0633 \u0644\u0642\u0627\u062d \u0627\u0633\u067e\u0631\u0645 \u0628\u0627 \u062a\u062e\u0645\u06a9 \u0627\u0633\u062a. \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0627 \u062a\u0646\u0638\u06cc\u0645 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627 \u0648 \u0645\u062a\u0639\u0627\u062f\u0644 \u06a9\u0631\u062f\u0646 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u0628\u062f\u0646 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0639\u0644\u0644 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0627\u0632 \u0628\u06cc\u0646 \u0628\u0631\u0648\u0646\u062f \u0648 \u0641\u0631\u062f \u067e\u0633 \u0627\u0632 \u0686\u0646\u062f \u062a\u0644\u0627\u0634 \u0645\u062c\u062f\u062f \u0645\u0648\u0641\u0642 \u0628\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0634\u0648\u062f. \u0627\u0632 \u0622\u0646\u062c\u0627 \u06a9\u0647 \u0628\u0627 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u062f\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f \u0645\u063a\u0632 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f \u0647\u0648\u0631\u0645\u0648\u0646 \u0628\u0647\u0628\u0648\u062f \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062a\u0639\u0627\u062f\u0644 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc \u0648 \u0633\u0644\u0627\u0645\u062a \u06a9\u0628\u062f \u0646\u06cc\u0632 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u0646\u0627\u0632\u0627\u06cc\u06cc \u062f\u0631 \u0632\u0646\u0627\u0646 \u0639\u0641\u0648\u0646\u062a \u062f\u0633\u062a\u06af\u0627\u0647 \u062a\u0646\u0627\u0633\u0644\u06cc \u0627\u0633\u062a. <a href=\"https:\/\/bizma.ir\/product\/ganoderma-soap-dr-biz\/\" target=\"_blank\" rel=\"noopener\">\u0635\u0627\u0628\u0648\u0646 \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627<\/a> \u062e\u0648\u0627\u0635 \u0628\u06cc\u200c\u0646\u0638\u06cc\u0631\u06cc \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0639\u0641\u0648\u0646\u062a\u200c\u0647\u0627\u06cc \u0632\u0646\u0627\u0646 \u062f\u0627\u0631\u062f.<\/p>\n<p>\u0645\u0637\u0627\u0644\u0639\u0627\u062a \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u062b\u0627\u062a\u06cc\u0631 \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\u060c \u0627\u0646\u062c\u0627\u0645 \u0634\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u062a\u0645\u0627\u0645\u06cc \u0627\u06cc\u0646 \u0645\u0637\u0627\u0644\u0639\u0627\u062a\u060c \u0646\u062a\u0627\u06cc\u062c \u0645\u062b\u0628\u062a \u0648 \u0627\u0645\u06cc\u062f \u0628\u062e\u0634 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0648\u0627\u0642\u0639 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0627 \u0628\u0647\u0628\u0648\u062f \u0633\u0644\u0627\u0645\u062a \u06a9\u0644\u06cc \u0628\u062f\u0646\u060c \u062a\u0639\u0627\u062f\u0644 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc\u060c \u0628\u0647\u0628\u0648\u062f \u0633\u0644\u0627\u0645\u062a \u06a9\u0628\u062f\u060c \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u0646\u0633 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062a\u0627\u062b\u06cc\u0631 \u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f. \u0628\u0627 \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u062c\u0646\u0633\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0642\u062f\u0631\u062a \u0628\u0627\u0631\u0648\u0631\u06cc \u0632\u0646 \u0648 \u0645\u0631\u062f \u0631\u0627 \u062a\u0642\u0648\u06cc\u062a \u06a9\u0631\u062f. \u0642\u0627\u0631\u0686 \u0631\u06cc\u0634\u06cc \u06cc\u0627 \u0647\u0645\u0627\u0646 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0627 \u062a\u0642\u0648\u06cc\u062a \u0646\u0634\u0627\u0637 \u0648 \u0633\u0644\u0627\u0645\u062a\u06cc \u0639\u0645\u0648\u0645\u06cc\u060c \u0628\u062f\u0646 \u0631\u0627 \u0648\u0627\u062f\u0627\u0631 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633 \u0648 \u0628\u0647\u0628\u0648\u062f \u0641\u0631\u0622\u06cc\u0646\u062f \u062a\u0648\u0644\u06cc\u062f \u0645\u062b\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AA%D8%A7%D8%AB%DB%8C%D8%B1_%D9%82%D9%87%D9%88%D9%87_%D8%B3%D9%88%D9%BE%D8%B1%DB%8C%D9%85_%DA%AF%D8%A7%D9%86%D9%88%D8%AF%D8%B1%D9%85%D8%A7_%D8%AF%D8%B1_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\"><\/span>\u062a\u0627\u062b\u06cc\u0631 \u0642\u0647\u0648\u0647 \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0627 \u062a\u0627\u062b\u06cc\u0631 \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0631 \u0642\u0648\u0627\u06cc \u062c\u0646\u0633\u06cc \u0648 \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u062f\u0646\u060c \u0633\u0644\u0627\u0645\u062a \u06a9\u0628\u062f\u060c \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633 \u0648 \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u062c\u0646\u0633\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0648\u062b\u0631 \u0628\u0627\u0634\u062f. \u0627\u06af\u0631 \u0634\u0645\u0627 \u0647\u0645 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0631\u062f\u0646 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u0646\u0633 \u0637\u0628\u06cc\u0639\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0631\u0648\u0631\u06cc \u062e\u0648\u062f \u0647\u0633\u062a\u06cc\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0633\u0648\u067e\u0631\u06cc\u0645 \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<p>\u0645\u0634\u0627\u0647\u062f\u0647 <a href=\"https:\/\/bizma.ir\/product\/dr-biz-infertility-treatment-package\/\" target=\"_blank\" rel=\"noopener\">\u067e\u06a9\u06cc\u062c \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062c\u0646\u0633\u06cc \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a><\/p>\n<p>\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0642\u0648\u06cc\u200c\u062a\u0631\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0622\u062f\u0627\u067e\u062a\u0648\u0698\u0646 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u0628\u0627 \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0642\u0634\u0631 \u0622\u062f\u0631\u0646\u0627\u0644\u06cc\u0646 \u0645\u063a\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0631\u062d\u0645\u060c \u0627\u0633\u067e\u0631\u0645 \u0648 \u062a\u062e\u0645\u06a9\u200c\u0647\u0627 \u0631\u0627 \u0631\u0641\u0639 \u06a9\u0646\u062f. \u0628\u0627 \u0628\u0647\u0628\u0648\u062f \u0633\u0637\u062d \u0627\u0633\u062a\u0631\u0633 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0622\u0631\u0627\u0645\u0634 \u06a9\u0644\u06cc \u062f\u0631 \u0628\u062f\u0646\u060c \u0686\u0631\u062e\u0647 \u0642\u0627\u0639\u062f\u06af\u06cc \u062a\u0646\u0638\u06cc\u0645 \u0648 \u06a9\u06cc\u0641\u06cc\u062a \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0642\u0627\u0631\u0686 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062f\u0627\u0634\u062a\u0646 \u062e\u0648\u0627\u0635 \u0636\u062f \u0627\u0644\u062a\u0647\u0627\u0628\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0628\u0647\u0628\u0648\u062f \u0641\u0631\u0627\u06cc\u0646\u062f \u0627\u0633\u067e\u0631\u0645 \u0633\u0627\u0632\u06cc \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u0648 \u06a9\u0627\u0647\u0634 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0645\u062b\u0644 \u0641\u06cc\u0628\u0631\u0648\u0645\u0698 \u0622\u0646\u062f\u0648\u0645\u062a\u0631\u06cc\u0648\u0632 \u06cc\u0627 \u0642\u0627\u0639\u062f\u06af\u06cc \u0647\u0627\u06cc \u062f\u0631\u062f\u0646\u0627\u06a9 \u062f\u0631 \u0632\u0646\u0627\u0646 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<p>\u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0633\u0648\u067e\u0631\u06cc\u0645 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632 \u0628\u0631\u0627\u06cc \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0627\u06cc\u0639 \u06cc\u0639\u0646\u06cc \u0647\u0645\u0627\u0646 \u067e\u0648\u062f\u0631 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0627\u0645\u06a9\u0627\u0646 \u067e\u0630\u06cc\u0631 \u0627\u0633\u062a. \u0648\u0644\u06cc \u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0648\u0634\u060c \u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0627\u0633\u062a. \u062f\u0632 \u0645\u0646\u0627\u0633\u0628 \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0631\u0648\u0631\u06cc \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0634\u0631\u0627\u06cc\u0637\u06cc \u06a9\u0647 \u0628\u062f\u0646 \u0634\u0645\u0627 \u062f\u0627\u0631\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0632 \u06cc\u06a9 \u0648 \u0646\u06cc\u0645 \u062a\u0627 \u0646\u0647 \u06af\u0631\u0645 \u0628\u0627\u0634\u062f. \u0633\u0639\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u067e\u0633 \u0627\u0632 \u062f\u0648\u0631\u0647\u200c\u06cc \u062f\u0631\u0645\u0627\u0646 \u0627\u0632 \u0645\u0635\u0631\u0641 \u0628\u06cc\u0634 \u0627\u0632 \u0627\u0646\u062f\u0627\u0632\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f. \u0632\u06cc\u0631\u0627 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u0646\u0627\u0631\u0627\u062d\u062a\u06cc \u0645\u0639\u062f\u0647\u060c \u0633\u0631\u062f\u0631\u062f\u060c \u062e\u0634\u06a9\u06cc \u0628\u06cc\u0646\u06cc \u0648 \u0645\u062c\u0627\u0631\u06cc \u062a\u0646\u0641\u0633\u06cc\u060c \u0645\u062f\u0641\u0648\u0639 \u062e\u0648\u0646\u06cc \u0648 \u0633\u0631\u06af\u06cc\u062c\u0647 \u0634\u0648\u062f.<\/p>\n<p>\u0628\u0647 \u0637\u0648\u0631 \u062e\u0644\u0627\u0635\u0647 \u0628\u0627\u06cc\u062f \u06af\u0641\u062a \u06a9\u0647 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062f\u0627\u0634\u062a\u0646 \u0639\u0635\u0627\u0631\u0647 \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062e\u0648\u0627\u0635 \u0633\u0644\u0627\u0645\u062a\u200c\u0645\u062d\u0648\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u062f\u0627\u0631\u062f\u060c \u0627\u0645\u0627 \u0631\u0634\u062f \u0648 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u062f\u0646\u060c \u06a9\u0627\u0647\u0634 \u067e\u0627\u0633\u062e \u0628\u0647 \u0627\u0633\u062a\u0631\u0633 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u0644\u0627\u0645\u062a \u06a9\u0628\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0639\u0627\u062f\u0644 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc \u0631\u0627 \u062f\u0631 \u0628\u062f\u0646 \u0632\u0648\u062c\u200c\u0647\u0627\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0647 \u0648 \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0633\u0644\u0627\u0645\u062a \u0631\u0648\u0646\u062f \u062a\u0648\u0644\u06cc\u062f \u0645\u062b\u0644 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0627\u0646\u0633 \u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0631 \u0627\u0641\u0631\u0627\u062f \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-medium wp-image-6286\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/04\/\u0633\u0648\u067e\u0631\u06cc\u0645-\u0628\u06cc\u0632\u0645\u0627-1-400x400-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/04\/\u0633\u0648\u067e\u0631\u06cc\u0645-\u0628\u06cc\u0632\u0645\u0627-1-400x400-1-300x300.jpg 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/04\/\u0633\u0648\u067e\u0631\u06cc\u0645-\u0628\u06cc\u0632\u0645\u0627-1-400x400-1-150x150.jpg 150w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/04\/\u0633\u0648\u067e\u0631\u06cc\u0645-\u0628\u06cc\u0632\u0645\u0627-1-400x400-1.jpg 400w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/bizma.ir\/product\/ganoderma-supreme-coffee-dr-biz\/\" target=\"_blank\" rel=\"nofollow\" class=\"shortc-button medium button\">\u0642\u06cc\u0645\u062a \u0642\u0647\u0648\u0647 \u0641\u0648\u0631\u06cc \u0633\u0648\u067e\u0631\u06cc\u0645 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a>\n<h3><span class=\"ez-toc-section\" id=\"%D9%86%D8%AD%D9%88%D9%87_%D9%85%D8%B5%D8%B1%D9%81_%D9%82%D9%87%D9%88%D9%87_%DA%AF%D8%A7%D9%86%D9%88%D8%AF%D8%B1%D9%85%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%86%D8%A7%D8%B2%D8%A7%DB%8C%DB%8C_%D9%88_%D9%86%D8%A7%D8%A8%D8%A7%D8%B1%D9%88%D8%B1%DB%8C\"><\/span>\u0646\u062d\u0648\u0647 \u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u0645\u06a9\u0645\u0644\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u0634\u0648\u062f. \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0628\u0647 \u062c\u0627\u06cc \u062e\u0631\u06cc\u062f \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062a\u0642\u0644\u0628\u06cc \u06a9\u0647 \u0627\u0632 \u0642\u0627\u0631\u0686 \u0644\u0648\u0633\u06cc\u062f\u0648\u0645 \u062f\u0631 \u062a\u0648\u0644\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0628\u0647 \u0635\u0648\u0631\u062a \u0641\u0644\u0647 \u0648 \u06a9\u0627\u0645\u0644\u0627\u064b \u0622\u0644\u0648\u062f\u0647 \u0639\u0631\u0636\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f\u060c \u0642\u0647\u0648\u0647\u200c\u0647\u0627\u06cc \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632 \u0631\u0627 \u062a\u0647\u06cc\u0647 \u06a9\u0646\u06cc\u062f. \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0645\u0648\u062c\u0648\u062f \u062f\u0631 \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0642\u0647\u0648\u0647\u200c\u0647\u0627 \u06af\u0646\u062c\u0627\u0646\u062f\u0647 \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u062a\u0627 \u0628\u06cc\u0645\u0627\u0631\u0627\u0646 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u062f\u0631 \u06a9\u0646\u0627\u0631 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0642\u0647\u0648\u0647 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0627\u0646\u0631\u0698\u06cc \u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632\u060c \u0627\u0632 \u062e\u0648\u0627\u0635 \u0633\u0644\u0627\u0645\u062a \u0645\u062d\u0648\u0631 \u0648 \u0641\u0631\u0627\u0633\u0648\u062f\u0645\u0646\u062f \u0627\u06cc\u0646 \u0646\u0648\u0634\u06cc\u062f\u0646\u06cc\u200c\u0647\u0627 \u0646\u06cc\u0632 \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u0646\u062f.<\/p>\n<p>\u0627\u06af\u0631 \u0628\u0647 \u0637\u0639\u0645 \u062a\u0644\u062e \u0642\u0647\u0648\u0647 \u0639\u0644\u0627\u0642\u0647 \u0646\u062f\u0627\u0631\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u06a9\u0627\u0641\u06cc \u0627\u0633\u062a \u062a\u0627 \u0631\u0648\u0632\u0627\u0646\u0647 \u06f2 \u0627\u0644\u06cc \u06f3 \u0641\u0646\u062c\u0627\u0646 \u0627\u0632 \u0642\u0647\u0648\u0647 \u0648 \u0647\u0627\u062a \u0686\u0627\u06a9\u0644\u062a \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc\u060c \u062a\u0639\u0627\u062f\u0644 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc\u060c \u06a9\u0627\u0647\u0634 \u0627\u0644\u062a\u0647\u0627\u0628\u0627\u062a \u0631\u062d\u0645\u06cc \u0648 \u062f\u0631\u06cc\u0627\u0641\u062a \u0627\u0645\u0644\u0627\u062d \u0648 \u0645\u0648\u0627\u062f \u0645\u063a\u0630\u06cc \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a\u0646 \u0627\u0633\u067e\u0631\u0645\u200c\u0647\u0627\u06cc \u0642\u0648\u06cc\u200c\u062a\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u062f\u0631 \u0645\u062f\u062a \u0632\u0645\u0627\u0646 \u06a9\u0648\u062a\u0627\u0647 \u0628\u0647 \u0646\u062a\u06cc\u062c\u0647 \u0628\u0631\u0633\u06cc\u062f.<\/p>\n<p>\u0628\u0631\u0627\u06cc \u0645\u0634\u0627\u0647\u062f\u0647 <a href=\"https:\/\/bizma.ir\/category-ganoderma-coffee\/\" target=\"_blank\" rel=\"noopener\"><strong>\u0642\u06cc\u0645\u062a \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/strong><\/a>\u00a0\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0647\u0645\u06cc\u0646 \u062d\u0627\u0644\u0627 \u0633\u0641\u0627\u0631\u0634 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 <strong>\u0628\u06cc\u0632\u0645\u0627<\/strong> \u062b\u0628\u062a \u06a9\u0646\u06cc\u062f \u0648 \u0627\u06cc\u0646 \u0642\u0647\u0648\u0647\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u06a9\u0648\u062a\u0627\u0647\u200c\u062a\u0631\u06cc\u0646 \u0632\u0645\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0648 \u0628\u0627 \u0631\u0642\u0627\u0628\u062a\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0642\u06cc\u0645\u062a \u062a\u0647\u06cc\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-9066 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u062d\u0648\u0647-\u0645\u0635\u0631\u0641-\u0642\u0647\u0648\u0647-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0628\u0631\u0627\u06cc-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0648-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc.webp\" alt=\"\u0646\u062d\u0648\u0647 \u0645\u0635\u0631\u0641 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u062d\u0648\u0647-\u0645\u0635\u0631\u0641-\u0642\u0647\u0648\u0647-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0628\u0631\u0627\u06cc-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0648-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u062d\u0648\u0647-\u0645\u0635\u0631\u0641-\u0642\u0647\u0648\u0647-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0628\u0631\u0627\u06cc-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0648-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u062d\u0648\u0647-\u0645\u0635\u0631\u0641-\u0642\u0647\u0648\u0647-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0628\u0631\u0627\u06cc-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0648-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/06\/\u0646\u062d\u0648\u0647-\u0645\u0635\u0631\u0641-\u0642\u0647\u0648\u0647-\u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627-\u0628\u0631\u0627\u06cc-\u062f\u0631\u0645\u0627\u0646-\u0646\u0627\u0632\u0627\u06cc\u06cc-\u0648-\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h5><strong>\u062c\u0645\u0639 \u0628\u0646\u062f\u06cc<\/strong><\/h5>\n<p>\u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0639\u0644\u0644 \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0648\u0627\u0631\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u06cc\u0646 \u0639\u0644\u0644 \u0631\u0627 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0627\u062f \u0648 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0622\u0646 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u06a9\u0645\u06a9 \u06af\u0631\u0641\u062a \u062a\u0627 \u0632\u0648\u062c\u06cc\u0646 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u0635\u0627\u062d\u0628 \u0641\u0631\u0632\u0646\u062f \u0634\u0648\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0634\u0645\u0627 \u0633\u0628\u06a9 \u0632\u0646\u062f\u06af\u06cc \u0633\u0627\u0644\u0645\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648 \u062f\u0631 \u0633\u0646\u06cc\u0646 \u0645\u0646\u0627\u0633\u0628 \u0628\u0631\u0627\u06cc \u0641\u0631\u0632\u0646\u062f \u0622\u0648\u0631\u06cc \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f\u060c \u0627\u062d\u062a\u0645\u0627\u0644 \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0686\u0627\u0631 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0634\u0648\u06cc\u062f \u0628\u0633\u06cc\u0627\u0631 \u06a9\u0645 \u0627\u0633\u062a. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0627 \u067e\u06cc\u0634\u0631\u0641\u062a \u0639\u0644\u0645 \u0686\u06cc\u0632\u06cc \u062f\u0631 \u062d\u062f\u0648\u062f \u06f8\u06f5 \u062f\u0631\u0635\u062f \u0627\u0632 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc\u200c\u0647\u0627 \u0642\u0627\u0628\u0644\u06cc\u062a \u062f\u0631\u0645\u0627\u0646 \u062f\u0627\u0631\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u062f\u0648\u0646 \u0627\u0633\u062a\u0631\u0633 \u0648 \u062a\u062d\u0645\u0644 \u0627\u062d\u0633\u0627\u0633\u0627\u062a \u0645\u0646\u0641\u06cc \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0647\u0631\u0686\u0647 \u0632\u0648\u062f\u062a\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062f\u0631\u0645\u0627\u0646 \u0628\u0631\u0648\u06cc\u062f.<\/p>\n<p>\u062f\u0631 \u06a9\u0646\u0627\u0631 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646\u06cc \u067e\u0632\u0634\u06a9\u06cc \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0627 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc \u0628\u062f\u0646\u060c \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633 \u0648 \u0645\u062a\u0639\u0627\u062f\u0644 \u06a9\u0631\u062f\u0646 \u0645\u06cc\u0632\u0627\u0646 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u062a\u0631\u0634\u062d \u0634\u062f\u0647 \u062f\u0631 \u0628\u062f\u0646\u062a\u0627\u0646\u060c \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646 \u0631\u0627 \u06a9\u0645\u062a\u0631 \u06a9\u0646\u06cc\u062f. \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u062a\u0627 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u060c \u0622\u0631\u0627\u0645\u0634 \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u06cc \u0634\u0645\u0627 \u0628\u0647 \u0645\u0642\u062f\u0627\u0631 \u06a9\u0627\u0641\u06cc \u0648 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u062a\u0631\u0634\u062d \u0634\u0648\u0646\u062f. \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f <a href=\"https:\/\/bizma.ir\/category-ganoderma-coffee\/\" target=\"_blank\" rel=\"noopener\">\u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/a> \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0647\u0645\u06cc\u0646 \u0645\u062c\u0645\u0648\u0639\u0647 \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f.<\/p>\n<h5>\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644<\/h5>\n<h5>\u0642\u0627\u0631\u0686 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0686\u0647 \u062a\u0627\u062b\u06cc\u0631\u06cc \u062f\u0631 \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u062f\u0627\u0631\u062f\u061f<\/h5>\n<p>\u0627\u06cc\u0646 \u0642\u0627\u0631\u0686 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0622\u062f\u0627\u067e\u062a\u0648\u0698\u0646\u060c \u0622\u0646\u062a\u06cc \u0627\u06a9\u0633\u06cc\u062f\u0627\u0646\u060c \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0636\u062f \u0627\u0644\u062a\u0647\u0627\u0628\u06cc \u0648 \u067e\u0644\u06cc \u0633\u0627\u06a9\u0627\u0631\u06cc\u062f\u200c\u0647\u0627\u06cc \u062e\u0627\u0635 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0648 \u062a\u0642\u0648\u06cc\u062a \u0633\u06cc\u0633\u062a\u0645 \u0627\u06cc\u0645\u0646\u06cc\u060c \u062a\u0646\u0638\u06cc\u0645 \u0648 \u0645\u062a\u0639\u0627\u062f\u0644 \u06a9\u0631\u062f\u0646 \u062a\u0631\u0634\u062d \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627\u060c \u06a9\u0627\u0647\u0634 \u0627\u0633\u062a\u0631\u0633\u060c \u0631\u0641\u0639 \u0639\u0641\u0648\u0646\u062a\u200c\u0647\u0627 \u0648 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc \u062f\u0633\u062a\u06af\u0627\u0647 \u062c\u0646\u0633\u06cc\u060c \u062a\u0642\u0648\u06cc\u062a \u0642\u062f\u0631\u062a \u0645\u0631\u062f \u062f\u0631 \u0627\u0633\u067e\u0631\u0645 \u0633\u0627\u0632\u06cc \u0648 \u062a\u0646\u0638\u06cc\u0645 \u062a\u062e\u0645\u06a9 \u06af\u0630\u0627\u0631\u06cc \u0648 \u0686\u0631\u062e\u0647 \u0642\u0627\u0639\u062f\u06af\u06cc \u062a\u0627\u062b\u06cc\u0631 \u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f.<\/p>\n<h5>\u06a9\u062f\u0627\u0645 \u0637\u0639\u0645 \u0627\u0632 \u0642\u0647\u0648\u0647 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u062f\u0631 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0645\u0648\u062b\u0631 \u0627\u0633\u062a\u061f<\/h5>\n<p>\u0642\u0647\u0648\u0647 \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0645\u0642\u062f\u0627\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0632 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0631\u0627 \u062f\u0631 \u062e\u0648\u062f \u062f\u0627\u0631\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0642\u0647\u0648\u0647 \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062f\u0627\u0634\u062a\u0646 \u062c\u06cc\u0646\u0633\u06cc\u0646\u06af \u0648 \u062e\u0631\u0646\u0648\u0628\u060c \u062e\u0648\u0627\u0635 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0628\u0647 \u0628\u062f\u0646 \u0634\u0645\u0627 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u062f. \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0631\u0627\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0646\u062a\u0627\u06cc\u062c \u0628\u0647\u062a\u0631 \u0648 \u0628\u06cc\u0634\u062a\u0631\u060c \u0631\u0648\u0632\u0627\u0646\u0647 \u062f\u0648 \u0627\u0644\u06cc \u0633\u0647 \u0641\u0646\u062c\u0627\u0646 \u0627\u0632 \u0642\u0647\u0648\u0647 \u0633\u0648\u067e\u0631\u06cc\u0645 \u06af\u0627\u0646\u0648\u062f\u0631\u0645\u0627 \u0628\u0631\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u0646\u0627\u0632\u0627\u06cc\u06cc \u0648 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u0645\u0642\u0627\u0644\u0627\u062a \u0645\u0631\u062a\u0628\u0637 :<\/strong><\/p>\n<ul>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/%d8%a7%d9%81%d8%b2%d8%a7%db%8c%d8%b4-%d9%85%db%8c%d9%84-%d8%ac%d9%86%d8%b3%db%8c\/\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u0644 \u062c\u0646\u0633\u06cc \u0622\u0642\u0627\u06cc\u0627\u0646 \u0628\u062f\u0648\u0646 \u0646\u06cc\u0627\u0632 \u0628\u0647 \u062f\u0627\u0631\u0648<\/a><\/li>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/%d8%a7%d9%81%d8%b2%d8%a7%db%8c%d8%b4-%d9%85%db%8c%d9%84-%d8%ac%d9%86%d8%b3%db%8c-%d8%b2%d9%86%d8%a7%d9%86\/\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u0644 \u062c\u0646\u0633\u06cc \u0632\u0646\u0627\u0646 \u0628\u0647 \u0622\u0633\u0627\u0646\u06cc<\/a><\/li>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/ovarian-cysts\/\">\u062f\u0631\u0645\u0627\u0646 \u06a9\u06cc\u0633\u062a \u062a\u062e\u0645\u062f\u0627\u0646\u061b \u0639\u0644\u062a\u060c \u0639\u0644\u0627\u0626\u0645 \u0648 \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0646<\/a><\/li>\n<li><a href=\"https:\/\/bizma.ir\/mag\/%d9%82%d9%87%d9%88%d9%87-%d8%b3%d9%88%d9%be%d8%b1%db%8c%d9%85-%d8%a8%d8%b1%d8%a7%db%8c-%d9%86%d8%a7%d8%a8%d8%a7%d8%b1%d9%88%d8%b1%db%8c\/\" target=\"_blank\" rel=\"noopener\">\u0642\u0647\u0648\u0647 \u0633\u0648\u067e\u0631\u06cc\u0645 \u0628\u0631\u0627\u06cc \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc<\/a><\/li>\n<li><a href=\"https:\/\/bizma.ir\/mag\/%d8%b3%db%8c%d8%b1-%d8%b3%db%8c%d8%a7%d9%87-%d8%a8%d8%b1%d8%a7%db%8c-%d8%b2%d9%88%d8%af-%d8%a7%d9%86%d8%b2%d8%a7%d9%84%db%8c\/\" target=\"_blank\" rel=\"noopener\">\u0633\u06cc\u0631 \u0633\u06cc\u0627\u0647 \u0628\u0631\u0627\u06cc \u0632\u0648\u062f \u0627\u0646\u0632\u0627\u0644\u06cc<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u0642\u0628\u0644 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632 \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0632\u0648\u062c\u200c\u0647\u0627 \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u062c\u0647\u0627\u0646 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0646\u0627\u0628\u0627\u0631\u0648\u0631\u06cc \u0631\u0627 \u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0627\u0648\u0644 \u0627\u0632\u062f\u0648\u0627\u062c \u062e\u0648\u062f \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f \u0648\u0644\u06cc \u067e\u0633 \u0627\u0632 \u062f\u0646\u0628\u0627\u0644 \u06a9\u0631\u062f\u0646 \u062f\u0648\u0631\u0647 \u062f\u0631\u0645\u0627\u0646\u06cc \u0628\u0627 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062f\u0631\u0645\u0627\u0646 \u062a\u0648\u0627\u0646\u0633\u062a\u0647\u200c\u0627\u0646\u062f \u0635\u0627\u062d\u0628 \u0641\u0631\u0632\u0646\u062f \u0634\u0648\u062f. \u0627\u062d\u0633\u0627\u0633 \u0644\u0630\u062a \u067e\u062f\u0631 \u0648 \u0645\u0627\u062f\u0631 \u0634\u062f\u0646 \u062a\u062c\u0631\u0628\u0647 \u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u062e\u06cc \u0627\u0632 &hellip;<\/p>\n","protected":false},"author":2787,"featured_media":9057,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[221],"class_list":["post-4381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health","tag-ganoderma"],"_links":{"self":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts\/4381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/users\/2787"}],"replies":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/comments?post=4381"}],"version-history":[{"count":0,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts\/4381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/media\/9057"}],"wp:attachment":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/media?parent=4381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/categories?post=4381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/tags?post=4381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}