{"id":6665,"date":"2022-11-05T17:00:45","date_gmt":"2022-11-05T13:30:45","guid":{"rendered":"https:\/\/bizma.ir\/mag\/?p=6665"},"modified":"2026-06-13T20:41:51","modified_gmt":"2026-06-13T17:11:51","slug":"%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af","status":"publish","type":"post","link":"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/","title":{"rendered":"\u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u0628\u0627 \u0633\u0627\u062f\u0647 \u062a\u0631\u06cc\u0646 \u0631\u0648\u0634 \u062e\u0627\u0646\u06af\u06cc!"},"content":{"rendered":"<p>\u0632\u0646\u0627\u0646 \u0627\u0632 \u0633\u0646 \u0628\u0644\u0648\u063a \u062a\u0627 \u06cc\u0627\u0626\u0633\u06af\u06cc\u060c \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0627\u0647\u0627\u0646\u0647 \u0628\u0627 \u0641\u0631\u0622\u06cc\u0646\u062f \u0637\u0628\u06cc\u0639\u06cc \u0628\u0647 \u0646\u0627\u0645 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u063a\u0644\u0628 \u0632\u0646\u0627\u0646 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631\u062f \u0648 \u0627\u0633\u067e\u0627\u0633\u0645\u200c\u0647\u0627\u06cc \u0634\u06a9\u0645\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u062e\u0627\u0646\u06af\u06cc\u00a0\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0639\u0644\u0645\u06cc \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0637\u0644\u0627\u06cc\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u0642\u0627\u0639\u062f\u06af\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter-rtl ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u062e\u0648\u0627\u0647\u06cc\u062f \u062e\u0648\u0627\u0646\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D8%AF%D8%B1%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%A8%D9%87_%D8%AE%D8%A7%D8%B7%D8%B1_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\" >\u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u0628\u0647 \u062e\u0627\u0637\u0631 \u0686\u06cc\u0633\u062a\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D9%82%D8%B7%D8%B9_%D9%81%D9%88%D8%B1%DB%8C_%D9%88_%DA%A9%D8%A7%D9%87%D8%B4_%D8%AF%D8%B1%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C\" >\u0642\u0637\u0639 \u0641\u0648\u0631\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u062e\u0627\u0646\u06af\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B9%D9%82%D8%A8_%D8%A7%D9%81%D8%AA%D8%A7%D8%AF%D9%86_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%AF%D8%AE%D8%AA%D8%B1%D8%A7%D9%86%D9%87\" >\u062f\u0631\u0645\u0627\u0646 \u0639\u0642\u0628 \u0627\u0641\u062a\u0627\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u062f\u062e\u062a\u0631\u0627\u0646\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D8%B1%D9%88%D8%B4_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%81%D9%88%D8%B1%DB%8C_%D8%B9%D9%82%D8%A8_%D8%A7%D9%81%D8%AA%D8%A7%D8%AF%D9%86_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%AF%D8%B1_%D8%AF%D8%AE%D8%AA%D8%B1%D8%A7%D9%86_%D9%88_%D8%B2%D9%86%D8%A7%D9%86_%D9%85%D8%AC%D8%B1%D8%AF\" >\u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646 \u0641\u0648\u0631\u06cc \u0639\u0642\u0628 \u0627\u0641\u062a\u0627\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631 \u062f\u062e\u062a\u0631\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0645\u062c\u0631\u062f<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AF%D9%85%D9%86%D9%88%D8%B4_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%B4%D8%AF%D9%86\" >\u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0628\u0631\u0627\u06cc \u067e\u0631\u06cc\u0648\u062f \u0634\u062f\u0646<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B2%D9%88%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%B4%D8%AF%D9%86_%DA%86%DB%8C_%D8%A8%D8%AE%D9%88%D8%B1%DB%8C%D9%85%D8%9F\" >\u0628\u0631\u0627\u06cc \u0632\u0648\u062f \u067e\u0631\u06cc\u0648\u062f \u0634\u062f\u0646 \u0686\u06cc \u0628\u062e\u0648\u0631\u06cc\u0645\u061f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/bizma.ir\/mag\/%da%a9%d8%a7%d9%87%d8%b4-%d8%af%d8%b1%d8%af-%d9%be%d8%b1%db%8c%d9%88%d8%af\/#%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%B7%D9%84%D8%A7%DB%8C%DB%8C_%DA%A9%D8%A7%D9%87%D8%B4_%D8%AF%D8%B1%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF\" >\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0637\u0644\u0627\u06cc\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%A8%D9%87_%D8%AE%D8%A7%D8%B7%D8%B1_%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\"><\/span>\u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u0628\u0647 \u062e\u0627\u0637\u0631 \u0686\u06cc\u0633\u062a\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0631\u062d\u0645 \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u062e\u0648\u062f \u062f\u0631 \u0646\u06af\u0647 \u062f\u0627\u0634\u062a\u0646 \u062c\u0646\u06cc\u0646\u060c \u0647\u0631 \u0645\u0627\u0647 \u06cc\u06a9 \u0644\u0627\u06cc\u0647 \u0645\u062d\u0627\u0641\u0638 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0631\u062e \u0646\u062f\u0647\u062f \u0648 \u0647\u06cc\u0686 \u0627\u0633\u067e\u0631\u0645\u06cc \u0646\u062a\u0648\u0627\u0646\u062f \u0628\u0627 \u062a\u062e\u0645\u06a9 \u0622\u0632\u0627\u062f \u0634\u062f\u0647 \u0644\u0642\u0627\u062d \u06a9\u0646\u062f\u060c \u0627\u06cc\u0646 \u0644\u0627\u06cc\u0647 \u0636\u0639\u06cc\u0641 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0644\u0627\u06cc\u0647 \u0636\u0639\u06cc\u0641 \u0634\u062f\u0647 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u067e\u0631\u06cc\u0648\u062f \u062f\u0686\u0627\u0631 \u0634\u06a9\u0646\u0646\u062f\u06af\u06cc \u0648 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639 \u0627\u06cc\u0646 \u0628\u0627\u0641\u062a \u062e\u0648\u0646\u06cc \u062e\u0627\u0631\u062c \u0634\u062f\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u062f\u0631\u062f \u0648 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc \u0634\u0648\u062f. \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0647\u0631 \u06f2\u06f1 \u0631\u0648\u0632 \u06cc\u0627 \u0647\u0631 \u06f3\u06f5 \u0631\u0648\u0632 \u0627\u062a\u0641\u0627\u0642 \u0628\u06cc\u0641\u062a\u062f\u060c \u0627\u0644\u0628\u062a\u0647 \u0633\u06cc\u06a9\u0644 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0632\u0646\u0627\u0646 \u0627\u06cc\u0631\u0627\u0646\u06cc \u06f2\u06f8 \u0631\u0648\u0632 \u0627\u0633\u062a.<\/p>\n<p>\u0627\u06cc\u0646 \u062f\u0631\u062f \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0646\u0648\u0627\u062d\u06cc \u067e\u0627\u06cc\u06cc\u0646 \u0634\u06a9\u0645 \u06a9\u0645\u0631 \u06cc\u0627 \u062d\u062a\u06cc \u062f\u0631 \u0622\u0646\u200c\u0647\u0627 \u0627\u062d\u0633\u0627\u0633 \u0634\u0648\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a \u0632\u06cc\u0627\u062f \u0634\u062f\u0646 \u062f\u0631\u062f \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u0639\u0631\u0641\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f. \u0627\u0644\u0628\u062a\u0647 \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f \u06a9\u0647 \u06af\u0627\u0647\u06cc \u0628\u0627 \u0632\u06cc\u0627\u062f \u0634\u062f\u0646 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u062f\u0631\u062f \u062f\u0631 \u0642\u0633\u0645\u062a \u067e\u0627\u06cc\u06cc\u0646\u06cc \u0634\u06a9\u0645 \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D9%82%D8%B7%D8%B9_%D9%81%D9%88%D8%B1%DB%8C_%D9%88_%DA%A9%D8%A7%D9%87%D8%B4_%D8%AF%D8%B1%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%AE%D8%A7%D9%86%DA%AF%DB%8C\"><\/span>\u0642\u0637\u0639 \u0641\u0648\u0631\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u062e\u0627\u0646\u06af\u06cc<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u0644\u0627\u0632\u0645 \u0627\u0633\u062a \u062a\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c \u0647\u0627\u06cc \u0632\u0645\u06cc\u0646\u0647\u200c \u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0647\u06cc\u062f. \u062a\u0646\u06af\u06cc \u062f\u0647\u0627\u0646\u0647 \u0631\u062d\u0645\u060c \u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0641\u06cc\u0628\u0631\u0648\u0645\u060c \u062d\u0636\u0648\u0631 \u06a9\u06cc\u0633\u062a \u06cc\u0627 \u062f\u0627\u0634\u062a\u0646 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c \u0647\u0627\u06cc \u0627\u0644\u062a\u0647\u0627\u0628 \u0644\u06af\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0628\u0627\u06a9\u062a\u0631\u06cc \u0639\u0641\u0648\u0646\u06cc \u0627\u06cc\u062c\u0627\u062f \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u062c\u0645\u0639 \u0628\u0627\u0641\u062a \u062e\u0648\u0646\u06cc \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f. \u0628\u0631\u0627\u06cc \u0642\u0637\u0639 \u0641\u0648\u0631\u06cc \u062f\u0631\u062f\u0647\u0627\u06cc \u0634\u062f\u06cc\u062f \u067e\u0631\u06cc\u0648\u062f \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0647 \u0633\u0631\u0627\u063a \u0645\u0633\u06a9\u0646\u200c\u0647\u0627\u06cc \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0648 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u067e\u0631\u0639\u0648\u0627\u0631\u0636 \u0646\u0631\u0648\u06cc\u062f \u0648 \u0627\u0632 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647 \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<ul>\n<li><strong>\u062d\u0645\u0627\u0645 \u0648 \u062f\u0648\u0634 \u0622\u0628 \u06af\u0631\u0645 \u0648 \u06af\u0631\u0645 \u06a9\u0631\u062f\u0646 \u0634\u06a9\u0645 \u0628\u0627 \u06a9\u06cc\u0633\u0647 \u0622\u0628 \u06af\u0631\u0645<\/strong><\/li>\n<\/ul>\n<p>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u06cc\u0633\u0647\u200c\u0622\u0628\u200c\u06af\u0631\u0645 \u06cc\u0627 \u0631\u0641\u062a\u0646 \u0628\u0647 \u062d\u0645\u0627\u0645 \u0648 \u062f\u0648\u0634 \u06af\u0631\u0641\u062a\u0646 \u0628\u0627 \u0622\u0628 \u0646\u0633\u0628\u062a\u0627 \u06af\u0631\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0627\u0646\u0642\u0628\u0627\u0636\u0627\u062a \u0634\u06a9\u0645\u06cc \u0648 \u062f\u0631\u062f\u0647\u0627\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u067e\u0631\u06cc\u0648\u062f \u0628\u0627\u0634\u062f.<\/p>\n<ul>\n<li><strong>\u062a\u063a\u06cc\u06cc\u0631 \u0631\u0698\u06cc\u0645 \u063a\u0630\u0627\u06cc\u06cc<\/strong><\/li>\n<\/ul>\n<p>\u0628\u0627 \u06a9\u0645 \u06a9\u0631\u062f\u0646 \u0645\u0635\u0631\u0641 \u0686\u0631\u0628\u06cc \u0648 \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u06a9\u0631\u062f\u0646 \u0633\u0628\u0632\u06cc\u062c\u0627\u062a \u062f\u0631 \u0628\u0634\u0642\u0627\u0628 \u063a\u0630\u0627\u06cc\u062a\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u062e\u0648\u062f \u0645\u0648\u062b\u0631 \u0628\u0627\u0634\u06cc\u062f. \u0647\u0631\u0686\u0647 \u0645\u0646\u06cc\u0632\u06cc\u0645 \u0648\u0631\u0648\u062f\u06cc \u0628\u0647 \u0628\u062f\u0646 \u0634\u0645\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0634\u0648\u062f\u060c \u06af\u0631\u0641\u062a\u06af\u06cc \u0639\u0636\u0644\u0627\u062a \u0631\u062d\u0645 \u06a9\u0645\u062a\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f. \u0645\u0646\u06cc\u0632\u06cc\u0645 \u062f\u0631 \u0628\u0627\u062f\u0627\u0645\u060c \u0627\u0633\u0641\u0646\u0627\u062c \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0637\u0628\u06cc\u0639\u06cc \u062f\u06cc\u06af\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n<ul>\n<li><strong>\u0642\u0637\u0639 \u0645\u0635\u0631\u0641 \u0627\u0644\u06a9\u0644\u060c \u06a9\u0627\u0641\u0626\u06cc\u0646 \u0648 \u0646\u0648\u0634\u0627\u0628\u0647\u200c\u0647\u0627\u06cc \u06af\u0627\u0632\u062f\u0627\u0631<\/strong><\/li>\n<\/ul>\n<p>\u0646\u0648\u0634\u0627\u0628\u0647\u200c\u0647\u0627\u06cc \u06af\u0627\u0632\u062f\u0627\u0631\u060c \u0686\u0627\u06cc\u060c \u0642\u0647\u0648\u0647 \u0648 \u0645\u0648\u0627\u0631\u062f \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u0631\u0642\u06cc\u0642\u200c\u200c\u062a\u0631 \u0634\u062f\u0646 \u062e\u0648\u0646 \u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u062a\u0627 \u0622\u0628 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0632 \u0628\u062f\u0646 \u0634\u0645\u0627 \u062e\u0627\u0631\u062c \u0634\u0648\u062f \u0648 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc \u0634\u062f\u06cc\u062f\u06cc \u06a9\u0647 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u062f\u0631\u062f \u0634\u0645\u0627 \u0646\u06cc\u0632 \u062f\u0631 \u067e\u06cc \u062f\u0647\u06cc\u062f\u0631\u0627\u062a\u0647 \u0634\u062f\u0646 \u0628\u062f\u0646\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u062e\u0648\u0627\u0647\u062f \u06cc\u0627\u0641\u062a.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8857 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u06a9\u0627\u0647\u0634-\u062f\u0631\u062f-\u0642\u0627\u0639\u062f\u06af\u06cc.webp\" alt=\"\u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u0642\u0627\u0639\u062f\u06af\u06cc\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u06a9\u0627\u0647\u0634-\u062f\u0631\u062f-\u0642\u0627\u0639\u062f\u06af\u06cc.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u06a9\u0627\u0647\u0634-\u062f\u0631\u062f-\u0642\u0627\u0639\u062f\u06af\u06cc-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u06a9\u0627\u0647\u0634-\u062f\u0631\u062f-\u0642\u0627\u0639\u062f\u06af\u06cc-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u06a9\u0627\u0647\u0634-\u062f\u0631\u062f-\u0642\u0627\u0639\u062f\u06af\u06cc-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D8%B9%D9%82%D8%A8_%D8%A7%D9%81%D8%AA%D8%A7%D8%AF%D9%86_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%AF%D8%AE%D8%AA%D8%B1%D8%A7%D9%86%D9%87\"><\/span>\u062f\u0631\u0645\u0627\u0646 \u0639\u0642\u0628 \u0627\u0641\u062a\u0627\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u062f\u062e\u062a\u0631\u0627\u0646\u0647<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0686\u0631\u062e\u0647 \u0642\u0627\u0639\u062f\u06af\u06cc \u0628\u0647 \u0637\u0648\u0631 \u0645\u06cc\u0627\u0646\u06af\u06cc\u0646 \u0686\u06cc\u0632\u06cc \u062f\u0631 \u062d\u062f\u0648\u062f \u06f2\u06f8 \u0631\u0648\u0632 \u0637\u0648\u0644 \u0645\u06cc\u200c\u06a9\u0634\u062f. \u0627\u0644\u0628\u062a\u0647 \u0637\u0648\u0644 \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647 \u0628\u0631\u0627\u06cc \u0646\u0648\u062c\u0648\u0627\u0646\u0627\u0646 \u0648 \u062f\u062e\u062a\u0631\u0627\u0646\u06cc \u06a9\u0647 \u062a\u0627\u0632\u0647 \u067e\u0631\u06cc\u0648\u062f \u0634\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0633\u062a\u060c \u0686\u0631\u0627 \u06a9\u0647 \u0628\u062f\u0646 \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0631\u0646\u0627\u0645\u0647 \u062f\u0642\u06cc\u0642 \u0631\u0627 \u062f\u0646\u0628\u0627\u0644 \u0646\u06a9\u0646\u062f. \u0628\u0647\u200c\u0647\u0645\u06cc\u0646\u200c\u062e\u0627\u0637\u0631 \u0628\u0631\u062e\u06cc \u0627\u0632 \u062f\u062e\u062a\u0631\u0647\u0627 \u0634\u0627\u0647\u062f \u067e\u0631\u0634 \u062f\u0648\u0631\u0647 \u062f\u0631 \u067e\u0631\u06cc\u0648\u062f\u0647\u0627\u06cc \u0646\u0627\u0645\u0646\u0638\u0645 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p>\u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u062f\u0644\u0627\u06cc\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627\u0639\u062b \u067e\u0631\u0634 \u062f\u0648\u0631\u0647 \u0642\u0627\u0639\u062f\u06af\u06cc \u0634\u0648\u0646\u062f\u060c \u0639\u0648\u0627\u0645\u0644 \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0645\u062b\u0644 \u0634\u06cc\u0648\u0647 \u0632\u0646\u062f\u06af\u06cc\u060c \u0628\u0627\u0644\u0627 \u0628\u0648\u062f\u0646 \u0627\u0633\u062a\u0631\u0633\u060c \u06a9\u0627\u0647\u0634 \u06cc\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0648\u0632\u0646\u060c \u0628\u0631 \u0647\u0645 \u062e\u0648\u0631\u062f\u0646 \u0646\u0638\u0645 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc \u0648 \u0645\u0633\u0627\u0641\u0631\u062a \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0644 \u06a9\u0645 \u062e\u0637\u0631 \u0639\u0642\u0628 \u0627\u0641\u062a\u0627\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u062f\u062e\u062a\u0631\u0627\u0646\u0647 \u0647\u0633\u062a\u0646\u062f. \u0627\u0632 \u062f\u06cc\u06af\u0631 \u062f\u0644\u0627\u06cc\u0644 \u062a\u0627\u062e\u06cc\u0631 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631 \u062f\u062e\u062a\u0631\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f:<\/p>\n<ul>\n<li>\u0648\u0631\u0632\u0634 \u0633\u0646\u06af\u06cc\u0646<\/li>\n<li>\u0636\u062e\u06cc\u0645 \u0634\u062f\u0646 \u067e\u0644\u06cc\u067e\u200c\u0647\u0627 \u062f\u0631 \u067e\u0648\u0634\u0634 \u0631\u062d\u0645\u06cc<\/li>\n<li>\u0628\u06cc\u0645\u0627\u0631\u06cc \u0633\u0646\u062f\u0631\u0648\u0645 \u062a\u062e\u0645\u062f\u0627\u0646 \u067e\u0644\u06cc \u06a9\u06cc\u0633\u062a\u06cc\u06a9<\/li>\n<li>\u0627\u0628\u062a\u0644\u0627 \u0628\u0647 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u062a\u06cc\u0631\u0648\u0626\u06cc\u062f(\u067e\u0631\u06a9\u0627\u0631 \u06cc\u0627 \u06a9\u0645\u200c\u06a9\u0627\u0631)<\/li>\n<li>\u0634\u0631\u0648\u0639 \u0642\u0637\u0639 \u0645\u0635\u0631\u0641 \u0642\u0631\u0635\u200c\u0647\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 \u0648\u0632\u0646 \u06cc\u0627 \u062f\u0627\u0631\u0648\u0647\u0627\u06cc \u062e\u0627\u0635<\/li>\n<\/ul>\n<p>\u062d\u0636\u0648\u0631 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c\u0647\u0627\u06cc\u06cc \u0645\u062b\u0644 \u0641\u06cc\u0628\u0631\u0648\u0626\u06cc\u062f \u06cc\u0627 \u0686\u0633\u0628\u0627\u0646 \u0634\u062f\u0646 \u0644\u0648\u0644\u0647\u200c\u0647\u0627\u06cc \u0645\u062a\u0635\u0644 \u0628\u0647 \u0631\u062d\u0645 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062f\u06cc\u0627\u0628\u062a \u06cc\u0627 \u0628\u06cc\u0645\u0627\u0631\u06cc\u200c \u0646\u0627\u0631\u0633\u0627\u06cc\u06cc \u062a\u062e\u0645\u062f\u0627\u0646 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u062a\u0627\u062e\u06cc\u0631 \u062f\u0631 \u067e\u0631\u06cc\u0648\u062f \u062f\u062e\u062a\u0631\u0627\u0646\u0647 \u0634\u0648\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D9%88%D8%B4_%D8%AF%D8%B1%D9%85%D8%A7%D9%86_%D9%81%D9%88%D8%B1%DB%8C_%D8%B9%D9%82%D8%A8_%D8%A7%D9%81%D8%AA%D8%A7%D8%AF%D9%86_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%AF%D8%B1_%D8%AF%D8%AE%D8%AA%D8%B1%D8%A7%D9%86_%D9%88_%D8%B2%D9%86%D8%A7%D9%86_%D9%85%D8%AC%D8%B1%D8%AF\"><\/span>\u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646 \u0641\u0648\u0631\u06cc \u0639\u0642\u0628 \u0627\u0641\u062a\u0627\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631 \u062f\u062e\u062a\u0631\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0645\u062c\u0631\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0646\u06af\u0631\u0627\u0646 \u0646\u0634\u0648\u06cc\u062f \u0648\u0644\u06cc \u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u067e\u0632\u0634\u06a9 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f\u060c \u0686\u0631\u0627\u06a9\u0647 \u067e\u0631\u06cc\u0648\u062f \u0646\u0627\u0645\u0646\u0638\u0645 \u06cc\u06a9 \u0627\u062e\u062a\u0644\u0627\u0644 \u0628\u0633\u06cc\u0627\u0631 \u0634\u0627\u06cc\u0639 \u062f\u0631 \u0628\u06cc\u0646 \u062f\u062e\u062a\u0631\u0627\u0646 \u062c\u0648\u0627\u0646 \u0627\u0633\u062a. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0645\u0634\u06a9\u0644 \u062a\u06cc\u0631\u0648\u0626\u06cc\u062f\u060c \u062a\u0646\u0628\u0644\u06cc \u062a\u062e\u0645\u062f\u0627\u0646\u060c \u0641\u06cc\u0628\u0631\u0648\u0645 \u0648 \u0645\u0648\u0627\u0631\u062f \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0627\u062d\u062a\u0645\u0627\u0644\u0627\u064b \u0628\u0627 \u0645\u0635\u0631\u0641 <strong>\u0642\u0631\u0635\u200c\u0647\u0627\u06cc \u0627\u0644 \u062f\u06cc\u060c \u062f\u0627\u0631\u0686\u06cc\u0646 \u0648 \u0632\u0639\u0641\u0631\u0627\u0646 <\/strong>\u0645\u0634\u06a9\u0644 \u0634\u0645\u0627 \u062d\u0644 \u062e\u0648\u0627\u0647\u062f \u0634\u062f. \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062f\u062e\u062a\u0631\u0627\u0646 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0627 \u0633\u0646 \u06f1\u06f8 \u06cc\u0627 \u06f1\u06f9 \u0633\u0627\u0644\u06af\u06cc \u0634\u0627\u0647\u062f \u067e\u0631\u06cc\u0648\u062f\u0647\u0627\u06cc \u0646\u0627\u0645\u0646\u0638\u0645 \u0628\u0627\u0634\u0646\u062f\u060c \u067e\u0633 \u0645\u0635\u0631\u0641 \u0642\u0631\u0635 \u06cc\u0627 \u062f\u0627\u0631\u0648\u06cc\u06cc \u06a9\u0647 \u067e\u0632\u0634\u06a9 \u0634\u0645\u0627 \u062a\u062c\u0648\u06cc\u0632 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a \u0631\u0627 \u062c\u062f\u06cc \u0628\u06af\u06cc\u0631\u06cc\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0645\u0646\u0638\u0645\u200c\u062a\u0631\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8841 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062a\u0646\u0638\u06cc\u0645-\u062f\u0648\u0631\u0647-\u0642\u0627\u0639\u062f\u06af\u06cc-\u0628\u0627\u0646\u0648\u0627\u0646.webp\" alt=\"\u0631\u0648\u0634 \u062f\u0631\u0645\u0627\u0646 \u0641\u0648\u0631\u06cc \u0639\u0642\u0628 \u0627\u0641\u062a\u0627\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631 \u062f\u062e\u062a\u0631\u0627\u0646 \u0648 \u0632\u0646\u0627\u0646 \u0645\u062c\u0631\u062f\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062a\u0646\u0638\u06cc\u0645-\u062f\u0648\u0631\u0647-\u0642\u0627\u0639\u062f\u06af\u06cc-\u0628\u0627\u0646\u0648\u0627\u0646.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062a\u0646\u0638\u06cc\u0645-\u062f\u0648\u0631\u0647-\u0642\u0627\u0639\u062f\u06af\u06cc-\u0628\u0627\u0646\u0648\u0627\u0646-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062a\u0646\u0638\u06cc\u0645-\u062f\u0648\u0631\u0647-\u0642\u0627\u0639\u062f\u06af\u06cc-\u0628\u0627\u0646\u0648\u0627\u0646-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062a\u0646\u0638\u06cc\u0645-\u062f\u0648\u0631\u0647-\u0642\u0627\u0639\u062f\u06af\u06cc-\u0628\u0627\u0646\u0648\u0627\u0646-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"%D8%A8%D9%87%D8%AA%D8%B1%DB%8C%D9%86_%D8%AF%D9%85%D9%86%D9%88%D8%B4_%D8%A8%D8%B1%D8%A7%DB%8C_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%B4%D8%AF%D9%86\"><\/span>\u0628\u0647\u062a\u0631\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0628\u0631\u0627\u06cc \u067e\u0631\u06cc\u0648\u062f \u0634\u062f\u0646<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>\u062f\u0645\u0646\u0648\u0634\u200c\u0647\u0627 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062f\u0627\u0631\u0648\u06cc\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u0647\u0633\u062a\u0646\u062f\u060c \u0628\u0627 \u0627\u06cc\u0646\u200c\u062d\u0627\u0644 \u062a\u0631\u06a9\u06cc\u0628 \u063a\u06cc\u0631\u0639\u0644\u0645\u06cc \u0648 \u0627\u0635\u0627\u0641\u0647 \u06a9\u0631\u062f\u0646 \u0646\u0627\u062f\u0631\u0633\u062a \u0686\u0646\u062f\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u06af\u06cc\u0627\u0647\u06cc \u062f\u0631 \u0645\u0642\u0627\u062f\u06cc\u0631 \u063a\u06cc\u0631\u0645\u062c\u0627\u0632\u00a0 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc\u060c \u062f\u0631\u062f \u0648 \u0639\u0648\u0627\u0631\u0636 \u0627\u06cc\u0646\u200c\u0686\u0646\u06cc\u0646\u06cc \u0634\u0648\u062f.<\/p>\n<p>\u062f\u0645\u0646\u0648\u0634 \u0628\u0627\u0646\u0648\u0627\u0646 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0647\u062a\u0631\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u06af\u06cc\u0627\u0647\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u0648 \u0628\u0647\u0628\u0648\u062f \u062a\u0639\u0627\u062f\u0644 \u0647\u0648\u0631\u0645\u0648\u0646\u06cc\u060c \u0628\u0647 \u06a9\u0627\u0647\u0634 \u062e\u0648\u0646 \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a\u0647 \u0648 \u0645\u0646\u0638\u0645 \u0634\u062f\u0646 \u067e\u0631\u06cc\u0648\u062f \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0627\u0632 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a (\u062f\u0631 \u0645\u0642\u06cc\u0627\u0633 \u06a9\u0646\u062a\u0631\u0644 \u0634\u062f\u0647 \u0648 \u0639\u0644\u0645\u06cc) \u062a\u0647\u06cc\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u0648 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u0633\u0645\u200c\u0632\u062f\u0627\u06cc\u06cc \u0648 \u0627\u06cc\u062c\u0627\u062f \u062a\u0639\u0627\u062f\u0644 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f. \u0627\u06af\u0631 \u0645\u0635\u0631\u0641 \u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0631\u0627 \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 pms \u0648 \u0642\u0628\u0644 \u0627\u0632 \u0634\u0631\u0648\u0639 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc\u060c \u0627\u0633\u062a\u0627\u0631\u062a \u0628\u0632\u0646\u06cc\u062f\u060c \u0634\u0627\u0647\u062f \u06a9\u0627\u0647\u0634 \u062a\u0639\u0631\u06cc\u0642 \u0648 \u0627\u062d\u0633\u0627\u0633 \u062e\u0633\u062a\u06af\u06cc \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u0642\u0627\u0639\u062f\u06af\u06cc \u062e\u0648\u062f\u062a\u0627\u0646 \u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0648\u062f.<\/p>\n<p>\u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0628\u0627 \u062f\u0627\u0634\u062a\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0628\u0633\u06cc\u0627\u0631 \u0645\u0648\u062b\u0631\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0641\u06cc\u062a\u0648\u0627\u0633\u062a\u0631\u0648\u0698\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u062a\u0646\u0638\u06cc\u0645 \u0686\u0631\u062e\u0647 \u0642\u0627\u0639\u062f\u06af\u06cc \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0628\u0627 \u062a\u0646\u0638\u06cc\u0645 \u0645\u06cc\u0632\u0627\u0646 \u0639\u0645\u0644\u06a9\u0631\u062f \u062a\u062e\u0645\u062f\u0627\u0646\u060c \u0634\u0645\u0627 \u062f\u06cc\u06af\u0631 \u0646\u06af\u0631\u0627\u0646 \u062f\u0631\u062f \u06a9\u0634\u06cc\u062f\u0646 \u0646\u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0648\u062f. \u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0622\u0631\u0627\u0645\u0628\u062e\u0634 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062a\u0645\u0627\u0645 \u0628\u06cc\u200c\u0642\u0631\u0627\u0631\u06cc\u200c\u0647\u0627 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628\u200c\u0647\u0627\u06cc \u0642\u0628\u0644 \u0648 \u062d\u06cc\u0646 \u067e\u0631\u06cc\u0648\u062f \u0631\u0627 \u0627\u0632 \u0634\u0645\u0627 \u062f\u0648\u0631 \u06a9\u0646\u062f. \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0631\u0627\u0632\u06cc\u0627\u0646\u0647 \u0648 \u067e\u0646\u062c \u0627\u0646\u06af\u0634\u062a \u0627\u0634\u0627\u0631\u0647 \u06a9\u0631\u062f. \u0627\u0644\u0628\u062a\u0647 \u062a\u0645\u0627\u0645\u06cc \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u06f1\u06f0\u06f0% \u06af\u06cc\u0627\u0647\u06cc \u0647\u0633\u062a\u0646\u062f \u0648 \u062f\u0631 \u062a\u0647\u06cc\u0647 \u0622\u0646 \u0627\u0632 \u0647\u06cc\u0686 \u0645\u0627\u062f\u0647 \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0634\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/bizma.ir\/product\/dr-biz-special-drink-women\/\"><img decoding=\"async\" class=\"aligncenter wp-image-7433 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062f\u0645\u0646\u0648\u0634-\u0628\u0627\u0646\u0648\u0627\u0646.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062f\u0645\u0646\u0648\u0634-\u0628\u0627\u0646\u0648\u0627\u0646.jpg 400w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u062f\u0645\u0646\u0648\u0634-\u0628\u0627\u0646\u0648\u0627\u0646-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B2%D9%88%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF_%D8%B4%D8%AF%D9%86_%DA%86%DB%8C_%D8%A8%D8%AE%D9%88%D8%B1%DB%8C%D9%85%D8%9F\"><\/span>\u0628\u0631\u0627\u06cc \u0632\u0648\u062f \u067e\u0631\u06cc\u0648\u062f \u0634\u062f\u0646 \u0686\u06cc \u0628\u062e\u0648\u0631\u06cc\u0645\u061f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u062c\u0644\u0648 \u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u067e\u0631\u06cc\u0648\u062f \u0628\u0627 \u062a\u063a\u0630\u06cc\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0631\u0627\u06cc\u062c \u062f\u0631 \u0628\u06cc\u0646 \u0632\u0646\u0627\u0646 \u0648 \u062f\u062e\u062a\u0631\u0627\u0646 \u062c\u0648\u0627\u0646 \u0627\u0633\u062a \u0627\u06af\u0631 \u0646\u06af\u0631\u0627\u0646\u06cc \u062f\u0631 \u0631\u0627\u0628\u0637\u0647 \u0628\u0627 \u0628\u0627\u0631\u062f\u0627\u0631\u06cc \u0646\u062f\u0627\u0631\u06cc\u062f \u0648 \u0645\u0637\u0645\u0626\u0646 \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0647\u06cc\u0686 \u0646\u0637\u0641\u0647 \u06cc\u0627 \u062c\u0646\u06cc\u0646\u06cc \u062f\u0631 \u0628\u062f\u0646 \u0634\u0645\u0627 \u062d\u0636\u0648\u0631 \u0646\u062f\u0627\u0631\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062f\u0644\u0627\u06cc\u0644 \u062f\u06cc\u06af\u0631 \u0628\u0631\u0627\u06cc \u062a\u0627\u062e\u06cc\u0631 \u062f\u0631 \u067e\u0631\u06cc\u0648\u062f \u0628\u0627\u0634\u06cc\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0627\u06af\u0631 \u0647\u06cc\u0686 \u0645\u0634\u06a9\u0644\u06cc \u0627\u0632 \u0644\u062d\u0627\u0638 \u0636\u062e\u0627\u0645\u062a \u0622\u0646\u062f\u0648\u0645\u062a\u0631\u060c \u062d\u0636\u0648\u0631 \u06a9\u06cc\u0633\u062a \u0648 \u0645\u0648\u0627\u0631\u062f \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0646\u062f\u0627\u0631\u06cc\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0632\u06cc\u0631 \u0628\u0631\u0627\u06cc \u0632\u0648\u062f \u067e\u0631\u06cc\u0648\u062f \u0634\u062f\u0646 \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/p>\n<ul>\n<li>\u0631\u0627\u0632\u06cc\u0627\u0646\u0647 (\u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u0645\u0646\u0648\u0634 \u0648 \u0639\u0631\u0642)<\/li>\n<li>\u0632\u0646\u062c\u0628\u06cc\u0644 \u062a\u06a9\u0647\u200c\u062a\u06a9\u0647 \u0634\u062f\u0647 \u0648 \u062a\u0627\u0632\u0647<\/li>\n<li>\u062f\u0627\u0631\u0686\u06cc\u0646 \u067e\u0648\u062f\u0631 \u0634\u062f\u0647 \u0637\u0628\u06cc\u0639\u06cc<\/li>\n<li>\u0632\u0639\u0641\u0631\u0627\u0646 \u062f\u0645\u200c\u0622\u0648\u0631\u06cc \u0634\u062f\u0647<\/li>\n<li>\u0622\u0628 \u062c\u0639\u0641\u0631\u06cc \u062e\u0627\u0645<\/li>\n<li>\u0627\u0646\u0628\u0647 \u06a9\u0627\u0645\u0644\u0627 \u0631\u0633\u06cc\u062f\u0647<\/li>\n<\/ul>\n<p>\u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0642\u0627\u0639\u062f\u0647\u200c\u0622\u0648\u0631 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0635\u0648\u0631\u062a \u0627\u0635\u0648\u0644\u06cc \u0648 \u062f\u0631 \u0645\u0642\u0627\u062f\u06cc\u0631 \u062f\u0631\u0633\u062a \u0645\u0635\u0631\u0641 \u0634\u0648\u0646\u062f\u060c \u0686\u0631\u0627 \u06a9\u0647 \u0645\u0635\u0631\u0641 \u0628\u06cc\u0634 \u0627\u0632 \u0627\u0646\u062f\u0627\u0632\u0647 \u0622\u0646\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0628\u0631\u0648\u0632 \u0645\u0633\u0645\u0648\u0645\u06cc\u062a \u06cc\u0627 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc \u0634\u062f\u06cc\u062f \u0634\u0648\u062f\u060c \u062a\u0648\u062c\u0647 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u062d\u062a\u06cc \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u062f\u0627\u0631\u0648\u06cc\u06cc \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0639\u0648\u0627\u0631\u0636\u06cc \u0631\u0627 \u062f\u0631 \u067e\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0628\u0627\u0639\u062b \u0634\u0648\u0646\u062f \u062a\u0627 \u0627\u0644\u06af\u0648\u06cc \u0642\u0627\u0639\u062f\u06af\u06cc \u0634\u0645\u0627 \u0628\u0631 \u0647\u0645 \u0628\u0631\u06cc\u0632\u062f. \u0627\u06af\u0631 \u067e\u0631\u06cc\u0648\u062f \u0634\u0645\u0627 \u062f\u0686\u0627\u0631 \u0634\u0648\u06a9 \u0648 \u062a\u0623\u062e\u06cc\u0631 \u0634\u062f\u0647\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0627\u0628\u062a\u062f\u0627 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u0633\u062a\u0631\u0633 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0633\u067e\u0633 \u0628\u0627 \u062f\u0645\u0646\u0648\u0634 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632 \u0645\u062e\u0635\u0648\u0635 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u0642\u0627\u0639\u062f\u06af\u06cc \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u062d\u0627\u0644\u0627 \u0631\u0648\u062d\u06cc \u0648 \u062a\u0646\u0638\u06cc\u0645 \u0647\u0648\u0631\u0645\u0648\u0646\u200c\u0647\u0627 \u0628\u067e\u0631\u062f\u0627\u0632\u06cc\u062f.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87%DA%A9%D8%A7%D8%B1%D9%87%D8%A7%DB%8C_%D8%B7%D9%84%D8%A7%DB%8C%DB%8C_%DA%A9%D8%A7%D9%87%D8%B4_%D8%AF%D8%B1%D8%AF_%D9%BE%D8%B1%DB%8C%D9%88%D8%AF\"><\/span>\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0637\u0644\u0627\u06cc\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>\u0627\u06af\u0631 \u0632\u0646\u062c\u0628\u06cc\u0644\u060c \u0634\u06a9\u0644\u0627\u062a \u062a\u0644\u062e\u060c \u0631\u0627\u0632\u06cc\u0627\u0646\u0647\u060c \u062f\u0627\u0631\u0686\u06cc\u0646 \u0648 \u0645\u0648\u0627\u0631\u062f \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0631\u0627 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0631\u062f\u0647 \u0648\u0644\u06cc \u0646\u062a\u06cc\u062c\u0647 \u062e\u0627\u0635\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a \u0646\u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0633\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0637\u0644\u0627\u06cc\u06cc \u0627\u0631\u0627\u0626\u0647 \u0634\u062f\u0647 \u0631\u0627 \u0627\u0645\u062a\u062d\u0627\u0646 \u06a9\u0646\u06cc\u062f:<\/p>\n<ul>\n<li><strong>\u0645\u0627\u0633\u0627\u0698 \u062f\u0627\u062f\u0646 \u0634\u06a9\u0645 \u0648 \u06a9\u0645\u0631 \u0628\u0627 \u0631\u0648\u063a\u0646\u200c\u0647\u0627\u06cc \u0645\u0639\u0637\u0631 \u0648 \u0645\u062e\u0635\u0648\u0635<\/strong><\/li>\n<\/ul>\n<p>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u0633\u0627\u0646\u0633 \u06cc\u0627 \u0631\u0648\u063a\u0646\u200c\u0647\u0627\u06cc \u0627\u0633\u0637\u0648\u062e\u0648\u062f\u0648\u0633 \u0648 \u0645\u0631\u06cc\u0645\u200c\u06af\u0644\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u0648 \u06af\u0631\u0641\u062a\u06af\u06cc \u0639\u0636\u0644\u0627\u062a \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0634\u0645\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u062f\u0631 \u0637\u0648\u0644 \u0645\u062f\u062a \u0642\u0627\u0639\u062f\u06af\u06cc \u062e\u0648\u062f \u0627\u0632 \u0627\u06cc\u0646 \u0631\u0648\u063a\u0646\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0645\u0627\u0633\u0627\u0698 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0641\u0631\u0627\u0645\u0648\u0634 \u0646\u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u0645\u06cc.\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0622\u0631\u0648\u0645\u0627\u062a\u0631\u0627\u067e\u06cc \u0646\u06cc\u0632 \u062f\u0631 \u0628\u0647\u0628\u0648\u062f \u0633\u0637\u062d \u0627\u0633\u062a\u0631\u0633 \u0648 \u0627\u0636\u0637\u0631\u0627\u0628 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u0646\u062f.<\/p>\n<ul>\n<li><strong>\u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u0628\u06cc\u0634\u062a\u0631<\/strong><\/li>\n<\/ul>\n<p>\u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u0648\u0644\u0631\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u062f\u0631 \u06a9\u0627\u0647\u0634 \u06af\u0631\u0641\u062a\u06af\u06cc \u0648 \u0627\u0646\u0642\u0628\u0627\u0636\u0627\u062a \u0631\u062d\u0645\u06cc \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u062f. \u0627\u06af\u0631 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0631\u0627\u0647\u06a9\u0627\u0631\u06cc \u0637\u0628\u06cc\u0639\u06cc \u0628\u0631\u0627\u06cc \u0631\u0641\u0639 \u06af\u0631\u0641\u062a\u06af\u06cc\u200c\u0647\u0627\u06cc \u0639\u0636\u0644\u0627\u0646\u06cc \u0631\u062d\u0645 \u0647\u0633\u062a\u06cc\u062f \u0648 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u06cc\u062f \u06a9\u0647 \u0646\u0641\u062e \u0634\u06a9\u0645\u062a\u0627\u0646 \u0631\u0627 \u0646\u06cc\u0632 \u06a9\u0627\u0647\u0634 \u062f\u0647\u06cc\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u0642\u0627\u0639\u062f\u06af\u06cc \u0631\u0648\u0632\u0627\u0646\u0647 \u062d\u062f\u0627\u0642\u0644 \u062f\u0648 \u0644\u06cc\u062a\u0631 \u0622\u0628 \u0628\u0646\u0648\u0634\u06cc\u062f. \u062f\u0631\u0646\u0647\u0627\u06cc\u062a \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u0627\u0646\u0648\u0627\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0628\u0631 \u0627\u06cc\u0646 \u0627\u0648\u0636\u0627\u0639 \u0645\u0633\u0644\u0637 \u0634\u0648\u0646\u062f\u060c \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0627\u06af\u0631 \u067e\u0631\u06cc\u0648\u062f \u0634\u0645\u0627 \u0634\u062f\u06cc\u062f \u0634\u062f\u0647\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631\u062f \u0631\u0627 \u062a\u062d\u0645\u0644 \u0646\u06a9\u0646\u06cc\u062f \u0648 \u0628\u0627 \u06af\u0631\u0641\u062a\u0646 \u0645\u0631\u062e\u0635\u06cc\u060c \u062f\u0631 \u062e\u0627\u0646\u0647 \u0627\u0633\u062a\u0631\u0627\u062d\u062a \u06a9\u0646\u06cc\u062f. \u0633\u0631\u06a9\u0627\u0631 \u0631\u0641\u062a\u0646 \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u06a9\u0645\u0631 \u0634\u0645\u0627 \u0627\u0632 \u062f\u0631\u062f \u062e\u0645 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u06a9\u0627\u0631 \u0639\u0627\u0642\u0644\u0627\u0646\u0647\u200c\u0627\u06cc \u0646\u06cc\u0633\u062a.<\/p>\n<ul>\n<li><strong>\u0645\u062f\u06cc\u062a\u06cc\u0634\u0646 \u0648 \u0645\u0631\u0627\u0642\u0628\u0647<\/strong><\/li>\n<\/ul>\n<p>\u0627\u06af\u0631 \u06a9\u0644\u0627\u0641\u0647 \u0648 \u0645\u0636\u0637\u0631\u0628 \u0647\u0633\u062a\u06cc\u062f\u060c \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0627 \u062a\u0646\u0641\u0633 \u0639\u0645\u06cc\u0642 \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0645\u062f\u06cc\u062a\u06cc\u0634\u0646\u060c \u0622\u0631\u0627\u0645\u0634 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc\u062f. \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0646\u0638\u0631 \u0631\u0648\u062d\u06cc \u0648 \u0631\u0648\u0627\u0646\u06cc \u0634\u0645\u0627 \u0631\u0627 \u0622\u0631\u0627\u0645 \u06a9\u0646\u062f.<\/p>\n<ul>\n<li><strong>\u06a9\u06cc\u0633\u0647 \u0622\u0628 \u06af\u0631\u0645<\/strong><\/li>\n<\/ul>\n<p>\u06a9\u06cc\u0633\u0647\u200c\u0647\u0627\u06cc \u0622\u0628 \u06af\u0631\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u0627\u0646\u0646\u062f \u062f\u0627\u0631\u0648\u06cc \u0627\u06cc\u0628\u0648\u067e\u0631\u0648\u0641\u0646 \u062f\u0631 \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0628\u0627\u0634\u0646\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u062f\u0627\u0648\u0645 \u0627\u0632 \u0627\u06cc\u0646 \u06a9\u06cc\u0633\u0647\u200c\u0647\u0627 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062a\u0631\u0634\u062d \u0627\u0646\u062f\u0648\u0631\u0641\u06cc\u0646 \u062f\u0631 \u0628\u062f\u0646 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-8843 size-full\" src=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u0631\u0648\u0634-\u062f\u0631\u0645\u0627\u0646-\u0641\u0648\u0631\u06cc-\u0639\u0642\u0628-\u0627\u0641\u062a\u0627\u062f\u0646-\u067e\u0631\u06cc\u0648\u062f-\u062f\u0631-\u062f\u062e\u062a\u0631\u0627\u0646-\u0648-\u0632\u0646\u0627\u0646-\u0645\u062c\u0631\u062f.webp\" alt=\"\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f\" width=\"830\" height=\"500\" srcset=\"https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u0631\u0648\u0634-\u062f\u0631\u0645\u0627\u0646-\u0641\u0648\u0631\u06cc-\u0639\u0642\u0628-\u0627\u0641\u062a\u0627\u062f\u0646-\u067e\u0631\u06cc\u0648\u062f-\u062f\u0631-\u062f\u062e\u062a\u0631\u0627\u0646-\u0648-\u0632\u0646\u0627\u0646-\u0645\u062c\u0631\u062f.webp 830w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u0631\u0648\u0634-\u062f\u0631\u0645\u0627\u0646-\u0641\u0648\u0631\u06cc-\u0639\u0642\u0628-\u0627\u0641\u062a\u0627\u062f\u0646-\u067e\u0631\u06cc\u0648\u062f-\u062f\u0631-\u062f\u062e\u062a\u0631\u0627\u0646-\u0648-\u0632\u0646\u0627\u0646-\u0645\u062c\u0631\u062f-300x181.webp 300w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u0631\u0648\u0634-\u062f\u0631\u0645\u0627\u0646-\u0641\u0648\u0631\u06cc-\u0639\u0642\u0628-\u0627\u0641\u062a\u0627\u062f\u0646-\u067e\u0631\u06cc\u0648\u062f-\u062f\u0631-\u062f\u062e\u062a\u0631\u0627\u0646-\u0648-\u0632\u0646\u0627\u0646-\u0645\u062c\u0631\u062f-768x463.webp 768w, https:\/\/bizma.ir\/mag\/wp-content\/uploads\/2022\/11\/\u0631\u0648\u0634-\u062f\u0631\u0645\u0627\u0646-\u0641\u0648\u0631\u06cc-\u0639\u0642\u0628-\u0627\u0641\u062a\u0627\u062f\u0646-\u067e\u0631\u06cc\u0648\u062f-\u062f\u0631-\u062f\u062e\u062a\u0631\u0627\u0646-\u0648-\u0632\u0646\u0627\u0646-\u0645\u062c\u0631\u062f-780x470.webp 780w\" sizes=\"(max-width: 830px) 100vw, 830px\" \/><\/p>\n<h4>\u06a9\u0644\u0627\u0645 \u0646\u0647\u0627\u06cc\u06cc<\/h4>\n<p>\u0634\u0645\u0627 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0628\u0627 \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a\u0646 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0646\u0638\u0645 \u0628\u0648\u062f\u0646 \u0642\u0627\u0639\u062f\u06af\u06cc\u200c \u062a\u0627\u0646 \u0627\u0632 \u0631\u0648\u0634\u200c \u0647\u0627\u06cc \u0645\u062a\u0641\u0627\u0648\u062a\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f\u200c \u0628\u0627 \u062a\u0648\u062c\u0647\u200c \u0628\u0647 \u0645\u06cc\u0632\u0627\u0646 \u062e\u0648\u0646\u0631\u06cc\u0632\u06cc\u060c \u0631\u0646\u06af \u062e\u0648\u0646 \u0648 \u0645\u0648\u0627\u0631\u062f \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u06af\u0627\u0647\u06cc \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0645\u0631\u0627\u062c\u0639\u0647 \u0628\u0647 \u067e\u0632\u0634\u06a9 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u067e\u0633 \u0628\u062f\u0648\u0646 \u06cc\u0627\u0641\u062a\u0646 \u0639\u0644\u062a \u062a\u0627\u062e\u06cc\u0631 \u062f\u0631 \u067e\u0631\u06cc\u0648\u062f \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0645\u0635\u0631\u0641 \u062e\u0648\u062f\u0633\u0631\u0627\u0646\u0647 \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u06af\u06cc\u0627\u0647\u06cc \u0642\u0627\u0639\u062f\u0647\u200c\u0622\u0648\u0631 \u0646\u06a9\u0646\u06cc\u062f.<\/p>\n<p>\u0628\u0627\u200c \u0627\u06cc\u0646\u200c \u062d\u0627\u0644 \u0627\u06af\u0631 \u0646\u06af\u0631\u0627\u0646\u06cc \u0627\u0632 \u0633\u0646\u062f\u0631\u0648\u0645 \u062a\u062e\u0645\u062f\u0627\u0646 \u067e\u0644\u06cc\u200c\u06a9\u06cc\u0633\u062a\u06cc\u06a9\u060c \u0641\u06cc\u0628\u0631\u0648\u0645 \u0631\u062d\u0645\u06cc \u0648 \u0645\u0648\u0627\u0631\u062f \u0627\u06cc\u0646 \u0686\u0646\u06cc\u0646\u06cc \u0646\u062f\u0627\u0631\u06cc\u062f \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 <strong>\u062f\u0645\u0646\u0648\u0634 \u0628\u0627\u0646\u0648\u0627\u0646 \u062f\u06a9\u062a\u0631 \u0628\u06cc\u0632<\/strong> \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u062a\u0631\u06a9\u06cc\u0628 \u06af\u06cc\u0627\u0647\u06cc \u06af\u0632\u06cc\u0646\u0647\u200c\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0627\u06cc\u062f\u0647\u200c \u0622\u0644 \u0628\u0631\u0627\u06cc \u06a9\u0646\u062a\u0631\u0644 \u0648 \u062f\u0631\u0645\u0627\u0646 \u0627\u062e\u062a\u0644\u0627\u0644\u0627\u062a \u062c\u0633\u0645\u06cc \u0648 \u0631\u0648\u062d\u06cc \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 pms \u0648 \u0642\u0627\u0639\u062f\u06af\u06cc \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u062a\u0647\u06cc\u0647 \u0627\u06cc\u0646 \u062f\u0645\u0646\u0648\u0634 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 <a href=\"https:\/\/bizma.ir\/\" target=\"_blank\" rel=\"noopener\">\u0628\u06cc\u0632\u0645\u0627<\/a> \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u06cc\u062f.<\/p>\n<blockquote class=\"quote-light\"><p>\u0645\u0642\u0627\u0644\u0627\u062a \u0645\u0631\u062a\u0628\u0637 :<\/p>\n<ul>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/%d8%af%d9%84%d8%a7%db%8c%d9%84-%d9%82%d8%a7%d8%b9%d8%af%da%af%db%8c-%d9%86%d8%a7%d9%85%d9%86%d8%b8%d9%85\/\">\u062f\u0644\u0627\u06cc\u0644 \u0642\u0627\u0639\u062f\u06af\u06cc \u0646\u0627\u0645\u0646\u0638\u0645\u061b \u0622\u06cc\u0627 \u067e\u0631\u06cc\u0648\u062f \u0646\u0627\u0645\u0646\u0638\u0645 \u062e\u0637\u0631\u0646\u0627\u06a9 \u0627\u0633\u062a\u061f<\/a><\/li>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/hair-color-during-menstruation\/\">\u0631\u0646\u06af \u0645\u0648 \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u0642\u0627\u0639\u062f\u06af\u06cc\u061b \u0628\u0627\u06cc\u062f\u0647\u0627 \u0648 \u0646\u0628\u0627\u06cc\u062f\u0647\u0627<\/a><\/li>\n<li class=\"post-title\"><a href=\"https:\/\/bizma.ir\/mag\/ovarian-cysts\/\">\u062f\u0631\u0645\u0627\u0646 \u06a9\u06cc\u0633\u062a \u062a\u062e\u0645\u062f\u0627\u0646\u061b \u0639\u0644\u062a\u060c \u0639\u0644\u0627\u0626\u0645 \u0648 \u067e\u06cc\u0634\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0622\u0646<\/a><\/li>\n<\/ul>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>\u0632\u0646\u0627\u0646 \u0627\u0632 \u0633\u0646 \u0628\u0644\u0648\u063a \u062a\u0627 \u06cc\u0627\u0626\u0633\u06af\u06cc\u060c \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0627\u0647\u0627\u0646\u0647 \u0628\u0627 \u0641\u0631\u0622\u06cc\u0646\u062f \u0637\u0628\u06cc\u0639\u06cc \u0628\u0647 \u0646\u0627\u0645 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631\u06af\u06cc\u0631 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0627\u063a\u0644\u0628 \u0632\u0646\u0627\u0646 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u067e\u0631\u06cc\u0648\u062f \u062f\u0631\u062f \u0648 \u0627\u0633\u067e\u0627\u0633\u0645\u200c\u0647\u0627\u06cc \u0634\u06a9\u0645\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u067e\u0631\u06cc\u0648\u062f \u062e\u0627\u0646\u06af\u06cc\u00a0\u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0628\u0633\u06cc\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f\u060c \u0647\u0645\u0631\u0627\u0647 \u0645\u0627 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0628\u0627 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0639\u0644\u0645\u06cc \u0648 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0637\u0644\u0627\u06cc\u06cc \u06a9\u0627\u0647\u0634 \u062f\u0631\u062f \u0642\u0627\u0639\u062f\u06af\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0622\u0634\u0646\u0627 \u0634\u0648\u06cc\u062f. &hellip;<\/p>\n","protected":false},"author":2787,"featured_media":8852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-6665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health"],"_links":{"self":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts\/6665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/users\/2787"}],"replies":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/comments?post=6665"}],"version-history":[{"count":0,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/posts\/6665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/media\/8852"}],"wp:attachment":[{"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/media?parent=6665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/categories?post=6665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bizma.ir\/mag\/wp-json\/wp\/v2\/tags?post=6665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}